{"id":3476,"date":"2023-07-18T12:42:17","date_gmt":"2023-07-18T16:42:17","guid":{"rendered":"https:\/\/cnewa.org\/es\/?post_type=magazine&#038;p=3476"},"modified":"2025-09-10T12:32:03","modified_gmt":"2025-09-10T16:32:03","slug":"viviendo-una-vida-cristiana-en-la-tierra-de-jesus","status":"publish","type":"magazine","link":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/","title":{"rendered":"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">Stefan Amseis, residente de Ramle, una ciudad religiosamente diversa en el centro de Israel, siempre lleva una cruz alrededor de su cuello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estos d\u00edas, sin embargo, el hombre de 30 a\u00f1os, que se identifica como un ciudadano \u00e1rabe cristiano de Israel, est\u00e1 siendo muy cuidadoso debido al deterioro de la seguridad tras informes de un reciente aumento de extremistas jud\u00edos que escupen a los cristianos y vandalizan propiedades cristianas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando estoy en Jerusal\u00e9n me preocupa que los jud\u00edos nacionalistas o ultraortodoxos me escupan si saben que soy cristiano\u201d, dice Amseis, director de la edici\u00f3n \u00e1rabe de <a href=\"https:\/\/myfranciscan.org\/holy-land-review\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rese\u00f1as de Tierra Santa<\/a> (As-Salam Wal-Kheir), la revista de los franciscanos de Tierra Santa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peque\u00f1os grupos de jud\u00edos fan\u00e1ticos han acosado a los cristianos por a\u00f1os, pero el n\u00famero de incidentes se dispar\u00f3 este invierno, poco despu\u00e9s que el nuevo gobierno de Israel asumiera el cargo el 29 de diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHemos visto ataques m\u00e1s audaces a plena luz del d\u00eda en algunas propiedades de la iglesia\u201d, dice Joseph Hazboun, director regional de CNEWA-Misi\u00f3n Pontificia para Palestina e Israel. Hazboun ve la situaci\u00f3n directamente desde su oficina en el barrio cristiano de la Ciudad Vieja de Jerusal\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9l enumera algunos incidentes: el vandalismo del cementerio de la iglesia anglicana en el Monte de los Olivos y el ataque de febrero a la Iglesia de la Flagelaci\u00f3n en la V\u00eda Dolorosa, en la que un turista jud\u00edo ortodoxo estadounidense destruy\u00f3 una imponente estatua de Jes\u00fas. El agresor grit\u00f3: \u201c\u00a1No \u00eddolos en la ciudad santa de Jerusal\u00e9n!\u201d mientras golpe\u00f3 la cara de la estatua con un martillo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"814\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_325H-1024x814.jpg\" alt=\"Mujer sonr\u00ed frente a su hijo reci\u00e9n nacido que est\u00e1 en una incubadora.\" class=\"wp-image-3480\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_325H-1024x814.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_325H-300x239.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_325H-768x611.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_325H-1600x1272.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_325H-1536x1221.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_325H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Mira Laham y su hijo, Taim, en la sala de maternidad del Hospital Franc\u00e9s San Vicente de Pa\u00fal en Nazaret. (foto: Ilene Perlman)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Religiosas y sacerdotes son escupidos y maldecidos con frecuencia cuando caminan por las estrechas calles de la Ciudad Vieja, que tambi\u00e9n es hogar de un grupo de j\u00f3venes extremistas jud\u00edos.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Obispo Rafic Nahra en Nazaret, vicario patriarcal para Israel y obispo auxiliar del Patriarcado Latino de Jerusal\u00e9n, dice que la polic\u00eda no toma en serio las acciones de los extremistas. Casi no ha habido arrestos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSabemos que el gobierno no apoya los ataques, pero su respuesta ha sido d\u00e9bil. Si las sinagogas fueran atacadas, la respuesta ser\u00eda m\u00e1s fuerte\u201d, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rabino David Rosen, director de asuntos interreligiosos internacionales del Comit\u00e9 Jud\u00edo Americano con sede en Jerusal\u00e9n, dice que el gobierno hace algunos esfuerzos, pero no los suficientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe est\u00e1 proporcionando m\u00e1s seguridad y se han instalado m\u00e1s c\u00e1maras en \u00e1reas vulnerables, pero el problema es que la polic\u00eda no tiene motivos legales para actuar contra algunos de los instigadores\u201d, dice. \u201cEscupir no es un crimen de odio bajo la ley israel\u00ed. Lo que se necesita es legislaci\u00f3n que demuestre que estas acciones no se toman a la ligera\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El obispo Nahra atribuye al menos parte de la inacci\u00f3n del gobierno a la agitaci\u00f3n interna de Israel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay profundas divisiones en de la sociedad jud\u00eda, y nuestros \u2018peque\u00f1os\u2019 problemas parecen nada para ellos\u201d, dice el obispo. \u201cPero esto parece discriminaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Desde marzo, cientos de miles de israel\u00edes han salido a las calles a protestar los planes del nuevo gobierno de alterar el sistema judicial y expandir la autoridad jud\u00eda ortodoxa en la esfera p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ondeando banderas israel\u00edes y pidiendo democracia, los manifestantes han organizado huelgas generales y manifestaciones semanales que han bloqueado las principales carreteras. Dicen que las leyes propuestas son antidemocr\u00e1ticas y teocr\u00e1ticas, alegando que Israel fue fundado como un pa\u00eds secular y como una patria para jud\u00edos de todas las tendencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que se describe como partidos jud\u00edos de extrema derecha y ultraortodoxos dentro de la coalici\u00f3n del primer ministro apoyan la expansi\u00f3n de los asentamientos jud\u00edos en territorios palestinos, presupuestos m\u00e1s altos para instituciones ultraortodoxas y la exenci\u00f3n del servicio militar obligatorio para los ultraortodoxos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Justo antes del comienzo de la Pascua, los partidos ultraortodoxos, cuyos componen casi la mitad de la coalici\u00f3n gobernante de 64 esca\u00f1os, impulsaron una ley que permite a los hospitales prohibir los alimentos que no son de Pascua, como el pan, durante el feriado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_294H-1024x682.jpg\" alt=\"\" class=\"wp-image-3482\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_294H-1024x682.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_294H-300x200.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_294H-768x511.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_294H-1600x1065.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_294H-1536x1022.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_294H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La hermana Maha Sansour visita al personal y a los pacientes del departamento geri\u00e1trico del Hospital Franc\u00e9s San Vicente de Pa\u00fal en Nazaret durante una actividad art\u00edstica para Pascua de Resurrecci\u00f3n y Ramad\u00e1n. (foto: Ilene Perlman)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La ley afecta no solo a jud\u00edos seculares, sino tambi\u00e9n a las minor\u00edas religiosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa ley muestra una falta de consideraci\u00f3n por los ciudadanos no jud\u00edos de Israel y va en contra de los valores democr\u00e1ticos del estado\u201d, dice Hazboun. \u201cNo es diferente de una facci\u00f3n musulmana que impondr\u00eda el uso del hiyab o la prohibici\u00f3n del alcohol\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De mayor preocupaci\u00f3n son los esfuerzos de la coalici\u00f3n por debilitar la autoridad de la Corte Suprema, cuyos fallos en las \u00faltimas dos d\u00e9cadas han tendido a ser moderados, especialmente con respecto a los derechos de las mujeres, los jud\u00edos no ortodoxos y las minor\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si el llamado proyecto de ley de \u201crevisi\u00f3n judicial\u201d se aprueba sin modificaciones significativas, solo se necesitar\u00edan 61 legisladores en el Parlamento de 120 esca\u00f1os para revocar muchos fallos de la Corte Suprema. Otro proyecto de ley dar\u00eda a los parlamentarios una voz mucho mayor sobre qui\u00e9n puede servir como juez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neri Zilber, asesor de pol\u00edticas con sede en Israel en el Foro de Pol\u00edtica de Israel, describe la situaci\u00f3n como \u201cla crisis constitucional m\u00e1s grave\u201d en los 75 a\u00f1os de historia de Israel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c[Esos] proyectos marcar\u00edan el comienzo de un gobierno mayoritario: la mayor\u00eda en el Parlamento y el gobierno podr\u00edan decidir aprobar cualquier ley o tomar cualquier decisi\u00f3n que elijan\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una reforma judicial radical podr\u00eda resultar en la ausencia de protecciones reales para cosas como los derechos de las minor\u00edas, advierte Zilber. En teor\u00eda, podr\u00eda prohibir que los partidos \u00e1rabes se presenten a las elecciones sobre la base de que no reconocen a Israel como un estado jud\u00edo y democr\u00e1tico.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"681\" height=\"1024\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-681x1024.jpg\" alt=\"Ninna mira a la c\u00e1mara en foto con feligreses parados en sus butacas en una iglesia.\" class=\"wp-image-3487\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-681x1024.jpg 681w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-200x300.jpg 200w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-768x1154.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-1600x2404.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-1022x1536.jpg 1022w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-1363x2048.jpg 1363w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_142H-scaled.jpg 1704w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><figcaption class=\"wp-element-caption\">Feligreses asisten a una liturgia de Jueves Santo en la Iglesia Griega Ortodoxa de la Natividad de la Virgen Mar\u00eda en Kafr Yasif, Israel, el 13 de abril. (foto: Ilene Perlman)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPodr\u00edamos tener una situaci\u00f3n en la que los ciudadanos \u00e1rabes, que son el 21% de la poblaci\u00f3n, no tengan representaci\u00f3n pol\u00edtica\u201d, a\u00f1ade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los 182.000 ciudadanos cristianos de Israel, unos 138.000 son \u00e1rabes, seg\u00fan la Oficina Central de Estad\u00edsticas de Israel. Muchos, no todos, se identifican como palestinos. Los cristianos son aproximadamente el 2% de la poblaci\u00f3n de Israel de 9,7 millones, mientras que los musulmanes representan el 18%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los partidos \u00e1rabes suelen presentarse a las elecciones nacionales y se sientan en la oposici\u00f3n en la Knesset. Sin embargo, Ra&#8217;am, un partido isl\u00e1mico, hizo historia en 2021, cuando se uni\u00f3 a la coalici\u00f3n gobernante entonces moderada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de las profundas divisiones en la sociedad israel\u00ed, Zilber ve un lado positivo: todos los aspectos de la sociedad israel\u00ed, incluidos moderados e izquierdistas, se han vuelto mucho m\u00e1s proactivos para establecer un curso para el futuro del pa\u00eds. Seg\u00fan las encuestas de opini\u00f3n realizadas esta primavera, si las elecciones se celebraran pronto, el actual primer ministro y su partido no podr\u00edan formar un gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsto podr\u00eda ser un paso para votar por un gobierno m\u00e1s razonable\u201d, dice Zilber.<\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">A los ciudadanos \u00e1rabes, incluidos los cristianos, les preocupa que las prioridades del gobierno actual resulten en un apoyo a\u00fan menor para los sectores \u00e1rabes y no jud\u00edos que ya carecen de atenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTememos que la asignaci\u00f3n presupuestaria sin precedentes ($9.7 mil millones) aprobada por el gobierno anterior para cerrar la brecha entre \u00e1rabes y jud\u00edos se congele y se use para financiar asentamientos y la Guardia Nacional\u201d, dijo Thabet Abu Rass, codirector ejecutivo de Iniciativas Abraham, una organizaci\u00f3n sin fines de lucro que aboga por la igualdad \u00e1rabe en Israel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien el sector \u00e1rabe tiene muchas preocupaciones, la financiaci\u00f3n gubernamental y las iniciativas para combatir el crimen organizado y la violencia dentro de los pueblos y ciudades \u00e1rabes est\u00e1n en la parte superior de la lista, dice Abu Rass.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2022, 112 ciudadanos \u00e1rabes y cuatro no ciudadanos murieron debido a actividades delictivas dentro de la comunidad \u00e1rabe perpetradas por sus propios miembros. De estos, el 87% murieron por disparos. Cinco v\u00edctimas perdieron la vida en circunstancias relacionadas con la polic\u00eda, seg\u00fan las Iniciativas Abraham.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl ministro de seguridad deber\u00eda garantizar la seguridad p\u00fablica de todos los ciudadanos israel\u00edes, pero no hace nada para brindar seguridad a la comunidad \u00e1rabe\u201d, dice Abu Rass.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras preocupaciones importantes son el envejecimiento de la infraestructura y la falta de tierra suficiente para acomodar el crecimiento natural dentro de los municipios \u00e1rabes.<\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">El pueblo de Kafr Yossef en Galilea es un buen ejemplo. El pintoresco pueblo monta\u00f1oso, salpicado de hermosas casas de piedra y hermosas iglesias, es hogar de cristianos, musulmanes y drusos. La comunidad cristiana, casi el 60% de la poblaci\u00f3n, tiene escuelas galardonadas y grupos juveniles pr\u00f3speros, pero no hay suficientes viviendas para acomodar a los hijos adultos de los residentes que desean residir all\u00ed.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta escasez de viviendas, que afecta a todos los israel\u00edes, pero es especialmente aguda en los municipios \u00e1rabes, ha motivado a muchos j\u00f3venes a mudarse a las ciudades cercanas de Akko y Haifa, e incluso al extranjero despu\u00e9s de graduarse de la universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la tranquilidad previa a celebrar una liturgia del Jueves Santo en la recientemente construida Iglesia de la Natividad de la Virgen Mar\u00eda, el p\u00e1rroco ortodoxo griego, el padre Atallah Makhouli, toca una nota seria.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_027H-1024x682.jpg\" alt=\"Retrato del padre Atallah Makhouli, Jerusal\u00e9n.\" class=\"wp-image-3488\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_027H-1024x682.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_027H-300x200.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_027H-768x511.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_027H-1600x1065.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_027H-1536x1022.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_027H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">El padre Atallah Makhouli sirve a los fieles ortodoxos griegos en Kafr Yossef. (foto: Ilene Perlman)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros los cristianos hemos estado aqu\u00ed por generaciones y generaciones. Esperamos estar aqu\u00ed por muchas m\u00e1s. Pero el futuro de nuestros hijos depende de la paz\u201d, dice el padre Makhouli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9l se\u00f1ala que militantes palestinos dispararon m\u00e1s de 30 cohetes contra Galilea el 6 de abril, y que la violencia en Cisjordania y Jerusal\u00e9n se ha disparado en las \u00faltimas semanas. Pero ni la paz puede impedir que los j\u00f3venes se vayan si no pueden mantener una buena calidad de vida y no tienen la capacidad de construir hogares, agrega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl gobierno no nos da la tierra para expandir la aldea. Es un viejo problema\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a su peque\u00f1o n\u00famero, los cristianos en Israel tambi\u00e9n enfrentan la amenaza de la asimilaci\u00f3n, dice Josef Shahada, l\u00edder de la comunidad ortodoxa griega y educador en Kafr Yasif.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVivimos entre jud\u00edos y \u00e1rabes, una minor\u00eda en Israel, pero tambi\u00e9n dentro de la sociedad \u00e1rabe\u201d, lo que puede dificultar el mantenimiento de una identidad \u00fanica, agrega. Esto es especialmente cierto cuando estudiantes cristianos asisten a universidades israel\u00edes y encuentran trabajos que los incorporan a\u00fan m\u00e1s en la sociedad jud\u00eda o musulmana israel\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De nuevo en Nazaret, el obispo Nahra dice que el hecho de que los cristianos en Israel sean altamente educados, occidentalizados y en su mayor parte financieramente seguros es una bendici\u00f3n y un desaf\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ayudar a los ni\u00f1os y sus familias a sentirse m\u00e1s conectados con Jes\u00fas y la iglesia, el Patriarcado Latino de Jerusal\u00e9n ha identificado varias \u00e1reas que necesitan mejoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una prioridad es mejorar la formaci\u00f3n en la fe de los profesores de catecismo de las escuelas, para que puedan ense\u00f1ar la fe cristiana con entusiasmo y alegr\u00eda. Otra es fomentar una mayor participaci\u00f3n de la familia en los servicios y actividades de la iglesia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIsrael es una sociedad muy secular y cara, por lo que la gente tiene que trabajar muy duro\u201d, dice. \u201cHay poco tiempo para construir la vida familiar. Los padres a menudo no van a Misa, por lo que los ni\u00f1os no tienen una vida lit\u00fargica\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/aI5azC7ELLc?list=PL_pDlqw1fwPb9u6CudbGmOBPcW2CxRr9x\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las iglesias cat\u00f3licas tambi\u00e9n est\u00e1n colaborando para brindar oportunidades para que los j\u00f3venes cat\u00f3licos del pa\u00eds, ya sean cat\u00f3licos romanos o cat\u00f3licos orientales, se re\u00fanan, socialicen y, con suerte, se casen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tan frustrado como est\u00e1 por los obst\u00e1culos de financiaci\u00f3n de larga data del gobierno israel\u00ed a las instituciones cristianas, el padre Abdel Masih Fahim, franciscano y coordinador de escuelas cristianas en Israel, est\u00e1 satisfecho porque las escuelas cristianas pronto tendr\u00e1n su primer libro de texto de historia del cristianismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En t\u00e9rminos de plan de estudios, Israel nunca ha distinguido entre \u00e1rabes cristianos y musulmanes. Durante d\u00e9cadas, el Ministerio de Educaci\u00f3n exigi\u00f3 que las escuelas del sector \u00e1rabe ense\u00f1en historia y otras materias desde una perspectiva isl\u00e1mica, incluso en las escuelas cristianas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora, se\u00f1ala el padre Fahim, las escuelas cristianas \u201chan tenido que ense\u00f1ar con libros de historia isl\u00e1mica que ignoran 600 a\u00f1os de historia cristiana, desde el nacimiento de Jes\u00fas hasta el advenimiento del islam en el siglo VII. Tenemos cursos en lengua \u00e1rabe que toman textos del Cor\u00e1n. Entonces, le preguntamos [al ministerio de educaci\u00f3n], \u00bfpor qu\u00e9 no recurrir a textos del cristianismo, el Evangelio o la Biblia?\u201d<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped is-style-lightbox wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"673\" height=\"1024\" data-id=\"3485\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-673x1024.jpg\" alt=\"Retrato de Stefan Amseis, director de la edici\u00f3n \u00e1rabe de Rese\u00f1as de Tierra Santa.\" class=\"wp-image-3485\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-673x1024.jpg 673w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-197x300.jpg 197w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-768x1169.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-1600x2435.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-1009x1536.jpg 1009w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-1346x2048.jpg 1346w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-scaled.jpg 1682w\" sizes=\"auto, (max-width: 673px) 100vw, 673px\" \/><figcaption class=\"wp-element-caption\">Stefan Amseis es residente de Ramle, en el centro de Israel, y director de la edici\u00f3n \u00e1rabe de Rese\u00f1as de Tierra Santa. (foto: Ilene Perlman)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"664\" data-id=\"3484\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_202H-1024x664.jpg\" alt=\"Retrato de rabino David Rosen en Jerusal\u00e9n.\" class=\"wp-image-3484\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_202H-1024x664.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_202H-300x195.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_202H-768x498.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_202H-1600x1037.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_202H-1536x996.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_202H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">El rabino David Rosen es el director de asuntos interreligiosos internacionales del Comit\u00e9 Jud\u00edo Americano con sede en Jerusal\u00e9n. (foto: Ilene Perlman)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"665\" data-id=\"3483\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_244H-1024x665.jpg\" alt=\"El obispo Rafic Nahra, vicario patriarcal para Israel y obispo auxiliar del Patriarcado Latino de Jerusal\u00e9n en Nazaret.\" class=\"wp-image-3483\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_244H-1024x665.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_244H-300x195.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_244H-768x499.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_244H-1600x1039.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_244H-1536x998.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_244H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">El obispo Rafic Nahra es vicario patriarcal para Israel y obispo auxiliar del Patriarcado Latino de Jerusal\u00e9n en Nazaret. (foto: Ilene Perlman)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"662\" data-id=\"3481\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_306H-1024x662.jpg\" alt=\"La hermana Maha Sansour es miembro de las Hijas de la Caridad, Jerusal\u00e9n.\" class=\"wp-image-3481\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_306H-1024x662.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_306H-300x194.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_306H-768x497.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_306H-1600x1035.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_306H-1536x993.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_306H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La hermana Maha Sansour es miembro de las Hijas de la Caridad y enfermera jefe del Hospital Franc\u00e9s San Vicente de Pa\u00fal en Nazaret. (foto: Ilene Perlman)<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este largamente anhelado libro de texto est\u00e1 en sus etapas finales, dice.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por 125 a\u00f1os, el Hospital Franc\u00e9s San Vicente de Pa\u00fal en Nazaret ha atendido a pacientes de todas las religiones, tal como lo so\u00f1\u00f3 su fundadora, la Madre Leonie Sion de las Hijas de la Caridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy en d\u00eda, el hospital de 140 camas funciona como un centro de salud p\u00fablica general bajo las regulaciones del Ministerio de Salud. Sin embargo, al igual que las escuelas cristianas del pa\u00eds, recibe solo una fracci\u00f3n de los fondos que reciben los hospitales estatales. El Instituto Nacional de Seguros paga por la atenci\u00f3n de pacientes individuales, pero no por renovaciones hospitalarias o nuevos equipos m\u00e9dicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo mismo ocurre con otros hospitales semiprivados, como el Centro M\u00e9dico Hadassah en Jerusal\u00e9n, pero estas instalaciones m\u00e9dicas pueden compensar el d\u00e9ficit con fondos de donantes privados, incluida la di\u00e1spora jud\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El departamento geri\u00e1trico del Hospital Franc\u00e9s San Vicente de Pa\u00fal tiene 26 fr\u00e1giles pacientes hospitalizados. En un c\u00e1lido d\u00eda de primavera, un pu\u00f1ado de ellos realiza proyectos de arte terap\u00e9utico relacionados con la Pascua de Resurrecci\u00f3n y el Ramad\u00e1n en la estrecha pero alegre sala diurna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La hermana Maha Sansour, la enfermera jefa, observa las actividades y saluda calurosamente a todos los pacientes y miembros del personal. Pero su sonrisa se vuelve melanc\u00f3lica cuando regresa al pasillo. Anhela que el hospital pueda actualizar la sala.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon recursos financieros, podr\u00edamos tratar a m\u00e1s pacientes. Podr\u00edamos renovar un poco y agregar lavabos a cada habitaci\u00f3n\u201d, dice la hermana Maha, una de las tres Hijas de la Caridad que trabajan en el hospital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso con el d\u00e9ficit, el hospital ha logrado crear una brillante ala de maternidad que permite a las madres y sus reci\u00e9n nacidos permanecer en la misma habitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mira Laham observa a su hijo de dos d\u00edas, Taim, dormido en su mois\u00e9s. Viaj\u00f3 desde Haifa, donde vive, a Nazaret, su ciudad natal, para dar a luz en el hospital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi esposo es m\u00e9dico en el Hospital Rambam en Haifa, pero yo quer\u00eda estar en el Hospital Franc\u00e9s porque me encanta el ambiente y la atenci\u00f3n\u201d, dice. \u201cAdem\u00e1s, nac\u00ed aqu\u00ed y quer\u00eda que mi hijo naciera aqu\u00ed. Es parte de nuestra historia familiar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El esp\u00edritu del hospital refleja la visi\u00f3n de la hermana Leonie de crear un hospital cristiano para todos los que lo necesitan. Cruces adornan las paredes y, durante la Pascua de Resurrecci\u00f3n, conejitos de peluche y coloridos huevos de chocolate decoran cada pabell\u00f3n. Hay una capilla en el centro de la instalaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se sinti\u00f3 lo suficientemente fuerte, la se\u00f1ora Laham pidi\u00f3 a las hermanas que la acompa\u00f1aran a ella y a Taim a la capilla para ofrecer una oraci\u00f3n de gratitud y bendecir al beb\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que la se\u00f1ora Laham, Stefan Amseis siente una conexi\u00f3n visceral con la historia cristiana y con la tierra que Jes\u00fas llam\u00f3 hogar. Como muchos de sus compa\u00f1eros, siente la obligaci\u00f3n de fortalecer su iglesia y comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos cristianos son el 2% de la poblaci\u00f3n, y si todos se van, \u00bfc\u00f3mo podemos mejorar la situaci\u00f3n aqu\u00ed? Sentimos una responsabilidad. Si nos vamos, \u00bfqui\u00e9n cuidar\u00e1 nuestras iglesias?\u201d, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQueremos tener hijos aqu\u00ed y ponerlos en el camino para vivir una vida cristiana. En esta tierra\u201d.<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color wp-block-paragraph\"><em><a href=\"https:\/\/issuu.com\/cnewa\/docs\/one-1-2-issuu-en-espanol\/30\">Lea este art\u00edculo en nuestro formato de impresi\u00f3n digital aqu\u00ed.<\/a><\/em><\/p>\n\n\n<div class=\"cnewa-connections\">\n  <div class=\"cnewa-connections-heading\">\n    <h2>Conexi\u00f3n CNEWA<\/h2>\n  <\/div>\n  <div class=\"cnewa-connections-content\" style=\"background:#6B4D5E;color:#ffffff\">\n    <p style=\"font-weight: 400\">Aunque los cristianos son una minor\u00eda dentro de una minor\u00eda en Israel, los programas de servicio social de la iglesia son numerosos, y atienden a cristianos, jud\u00edos, musulmanes, a todos los segmentos de la sociedad. Una de esas iniciativas, el Hospital Franc\u00e9s San Vicente de Pa\u00fal en Nazaret, brinda atenci\u00f3n m\u00e9dica a los pacientes independientemente de su fe. Los fondos CNEWA-Misi\u00f3n Pontificia se destinan a proyectos de rehabilitaci\u00f3n, gastos operativos, \u00e1reas de juego para ni\u00f1os con necesidades especiales y servicios mejorados.<\/p>\n<p style=\"font-weight: 400\">\n<p style=\"font-weight: 400\">Para apoyar este trabajo crucial, llame al 1-800-442-6392 (Estados Unidos) o al 1-866-322-4441 (Canad\u00e1) o visite<\/p>\n<p style=\"font-weight: 400\"><a href=\"https:\/\/cnewa.org\/es\/que-hacemos\/israel\/\">cnewa.org\/es\/trabajo\/israel<\/a><\/p>\n  <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Stefan Amseis, residente de Ramle, una ciudad religiosamente diversa en el centro de Israel, siempre lleva una cruz alrededor de su cuello. En estos d\u00edas, sin embargo, el hombre de 30 a\u00f1os, que se identifica como un ciudadano \u00e1rabe cristiano de Israel, est\u00e1 siendo muy cuidadoso debido al deterioro de la seguridad tras informes de &hellip; <a href=\"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/\">Continued<\/a><\/p>\n","protected":false},"author":70019,"featured_media":3489,"template":"","magazine-issues":[501],"magazine-sections":[143],"class_list":["post-3476","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","magazine-issues-julio-2023","magazine-sections-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Viviendo una Vida Cristiana en la Tierra de Jes\u00fas | ONE en Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"Ciudadanos \u00e1rabes cristianos de Israel est\u00e1n siendo cuidadosos tras aumento reciente de extremistas jud\u00edos que escupen a los cristianos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas | ONE en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Ciudadanos \u00e1rabes cristianos de Israel est\u00e1n siendo cuidadosos tras aumento reciente de extremistas jud\u00edos que escupen a los cristianos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T16:32:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-Web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/\",\"name\":\"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas | ONE en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/07\\\/perlman202304_192H-Web.jpg\",\"datePublished\":\"2023-07-18T16:42:17+00:00\",\"dateModified\":\"2025-09-10T16:32:03+00:00\",\"description\":\"Ciudadanos \u00e1rabes cristianos de Israel est\u00e1n siendo cuidadosos tras aumento reciente de extremistas jud\u00edos que escupen a los cristianos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/07\\\/perlman202304_192H-Web.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/07\\\/perlman202304_192H-Web.jpg\",\"width\":1800,\"height\":900,\"caption\":\"Stefan Amseis es residente de Ramle, en el centro de Israel, y director de la edici\u00f3n \u00e1rabe de Rese\u00f1as de Tierra Santa. (foto: Ilene Perlman)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Magazine\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas | ONE en Espa\u00f1ol","description":"Ciudadanos \u00e1rabes cristianos de Israel est\u00e1n siendo cuidadosos tras aumento reciente de extremistas jud\u00edos que escupen a los cristianos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/","og_locale":"es_ES","og_type":"article","og_title":"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas | ONE en Espa\u00f1ol","og_description":"Ciudadanos \u00e1rabes cristianos de Israel est\u00e1n siendo cuidadosos tras aumento reciente de extremistas jud\u00edos que escupen a los cristianos.","og_url":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_modified_time":"2025-09-10T16:32:03+00:00","og_image":[{"width":1800,"height":900,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-Web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/","url":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/","name":"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas | ONE en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-Web.jpg","datePublished":"2023-07-18T16:42:17+00:00","dateModified":"2025-09-10T16:32:03+00:00","description":"Ciudadanos \u00e1rabes cristianos de Israel est\u00e1n siendo cuidadosos tras aumento reciente de extremistas jud\u00edos que escupen a los cristianos.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-Web.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/07\/perlman202304_192H-Web.jpg","width":1800,"height":900,"caption":"Stefan Amseis es residente de Ramle, en el centro de Israel, y director de la edici\u00f3n \u00e1rabe de Rese\u00f1as de Tierra Santa. (foto: Ilene Perlman)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/revista\/viviendo-una-vida-cristiana-en-la-tierra-de-jesus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"One Magazine","item":"https:\/\/cnewa.org\/es\/revista\/"},{"@type":"ListItem","position":3,"name":"Viviendo una Vida Cristiana en la Tierra de Jes\u00fas"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/3476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/magazine"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"version-history":[{"count":1,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/3476\/revisions"}],"predecessor-version":[{"id":7130,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/3476\/revisions\/7130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/3489"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=3476"}],"wp:term":[{"taxonomy":"magazine-issues","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-issues?post=3476"},{"taxonomy":"magazine-sections","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-sections?post=3476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}