{"id":4420,"date":"2024-01-10T12:07:36","date_gmt":"2024-01-10T17:07:36","guid":{"rendered":"https:\/\/cnewa.org\/es\/?post_type=magazine&#038;p=4420"},"modified":"2024-01-12T14:47:58","modified_gmt":"2024-01-12T19:47:58","slug":"sin-vuelta-atras","status":"publish","type":"magazine","link":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/","title":{"rendered":"Sin Vuelta Atr\u00e1s"},"content":{"rendered":"\n<p class=\"has-drop-cap wp-block-paragraph\">Al amanecer del 20 de septiembre, Boris Simonyan recibi\u00f3 la noticia de que \u00e9l y su familia deb\u00edan evacuar su hogar en Kochoghot, una peque\u00f1a aldea en la regi\u00f3n de Martakert de Nagorno-Karabaj, una comunidad que hist\u00f3ricamente ha sido \u00e9tnica armenia en una regi\u00f3n disputada desde hace mucho tiempo y ahora ocupada por Azerbaiy\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los bombardeos de las fuerzas azerbaiyanas hab\u00edan sido inclementes desde la 1 p.m. del d\u00eda anterior. A los 17 a\u00f1os, con su padre militar en el frente de batalla, le toc\u00f3 a Boris guiar a su madre y hermanos a un lugar seguro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El bloqueo impuesto por Azerbaiy\u00e1n meses antes hab\u00eda impedido que Boris continuara estudiando en la escuela t\u00e9cnica de Stepanakert, capital de la regi\u00f3n. Trabajaba en una obra de construcci\u00f3n cuando comenzaron los bombardeos. Sali\u00f3 del trabajo y r\u00e1pidamente recogi\u00f3 a su hermano de 11 a\u00f1os de la escuela y lo llev\u00f3 a casa, donde lo esperaban su madre y su hermana. Los escolt\u00f3 a un s\u00f3tano cercano para cubrirse antes de ayudar a otros en el pueblo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, Boris, su madre y sus hermanos se api\u00f1aron en la camioneta de un amigo y huyeron de Kochoghot a las 8:30 a.m.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_045H-1024x683.jpg\" alt=\"\" class=\"wp-image-4415\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_045H-1024x683.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_045H-300x200.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_045H-768x512.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_045H-1600x1067.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_045H-1536x1024.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_045H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Una familia huye de Nagorno-Karabaj hacia Armenia. M\u00e1s de 100.000 personas de etnia armenia evacuaron la regi\u00f3n despu\u00e9s de que cayera en manos de Azerbaiy\u00e1n en un acuerdo de alto el fuego el 20 de septiembre. (foto: Nazik Armenakyan)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo imaginamos que poco despu\u00e9s, el enemigo ya hab\u00eda ocupado nuestro pueblo\u201d, dice. \u201cTiemblo al pensar en lo que pudo haber ocurrido si nos hubi\u00e9ramos demorado unos minutos\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cEn un instante, la gente perdi\u00f3 lo que sus antepasados hab\u00edan construido minuciosamente durante siglos\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Boris, su madre, sus hermanos y sus abuelos maternos encontraron refugio en un campamento en la provincia de Shirak, al noroeste de Armenia. El campamento del Ordinariato Cat\u00f3lico Armenio, situado en Torosgyugh, normalmente organiza actividades de verano para ni\u00f1os, pero ahora acoge a refugiados de Nagorno-Karabaj en colaboraci\u00f3n con Caritas Armenia. Est\u00e1 a unas 11 millas de la segunda ciudad m\u00e1s grande de Armenia, Gyumri, pero a 208 millas del lugar que Boris llam\u00f3 hogar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia de Boris es parte de la hist\u00f3rica comunidad armenia evacuada a la fuerza este oto\u00f1o de Nagorno-Karabaj, en disputa desde hace mucho tiempo. El derecho internacional reconoce la regi\u00f3n como parte de Azerbaiy\u00e1n, pero la comunidad armenia local lo rechaz\u00f3 en la d\u00e9cada de 1990, lo que desencaden\u00f3 d\u00e9cadas de guerra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNos fuimos solo con lo que llev\u00e1bamos puesto\u201d, dice. \u201cNo hab\u00eda tiempo para ir a buscar combustible para el coche de mi padre, pero poco importaba. Al salir, todos, excepto nuestra familia, ya sab\u00edan su destino, pero decidieron no decirnos\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Sin Vuelta Atr\u00e1s\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/f9fAvJkCv8s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Kochoghot, una aldea de 560 habitantes, seg\u00fan el censo de 2010, tiene un historial de participaci\u00f3n militar. Sus residentes estuvieron (1941-1945) en varios puestos del Frente Oriental de la Segunda Guerra Mundial en la guerra entre la Uni\u00f3n Sovi\u00e9tica y la Alemania nazi; 78 de los 113 combatientes nunca regresaron. A principios de la d\u00e9cada de 1990, Kochoghot form\u00f3 dos unidades de voluntarios para luchar en la Primera Guerra de Nagorno-Karabaj. Entre ellos estaba el abuelo de Boris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi abuelo perdi\u00f3 la vida en la primera guerra, y ahora mi padre en esta\u201d, dice Boris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia viaj\u00f3 desde Kochoghot al aeropuerto de Stepanakert, cerrado desde hace mucho tiempo, donde estaban las tropas rusas de mantenimiento de la paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPasamos tres d\u00edas all\u00ed, expuestos a la intemperie, hambrientos y con fr\u00edo\u201d, dice Boris. \u201cAll\u00ed enterramos a nuestro padre en el cementerio fraterno\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_054H-1024x683.jpg\" alt=\"\" class=\"wp-image-4414\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_054H-1024x683.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_054H-300x200.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_054H-768x512.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_054H-1600x1067.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_054H-1536x1024.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_054H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Los desplazados por la fuerza de Nagorno-Karabaj llegan a Goris y se registran para partir hacia los refugios temporales proporcionados por el gobierno. (foto: Nazik Armenakyan)<\/figcaption><\/figure>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Enclavado en el coraz\u00f3n de las monta\u00f1as del C\u00e1ucaso Sur, Nagorno-Karabaj, rico en historia que abarca milenios, a menudo se omite en los mapas del mundo. Los zares rusos anexaron la regi\u00f3n armenia en 1805, pero el control de sus recursos y su gente se convirti\u00f3 en una fuente de discordia cuando Armenia y Azerbaiy\u00e1n buscaron su independencia con el colapso del Imperio Ruso en 1917.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los sovi\u00e9ticos controlaron la disputa cuando ambos pa\u00edses fueron absorbidos como rep\u00fablicas socialistas en la d\u00e9cada de 1920. En 1923, Nagorno-Karabaj se integr\u00f3 en la Rep\u00fablica Socialista Sovi\u00e9tica de Azerbaiy\u00e1n como una \u201cregi\u00f3n aut\u00f3noma\u201d, un \u201cregalo\u201d, se dice, de Stalin, que despreciaba la orgullosa cultura cristiana armenia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el fin de la Uni\u00f3n Sovi\u00e9tica en 1991, y despu\u00e9s de que Azerbaiy\u00e1n rechazara una propuesta tres a\u00f1os antes para unir la regi\u00f3n a Armenia, los armenios \u00e9tnicos declararon una rep\u00fablica independiente de Nagorno-Karabaj, tambi\u00e9n llamada Rep\u00fablica de Artsaj, que defendieron en la Primera Guerra de Nagorno-Karabaj (1991-1994).<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cNos fuimos solo con lo que llev\u00e1bamos puesta. No hab\u00eda tiempo para ir a buscar combustible para el coche de mi padre, pero poco importaba\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las fuerzas armenias expulsaron al ej\u00e9rcito azerbaiyano, apoder\u00e1ndose de otros siete distritos azerbaiyanos que limitaban con la ahora independiente Rep\u00fablica de Armenia y establecieron su propio gobierno, apoyado por Armenia. La guerra mat\u00f3 al menos a 30.000 y desplaz\u00f3 a cientos de miles en ambos bandos. A pesar del alto al fuego de 1994, continuaron estallando conflictos armados ocasionales dentro de Nagorno-Karabaj y a lo largo de la frontera entre Armenia y Azerbaiy\u00e1n, incluida una ofensiva azerbaiyana de cuatro d\u00edas en 2016.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Segunda Guerra de Nagorno-Karabaj estall\u00f3 en septiembre 2020. Durante 44 d\u00edas, unos 7.000 soldados murieron y m\u00e1s de 100.000 fueron desplazados en ambos bandos. En el alto al fuego negociado por la Federaci\u00f3n Rusa, Azerbaiy\u00e1n recuper\u00f3 los siete distritos que perdi\u00f3, as\u00ed como un tercio del territorio de Nagorno-Karabaj, aislando la regi\u00f3n de Armenia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos a\u00f1os despu\u00e9s, en diciembre 2022, Azerbaiy\u00e1n bloque\u00f3 el corredor de Lachin, la \u00fanica franja de tierra que conectaba Nagorno-Karabaj con Armenia, cortando as\u00ed el acceso a bienes esenciales y atenci\u00f3n m\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, el 19 de septiembre 2023, las fuerzas de Azerbaiy\u00e1n lanzaron un ataque a gran escala contra Nagorno-Karabaj. Seg\u00fan el acuerdo de alto al fuego alcanzado al d\u00eda siguiente, el Ej\u00e9rcito de Defensa de Artsaj fue desarmado y comenzar\u00eda el proceso de integraci\u00f3n de la regi\u00f3n en Azerbaiy\u00e1n. El 28 de septiembre, los dirigentes de la autoproclamada Rep\u00fablica de Nagorno-Karabaj acordaron disolverla antes del 1 de enero de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La operaci\u00f3n militar de un d\u00eda mat\u00f3 a m\u00e1s de 220 personas de etnia armenia y provoc\u00f3 la huida de m\u00e1s de 100.000 a Armenia. Para el 30 de septiembre, Nagorno-Karabaj, que lleg\u00f3 a tener una poblaci\u00f3n de 120.000, se hab\u00eda vaciado en gran medida.<\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Cruzar a Armenia a lo largo del corredor de Lachin fue el primer encuentro con las fuerzas azerbaiyanas para la hermana de Boris, Arpine, de 19 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTrat\u00e9 de convencerme de que eran como nosotros, gente com\u00fan que segu\u00eda \u00f3rdenes, pero no pod\u00eda dejar de temblar, sin saber qu\u00e9 pasar\u00eda en ese momento\u201d, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viaje de dos horas desde Stepanakert hasta la frontera armenia en Kornidzor dur\u00f3 casi dos d\u00edas. Luego continuaron hasta el campamento de refugiados, del que se hab\u00edan enterado por su vecina, Rima Poghosyan, y llegaron el 10 de octubre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El campamento cuenta con varias caba\u00f1as, un encantador paseo, una capilla y un comedor. Cada caba\u00f1a tiene cinco habitaciones con ba\u00f1o privado. Ropa reci\u00e9n lavada cuelga cuidadosamente afuera. El aroma a comida caliente flota desde la cocina del campamento. Al caer la noche, el parque infantil reverbera con los alegres sonidos de los ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una habitaci\u00f3n de una caba\u00f1a, la madre de Boris llora en un rinc\u00f3n. Cerca, su abuela a la loter\u00eda con su hermano, para distraerse. El ni\u00f1o asiste a la escuela local. Sus compa\u00f1eros de clase lo apoyan a pesar de que le cuesta entender el dialecto local. Boris, en cambio, se ha visto obligado a madurar m\u00e1s r\u00e1pido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cBusco trabajo para satisfacer las necesidades de mi familia\u201d, dice. \u201cNuestro futuro depende de ello\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la familia huy\u00f3 a Armenia durante la Segunda Guerra de Nagorno-Karabaj, creyeron que regresar\u00edan a Kochoghot, dice. Pero esta vez no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNi siquiera pudimos tomar una foto de mi hermano de 7 a\u00f1os que falleci\u00f3 en un accidente automovil\u00edstico. Todo sucedi\u00f3 muy r\u00e1pido y entramos en p\u00e1nico\u201d, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi tan solo hubiera podido recuperar el coche de mi padre y la foto de mi hermano. Y mover\u00eda la tumba de mi padre. Nada m\u00e1s\u201d.<\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Rima Poghosyan, su nuera y seis nietos tambi\u00e9n huyeron de Kochoghot el 20 de septiembre, buscando refugio entre las tropas rusas de mantenimiento de la paz en el aeropuerto de Stepanakert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, expuestos a la intemperie, decidieron refugiarse en un hotel y despu\u00e9s en el s\u00f3tano de una escuela. Sus tres hijos, que luchaban en la frontera, se reunieron con la familia el 24 de septiembre. Salieron de Stepanakert tres d\u00edas despu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUn anciano enfermo muri\u00f3 en nuestro coche, lo que nos llev\u00f3 a pasar r\u00e1pidamente por el puesto de control\u201d, relata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es su segunda vez en el campamento de Torosgyugh, donde su familia se refugi\u00f3 por siete meses debido a la guerra de 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNos esperaban aqu\u00ed, como si hubi\u00e9ramos regresado a casa, lo que significaba mucho\u201d, dice. \u201cLo perdimos todo, lo dejamos todo, fuimos testigos de todo. Por lo menos, hemos recibido una c\u00e1lida acogida aqu\u00ed\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los 11 miembros de su familia viven en una caba\u00f1a. Su hijo mayor, su esposa y sus seis hijos, ocupan una habitaci\u00f3n; ella y otros dos hijos ocupan otra. Un vecino anciano vive en la tercera habitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los trabajadores de Caritas llevaron a cabo una evaluaci\u00f3n de las necesidades y ex\u00e1menes m\u00e9dicos, proporcionando lo esencial. Una trabajadora social visit\u00f3 el campamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poghosyan destaca el contraste entre la atenci\u00f3n que reciben en el campamento y lo que soportaron durante el bloqueo, cuando \u201ccasi no hab\u00eda comida, y la poca que hab\u00eda disponible ten\u00eda precios exorbitantes\u201d. Recuerda haber molido cebada, garbanzos y lentejas para crear un sustituto del caf\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara los ni\u00f1os, incluso molimos el alimento para cerdos para asegurarnos de que tuvieran algo que comer. Hab\u00eda noches en las que nos \u00edbamos a la cama con hambre, pero acept\u00e1bamos nuestra situaci\u00f3n. Nos mantuvimos firmes en nuestra tierra\u201d, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo si soportar esos nueve meses de privaciones no fuera suficiente, tal vez [los azerbaiyanos] no estaban seguros de que nos fu\u00e9ramos, por lo que recurrieron a la guerra, asegur\u00e1ndose de que no tuvi\u00e9ramos otra opci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante sus momentos m\u00e1s dif\u00edciles, dice, encuentra consuelo en la oraci\u00f3n y en sus fervientes s\u00faplicas a Dios por la seguridad de sus hijos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDios contest\u00f3 mis oraciones. Mis hijos lograron salir sanos y salvos, y ahora estamos en este maravilloso campamento donde recibimos apoyo constante\u201d, dice. \u201cDespu\u00e9s de soportar tanto dolor, realmente necesitamos esta ayuda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reverendo Grigor Mkrtchyan, rector de la Catedral de los Santos M\u00e1rtires en Gyumri, ministra principalmente a los desplazados por la guerra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTuvimos v\u00edctimas, y un mayor n\u00famero de personas fueron desarraigadas por la fuerza de sus hogares, despojadas de su herencia cultural y espiritual\u201d, dice. \u201cNecesitan nuestra compasi\u00f3n; est\u00e1n en un estado psicol\u00f3gico fr\u00e1gil\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn los primeros d\u00edas, trajimos psic\u00f3logos. Los equipos m\u00e9dicos los visitan regularmente, asegur\u00e1ndose de que reciban la atenci\u00f3n que requieren\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mediados de octubre, el campamento ten\u00eda 90 personas, casi la mitad menores de 14 a\u00f1os. Eran 150 personas solo unos d\u00edas antes. Durante ese tiempo, el cura bautiz\u00f3 a 36 refugiados en la capilla del campo y organiz\u00f3 el Rito de la Santa Coronaci\u00f3n para las parejas que a\u00fan no se hab\u00edan casado en la iglesia. Los ni\u00f1os del campamento fueron matriculados en la escuela local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inicialmente, se esperaba que los refugiados permanecieran en el campamento seis meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSin embargo, es evidente que nadie los dejar\u00e1 sin refugio si no pueden encontrar un lugar propio, a pesar de que enfrentamos serias limitaciones econ\u00f3micas\u201d, dice el padre Mkrtchyan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iglesia est\u00e1 recaudando fondos para apoyar el campamento y construir un hogar para los refugiados ancianos, ya que los dos hogares de ancianos en la provincia de Shirak est\u00e1n llenos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstas personas han superado enormes dificultades para llegar a Armenia\u201d, dice Mkrtich Babayan, que dirige el programa de Caritas Armenia para los desplazados de Nagorno-Karabaj.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Babayan describe el tipo de atenci\u00f3n que la organizaci\u00f3n ben\u00e9fica de la comunidad cat\u00f3lica ha podido brindar en el campamento: tres comidas al d\u00eda, lavander\u00eda y dispositivos de calefacci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl clima es fr\u00edo y estamos trabajando para mejorar las condiciones\u201d, dice. \u201cEstas personas estaban en estado de shock, y poder recibirlas y no dejar a nadie a la intemperie fue un esfuerzo tremendo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caritas Armenia tambi\u00e9n oper\u00f3 un centro de refugiados en Goris, cerca de la frontera entre Armenia y Azerbaiy\u00e1n, en los primeros d\u00edas de la evacuaci\u00f3n de Nagorno-Karabaj. All\u00ed, distribuy\u00f3 paquetes de alimentos e higiene a 100 familias, as\u00ed como 50 colchones. Proporcion\u00f3 comidas calientes a 3.000 personas en un centro de registro en la provincia de Vayots Dzor, unos 500 juegos de ropa de cama en la provincia de Ararat y ropa de invierno a cientos de personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs una tragedia y una cat\u00e1strofe para nuestro pueblo\u201d, dice Babayan. \u201cEn un instante, la gente perdi\u00f3 lo que sus antepasados hab\u00edan construido minuciosamente durante siglos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs nuestro deber moral ofrecerles apoyo e integrarlos. Es un problema urgente que requiere una soluci\u00f3n a largo plazo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Lea este art\u00edculo en nuestro formato de impresi\u00f3n digital <a href=\"https:\/\/issuu.com\/cnewa\/docs\/one_magazine_en_espan_ol_enero_2024\/6\">aqu\u00ed<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Armenios \u00e9tnicos huyen de Nagorno-Karabaj sin esperanza de regresar<\/p>\n","protected":false},"author":70019,"featured_media":4416,"template":"","magazine-issues":[940],"magazine-sections":[143],"class_list":["post-4420","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","magazine-issues-enero-2024","magazine-sections-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sin Vuelta Atr\u00e1s | ONE en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sin Vuelta Atr\u00e1s | ONE en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Armenios \u00e9tnicos huyen de Nagorno-Karabaj sin esperanza de regresar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-12T19:47:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_036H.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/\",\"name\":\"Sin Vuelta Atr\u00e1s | ONE en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/01\\\/armenakyan202310_036H.jpg\",\"datePublished\":\"2024-01-10T17:07:36+00:00\",\"dateModified\":\"2024-01-12T19:47:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/01\\\/armenakyan202310_036H.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/01\\\/armenakyan202310_036H.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"Refugiados de etnia armenia de Nagorno-Karabaj llegan a Goris, Armenia. (foto: Nazik Armenakyan)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/sin-vuelta-atras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Magazine\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sin Vuelta Atr\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sin Vuelta Atr\u00e1s | ONE en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/","og_locale":"es_ES","og_type":"article","og_title":"Sin Vuelta Atr\u00e1s | ONE en Espa\u00f1ol","og_description":"Armenios \u00e9tnicos huyen de Nagorno-Karabaj sin esperanza de regresar","og_url":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_modified_time":"2024-01-12T19:47:58+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_036H.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/","url":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/","name":"Sin Vuelta Atr\u00e1s | ONE en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_036H.jpg","datePublished":"2024-01-10T17:07:36+00:00","dateModified":"2024-01-12T19:47:58+00:00","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_036H.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/01\/armenakyan202310_036H.jpg","width":1800,"height":1200,"caption":"Refugiados de etnia armenia de Nagorno-Karabaj llegan a Goris, Armenia. (foto: Nazik Armenakyan)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/revista\/sin-vuelta-atras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"One Magazine","item":"https:\/\/cnewa.org\/es\/revista\/"},{"@type":"ListItem","position":3,"name":"Sin Vuelta Atr\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/4420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/magazine"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"version-history":[{"count":0,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/4420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/4416"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=4420"}],"wp:term":[{"taxonomy":"magazine-issues","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-issues?post=4420"},{"taxonomy":"magazine-sections","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-sections?post=4420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}