{"id":5166,"date":"2024-06-03T13:57:58","date_gmt":"2024-06-03T17:57:58","guid":{"rendered":"https:\/\/cnewa.org\/es\/?post_type=magazine&#038;p=5166"},"modified":"2024-06-06T14:00:13","modified_gmt":"2024-06-06T18:00:13","slug":"una-peregrinacion-a-una-tierra-de-corazones-rotos","status":"publish","type":"magazine","link":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/","title":{"rendered":"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos"},"content":{"rendered":"\n<p><em>El autor Michael J.L. La Civita se uni\u00f3 al presidente de CNEWA, Mons. Peter I. Vaccari, en una <a href=\"https:\/\/cnewa.org\/es\/revista\/un-signo-de-esperanza-en-tierra-santa\/\">visita pastoral a Tierra Santa<\/a>, encabezada por el director de la junta ejecutiva de CNEWA, el cardenal Timothy M. Dolan, en abril. El viaje descubri\u00f3 un elemento com\u00fan en todos los pueblos de la regi\u00f3n: los corazones de todos est\u00e1n destrozados.<\/em><\/p>\n\n\n\n<p><strong>Fue a conmemorar.<\/strong> El rol pastoral del arzobispo de Nueva York \u2014ministra a m\u00e1s de 2.5 millones de cat\u00f3licos en 10 condados de Nueva York\u2014 tambi\u00e9n incluye liderar iniciativas locales, nacionales e internacionales de la iglesia. Una de esas ellas es la Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente (CNEWA), que cada arzobispo de Nueva York ha dirigido ex officio despu\u00e9s de que la Santa Sede reorganiz\u00f3 su administraci\u00f3n en 1931.<\/p>\n\n\n\n<p>Desde que el Papa Benedicto XVI nombr\u00f3 a Timothy M. Dolan como arzobispo de Nueva York en 2009, \u00e9l ha liderado las delegaciones de CNEWA en visitas al L\u00edbano (dos veces), Jordania, India, Irak, Polonia, Eslovaquia y Ucrania. Del 12 al 17 de abril, viaj\u00f3 a Israel y Palestina para conmemorar el 75 aniversario de la Misi\u00f3n Pontificia para Palestina, la agencia operativa de CNEWA en el Medio Oriente.<\/p>\n\n\n\n<p>El aniversario conmemora el cuidado de la Santa Sede por los vulnerables que viven en las tierras que llamamos santas. Conmovido por el despojo de m\u00e1s de 750.000 palestinos durante la guerra \u00e1rabe-israel\u00ed de 1948 \u2014conocida como Nakba, o cat\u00e1strofe, en \u00e1rabe\u2014 el Papa P\u00edo XII estableci\u00f3 la Misi\u00f3n Pontificia como un comit\u00e9 ad hoc para coordinar la ayuda cat\u00f3lica mundial para ayudarlos, y estableci\u00f3 su administraci\u00f3n bajo CNEWA.<\/p>\n\n\n\n<p>\u201cLos consideramos socios\u201d, dijo el cardenal a los sacerdotes, religiosos y laicos de las organizaciones que se han asociado con los equipos de la Misi\u00f3n Pontificia en Jerusal\u00e9n, Amm\u00e1n y Beirut durante una misa el 13 de abril en la capilla del Centro del Instituto Pontificio de Nuestra Se\u00f1ora de Jerusal\u00e9n.<\/p>\n\n\n\n<p>\u201cLos vemos como miembros de nuestra familia. Siempre han sido parte del carisma de la Misi\u00f3n Pontificia y de la Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente que veamos nuestros esfuerzos, no como que hacemos algo por ustedes, no que les hacemos algo, sino que hacemos algo con ustedes. Con ustedes, juntos. Juntos somos\u201d.<\/p>\n\n\n\n<p>Desde la dispersi\u00f3n de los refugiados palestinos, el Medio Oriente ha sufrido d\u00e9cadas de conflictos civiles y militares, convulsiones pol\u00edticas y colapso socioecon\u00f3mico, que han impactado a generaciones de israel\u00edes y palestinos, iraqu\u00edes y jordanos, libaneses y sirios. Posteriormente, los sucesores del Papa P\u00edo XII ampliaron el alcance y la circunscripci\u00f3n de la Misi\u00f3n Pontificia para brindar asistencia humanitaria a los m\u00e1s vulnerables en toda la regi\u00f3n, sin importar de su etnia, nacionalidad o identidad religiosa.<\/p>\n\n\n\n<p><strong>Fue a escuchar.<\/strong> Como pastor, el arzobispo de Nueva York atiende las almas de todos, tanto cat\u00f3licos, como no cat\u00f3licos. Por lo tanto, el cardenal Dolan anhelaba reunirse con los sobrevivientes de los ataques terroristas del 7 de octubre por parte de Ham\u00e1s contra Israel, y con las familias de aquellos que han sido tomados como rehenes. Los conoci\u00f3, escuch\u00f3 sus corazones y mentes, comparti\u00f3 su dolor y ofreci\u00f3 su consuelo y el de todos los neoyorquinos, cuyos corazones todav\u00eda est\u00e1n dolidos despu\u00e9s de los ataques del 11 de septiembre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0449-cc-r1-1024x768.jpg\" alt=\"\" class=\"wp-image-5168\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0449-cc-r1-1024x768.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0449-cc-r1-300x225.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0449-cc-r1-768x576.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0449-cc-r1-1600x1200.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0449-cc-r1-1536x1152.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0449-cc-r1.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">El cardenal Dolan y el rabino Noam Marans, fondo izq., se re\u00fanen con las familias de los rehenes israel\u00edes en  el Instituto Ecum\u00e9nico Tantur en Jerusal\u00e9n, el 16 de abril. (foto: Michael J.L. La Civita)<\/figcaption><\/figure>\n\n\n\n<p>Se\u00f1al\u00f3 que a quienes atac\u00f3 Ham\u00e1s eran las mismas personas que hab\u00edan abierto sus puertas al di\u00e1logo, patrocinando eventos para que israel\u00edes y palestinos se conocieran mejor, hombres y mujeres que buscaban dejar atr\u00e1s la confrontaci\u00f3n y hacer algo m\u00e1s que simplemente coexistir, buscaban desmantelar la noci\u00f3n del \u201cotro\u201d.<\/p>\n\n\n\n<p>Les agradeci\u00f3 su generosidad de esp\u00edritu, por abrir esa puerta y, aunque reconoci\u00f3 que sus corazones estaban destrozados y sus esp\u00edritus aplastados, y que sent\u00edan ira y temor por la suerte de sus seres queridos, les pidi\u00f3 que nunca perdieran la esperanza, y que sigan abriendo sus corazones a la esperanza de una paz justa y duradera.<\/p>\n\n\n\n<p><strong>Fue a inspirar.<\/strong> \u201cMientras contemplamos con gratitud los 75 a\u00f1os de la Misi\u00f3n Pontificia\u201d, dijo en su homil\u00eda en Nuestra Se\u00f1ora, \u201cpienso en las madres\u201d.<\/p>\n\n\n\n<p>\u201cMadres. Siempre que hay alegr\u00eda o tristeza en nuestras vidas, est\u00e1 la presencia de las madres\u201d.<\/p>\n\n\n\n<p>\u201cY con todo el trauma, todas las dificultades y todos los desaf\u00edos que ha atravesado el pueblo de Dios aqu\u00ed en Tierra Santa, incluso hasta ahora, las madres, con sus beb\u00e9s e hijos, siempre est\u00e1n en la primera l\u00ednea de la necesidad de amor y apoyo\u201d.<\/p>\n\n\n\n<p>\u201cPienso en nuestra Sant\u00edsima Madre Mar\u00eda, para quien este tambi\u00e9n era su hogar. Pienso en nuestra santa madre, la iglesia\u201d.<\/p>\n\n\n\n<p>El cardenal pensaba tambi\u00e9n en su propia madre, fallecida hace algunos a\u00f1os.<\/p>\n\n\n\n<p>\u201cDespu\u00e9s de su muerte\u201d, dijo, \u201cme di cuenta de que, en cierto modo, no tengo un hogar. \u2026 porque un sacerdote que no se ha casado, siempre considera su hogar donde vive su madre\u201d.<\/p>\n\n\n\n<p>\u201cY me di cuenta de que, como cat\u00f3lico, como creyente, siempre tenemos una madre. \u2026 en la Sant\u00edsima Madre de Jes\u00fas. \u2026 en la santa madre iglesia. \u2026 Siempre tenemos una iglesia madre aqu\u00ed en Jerusal\u00e9n, en Tierra Santa. Entonces, para m\u00ed, venir y estar con ustedes es en muchos sentidos, volver a casa.<\/p>\n\n\n\n<p>\u201cPor eso, nos sentimos en casa aqu\u00ed. Somos familia. Somos uno, y eso nos da un gran est\u00edmulo en nuestro trabajo, una gran esperanza\u2026. Y cuanto m\u00e1s dif\u00edciles se vuelven las cosas, m\u00e1s esperanzas tenemos y trabajamos m\u00e1s\u201d.<\/p>\n\n\n\n<p>\u201cUstedes lo hacen bien\u201d, concluy\u00f3, \u201cy son una inspiraci\u00f3n para nosotros\u201d.<\/p>\n\n\n\n<p>Al d\u00eda siguiente, despu\u00e9s de que la C\u00fapula de Hierro de Israel neutralizara la mayor\u00eda de los drones y misiles disparados por Ir\u00e1n en represalia por el ataque de Israel a una estructura diplom\u00e1tica iran\u00ed en Damasco, el cardenal Dolan viaj\u00f3 a la ciudad cristiana palestina de Beit Jala, un suburbio de Bel\u00e9n. Celebr\u00f3 la misa dominical en la iglesia de la Anunciaci\u00f3n, repleta de familias ansiosas por escuchar al cardenal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"585\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/Screenshot-2024-04-26-at-10.25.31\u202fAM-copy-1024x585.jpg\" alt=\"\" class=\"wp-image-5169\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/Screenshot-2024-04-26-at-10.25.31\u202fAM-copy-1024x585.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/Screenshot-2024-04-26-at-10.25.31\u202fAM-copy-300x171.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/Screenshot-2024-04-26-at-10.25.31\u202fAM-copy-768x439.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/Screenshot-2024-04-26-at-10.25.31\u202fAM-copy-1600x914.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/Screenshot-2024-04-26-at-10.25.31\u202fAM-copy-1536x877.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/Screenshot-2024-04-26-at-10.25.31\u202fAM-copy.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">El cardenal Dolan se re\u00fane con el presidente palestino Mahmoud Abbas en Ramala, el 14 de abril. (foto: George Jaraiseh)<\/figcaption><\/figure>\n\n\n\n<p>\u201cEstos son d\u00edas de angustia y dificultad para ustedes. \u2026 Tienen todas las razones para tener miedo, estar triste. Pero cuando entramos a esta iglesia esta ma\u00f1ana, no vi miedo\u201d, dijo, mientras su voz se elev\u00f3 con premura, sentimiento y volumen.<\/p>\n\n\n\n<p>\u201cNo vi tristeza. \u00a1Los o\u00ed cantar, Aleluya! \u00a1Aleluya! Los vi sonre\u00edr. Vi sus ojos d\u00e1ndonos la bienvenida y eso, amigos m\u00edos, nos da esperanza\u201d.<\/p>\n\n\n\n<p>\u201cY por eso, les digo, gracias\u201d.<\/p>\n\n\n\n<p><em>Lea este art\u00edculo en nuestro formato de impresi\u00f3n digital <a href=\"https:\/\/issuu.com\/cnewa\/docs\/one-50-2-2024-final-spanish-issuu\/8\">aqu\u00ed<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El autor Michael J.L. La Civita se uni\u00f3 al presidente de CNEWA, Mons. Peter I. Vaccari, en una visita pastoral a Tierra Santa, encabezada por el director de la junta ejecutiva de CNEWA, el cardenal Timothy M. Dolan, en abril. El viaje descubri\u00f3 un elemento com\u00fan en todos los pueblos de la regi\u00f3n: los corazones &hellip; <a href=\"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/\">Continued<\/a><\/p>\n","protected":false},"author":70019,"featured_media":5167,"template":"","magazine-issues":[1063],"magazine-sections":[143],"class_list":["post-5166","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","magazine-issues-junio-2024","magazine-sections-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos | ONE en Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos | ONE en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"El autor Michael J.L. La Civita se uni\u00f3 al presidente de CNEWA, Mons. Peter I. Vaccari, en una visita pastoral a Tierra Santa, encabezada por el director de la junta ejecutiva de CNEWA, el cardenal Timothy M. Dolan, en abril. El viaje descubri\u00f3 un elemento com\u00fan en todos los pueblos de la regi\u00f3n: los corazones &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T18:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0134-e1717423103466.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/\",\"name\":\"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos | ONE en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/IMG_0134-e1717423103466.jpg\",\"datePublished\":\"2024-06-03T17:57:58+00:00\",\"dateModified\":\"2024-06-06T18:00:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/IMG_0134-e1717423103466.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/IMG_0134-e1717423103466.jpg\",\"width\":1350,\"height\":906,\"caption\":\"De izq. a dcha.: Joseph Hazboun, Mons. Peter I. Vaccari y el cardenal Timothy M. Dolan se re\u00fanen despu\u00e9s de visitar el campamento de refugiados de Aida, el 14 de abril. (foto: Michael J.L. La Civita)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/una-peregrinacion-a-una-tierra-de-corazones-rotos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Magazine\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos | ONE en Espa\u00f1ol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/","og_locale":"es_ES","og_type":"article","og_title":"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos | ONE en Espa\u00f1ol","og_description":"El autor Michael J.L. La Civita se uni\u00f3 al presidente de CNEWA, Mons. Peter I. Vaccari, en una visita pastoral a Tierra Santa, encabezada por el director de la junta ejecutiva de CNEWA, el cardenal Timothy M. Dolan, en abril. El viaje descubri\u00f3 un elemento com\u00fan en todos los pueblos de la regi\u00f3n: los corazones &hellip; Continued","og_url":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_modified_time":"2024-06-06T18:00:13+00:00","og_image":[{"width":1350,"height":906,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0134-e1717423103466.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/","url":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/","name":"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos | ONE en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0134-e1717423103466.jpg","datePublished":"2024-06-03T17:57:58+00:00","dateModified":"2024-06-06T18:00:13+00:00","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0134-e1717423103466.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/IMG_0134-e1717423103466.jpg","width":1350,"height":906,"caption":"De izq. a dcha.: Joseph Hazboun, Mons. Peter I. Vaccari y el cardenal Timothy M. Dolan se re\u00fanen despu\u00e9s de visitar el campamento de refugiados de Aida, el 14 de abril. (foto: Michael J.L. La Civita)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/revista\/una-peregrinacion-a-una-tierra-de-corazones-rotos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"One Magazine","item":"https:\/\/cnewa.org\/es\/revista\/"},{"@type":"ListItem","position":3,"name":"Una Peregrinaci\u00f3n a una Tierra de Corazones Rotos"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/5166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/magazine"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"version-history":[{"count":0,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/5166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/5167"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=5166"}],"wp:term":[{"taxonomy":"magazine-issues","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-issues?post=5166"},{"taxonomy":"magazine-sections","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-sections?post=5166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}