{"id":5174,"date":"2024-06-03T13:57:10","date_gmt":"2024-06-03T17:57:10","guid":{"rendered":"https:\/\/cnewa.org\/es\/?post_type=magazine&#038;p=5174"},"modified":"2024-06-07T15:06:46","modified_gmt":"2024-06-07T19:06:46","slug":"un-lugar-al-que-pertenecer","status":"publish","type":"magazine","link":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/","title":{"rendered":"Un Lugar al que Pertenecer"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Una furgoneta va por una calle asfaltada en un remoto suburbio de Tbilisi, capital de Georgia, luego da tumbos por un callej\u00f3n de barro con casas desmoronadas, construidas con materiales encontrados, que contrastan con las casas con altas verjas de metal. Un pu\u00f1ado de ni\u00f1os de ropas andrajosas y zapatos impares que no les quedan, persiguen a la camioneta entre los charcos hasta que se estaciona en un callej\u00f3n sin salida.<\/p>\n\n\n\n<p>\u201c\u00a1Hola!\u201d gritan los ni\u00f1os, emocionados porque, como todos los martes, ha llegado a la barriada su escuela m\u00f3vil, operada por un proyecto de <a href=\"https:\/\/www.caritas.org\/donde-trabajamos\/europe\/georgia\/?lang=es\">Caritas Georgia<\/a>, llamado \u201cEmegobre\u201d (\u201cS\u00e9 un amigo\u201d), que administra un centro diurno para j\u00f3venes en Tbilisi.<\/p>\n\n\n\n<p>Del remolque se despliega en paneles deslizantes un aula m\u00f3vil que, con juegos interactivos, explica fundamentos de lectura, escritura y aritm\u00e9tica a ni\u00f1os con poca educaci\u00f3n o, como estos ni\u00f1os, sin educaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_014H-1024x819.jpg\" alt=\"\" class=\"wp-image-5176\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_014H-1024x819.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_014H-300x240.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_014H-768x614.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_014H-1600x1280.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_014H-1536x1229.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_014H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La maestra Teona Gedenidze, izq., facilita el aprendizaje de los ni\u00f1os de la calle en Tbilisi. (foto: Justyna Mielnikiewicz)<\/figcaption><\/figure>\n\n\n\n<p>Teona Gedenidze, profesora y coordinadora de la escuela m\u00f3vil, pone m\u00fasica y atrae a\u00fan m\u00e1s ni\u00f1os. Una asistente de educaci\u00f3n entre pares de 14 a\u00f1os y beneficiaria de Emegobre ayuda a Gedenidze a ense\u00f1ar a los 12 ni\u00f1os emocionados, reunidos para aprender el alfabeto georgiano y a contar. Despu\u00e9s de sus lecciones, participan en una producci\u00f3n de teatro y danza.<\/p>\n\n\n\n<p>\u201cPara estos ni\u00f1os, esta es la \u00fanica educaci\u00f3n que han visto en su vida\u201d, dice Gedenidze.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Un Lugar al que Pertenecer\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/mbOrbZD2aFc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Caritas tiene otra escuela m\u00f3vil, operada por \u201cTbili Sakhli\u201d (\u201cCasa C\u00e1lida\u201d), un centro de atenci\u00f3n para j\u00f3venes abierto las 24 horas en Rustavi, a unas 18 millas de la capital. El a\u00f1o pasado, las dos escuelas m\u00f3viles llegaron a 246 ni\u00f1os.<\/p>\n\n\n\n<p>Ambas escuelas m\u00f3viles atienden a comunidades pobres de familias inmigrantes mayormente kurdas-azer\u00edes de Azerbaiy\u00e1n, donde la mendicidad se castiga con penas&nbsp;&nbsp;de c\u00e1rcel. Los inmigrantes indocumentados que cruzan a Georgia en busca de trabajo no tienen derechos legales.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El equipo m\u00f3vil tiene mayor \u00e9xito cuando los ni\u00f1os son peque\u00f1os. Las intervenciones se vuelven m\u00e1s dif\u00edciles cuanto m\u00e1s tiempo pasa un ni\u00f1o en la calle.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Aunque la <a href=\"https:\/\/www.ohchr.org\/en\/human-rights\/universal-declaration\/translations\/spanish\">Declaraci\u00f3n Universal de Derechos Humanos<\/a> establece que \u201ctoda persona tiene derecho a la educaci\u00f3n\u201d, la educaci\u00f3n b\u00e1sica es inalcanzable para muchos ni\u00f1os en Georgia. Muchas circunstancias los mantienen en las calles, donde mendigan, ganando entre 20 y 50 lari georgianos (entre $7 y $20) al d\u00eda, muy por debajo del ingreso diario promedio en Georgia, seg\u00fan la Oficina Nacional de Estad\u00edsticas del pa\u00eds. El salario mensual medio es de 1.858 lari ($700).<\/p>\n\n\n\n<p>A menudo, un miembro de la familia obliga a estos ni\u00f1os a mendigar; algunos de estos ni\u00f1os son la \u00fanica fuente de ingresos de su familia. En algunos casos, los padres entregan a sus hijos a los acreedores, que los obligan a mendigar hasta que se salden las cuentas.<\/p>\n\n\n\n<p>El Departamento de Estado de EE. UU. y organizaciones no gubernamentales, como Anti-Slavery International y la Organizaci\u00f3n Internacional del Trabajo, han identificado la mendicidad infantil forzada como una forma de trata y esclavitud moderna. El Departamento de Estado de EE. UU. ha documentado que los ni\u00f1os de la calle en Georgia tambi\u00e9n son vulnerables a otras formas de trata.<\/p>\n\n\n\n<p>A medida que crecen y su ternura se desvanece, el potencial de ingresos de un ni\u00f1o mendigo disminuye. A la edad de 14 a\u00f1os, indican los trabajadores sociales, los ni\u00f1os suelen recurrir a la delincuencia, como el robo, y las ni\u00f1as a la prostituci\u00f3n. Dado que la ley georgiana no procesa a ni\u00f1os menores de 14 a\u00f1os, muchos j\u00f3venes son explotados por adolescentes mayores, como Oliver Twists modernos.<\/p>\n\n\n\n<p>Aunque no existen cifras exactas sobre el n\u00famero de ni\u00f1os de la calle en Georgia, un amplio estudio realizado por Save the Children en 2007 y publicado en 2009 estim\u00f3 que cerca de 1.600 ni\u00f1os viv\u00edan en las calles de las cuatro ciudades m\u00e1s grandes de Georgia: Tbilisi, Kutaisi, Rustavi y Batumi. Tambi\u00e9n inform\u00f3 que el 86% de estos ni\u00f1os no estaban matriculados en la escuela y el 60% nunca hab\u00eda ingresado a un sal\u00f3n de clases.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_069H-1024x819.jpg\" alt=\"\" class=\"wp-image-5177\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_069H-1024x819.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_069H-300x240.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_069H-768x614.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_069H-1600x1280.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_069H-1536x1229.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_069H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Tamar Sharashidze y Jemal Chachkhaia trabajan en el Centro Emegobre para ni\u00f1os de la calle en Tbilisi. (foto: Justyna Mielnikiewicz)<\/figcaption><\/figure>\n\n\n\n<p>Seg\u00fan trabajadores sociales, la ausencia de estad\u00edsticas precisas refleja el desinter\u00e9s del Estado por los ni\u00f1os y las familias desfavorecidas. A Georgia le falta desarrollar una estrategia de vivienda o un plan de acci\u00f3n para personas sin hogar que corresponda a las normas o mecanismos internacionales para la prevenci\u00f3n de la falta de vivienda.<\/p>\n\n\n\n<p class=\"has-drop-cap\">Sopo Mezvrilishvili ten\u00eda 6 a\u00f1os cuando su padre soltero la dej\u00f3 en el centro Caritas Nutsubidze en Tbilisi. Cuando \u00e9l muri\u00f3 dos a\u00f1os despu\u00e9s, ella fue internada en un orfanato estatal, pero se fue a las calles como otros ni\u00f1os. Regres\u00f3 como beneficiaria cuando ten\u00eda 18 a\u00f1os y luego a los 20, embarazada de su primera hija. Se qued\u00f3 en el centro de atenci\u00f3n materno infantil Santa B\u00e1rbara de Caritas en Tbilisi despu\u00e9s que naci\u00f3 su tercera hija.<\/p>\n\n\n\n<p>Ahora, madre soltera de 30 a\u00f1os con poca educaci\u00f3n, ha mantenido a su familia como madre subrogada. La subrogaci\u00f3n es una fuente legal de ingresos en Georgia a la que recurren algunas mujeres cuando tienen dificultades econ\u00f3micas.<\/p>\n\n\n\n<p>Mezvrilishvili trae a diario a sus tres hijas a Emegobre para diversas actividades. Est\u00e1 decidida en darle a sus hijas la vida estable que&nbsp;&nbsp;nunca tuvo, pero las probabilidades est\u00e1n en su contra. Sus brutales experiencias dentro y fuera de las calles le han dificultado pensar m\u00e1s all\u00e1 del presente. Cuando se le pregunta qu\u00e9 le gustar\u00eda hacer en el futuro, se queda en blanco. Est\u00e1 en modo de supervivencia, consumida por el temor que la desalojen de su peque\u00f1o departamento, ya que los alquileres en la ciudad de repente casi se duplicaron.<\/p>\n\n\n\n<p>\u201cSopo ama mucho a sus hijos y est\u00e1 muy involucrada en sus vidas, pero sin ingresos estables, no tiene perspectivas de tener su propia casa. No existen programas estatales para madres solteras\u201d, afirma Irina Abuladze, directora de Emegobre.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cAmo a estos ni\u00f1os. Quiero que tengan una buena vida. Todos los ni\u00f1os tienen ese derecho\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Seg\u00fan la Oficina Nacional de Estad\u00edsticas, la tasa de desempleo promedio en Georgia fue del 16.4% en 2023, aunque estimados no oficiales la sit\u00faan mucho m\u00e1s alta. A pesar de la reforma del bienestar social, los programas siguen siendo muy limitados.&nbsp;<\/p>\n\n\n\n<p class=\"has-drop-cap\">Las organizaciones humanitarias internacionales, como Caritas, tratan de llenar los vac\u00edos de la seguridad social del pa\u00eds, pero las crecientes necesidades son un desaf\u00edo demasiado grande para las organizaciones sin fines de lucro.<\/p>\n\n\n\n<p>En particular, los trabajadores juveniles reportan un fuerte aumento de problemas de conducta juvenil, entre los j\u00f3venes en riesgo.<\/p>\n\n\n\n<p>\u201cNecesitamos servicios especiales de atenci\u00f3n psiqui\u00e1trica\u201d, afirma Abuladze.<\/p>\n\n\n\n<p>El estado cubre menos del 50% de los costos de siete programas para j\u00f3venes de la calle, que ofrecen refugios las 24 horas, instalaciones diurnas y equipos m\u00f3viles en Batumi, Kutaisi, Tbilisi y Rustavi. Estos programas est\u00e1n a cargo de varios proveedores internacionales, adem\u00e1s de Caritas.<\/p>\n\n\n\n<p>Mantener suficiente personal calificado en estas condiciones es dif\u00edcil. Con el personal abrumado por las necesidades f\u00edsicas y psicol\u00f3gicas de los j\u00f3venes, Caritas tom\u00f3 la dif\u00edcil decisi\u00f3n de cerrar sus centros de 24 horas en Batumi y Tbilisi; y el albergue operado por Emegobre tambi\u00e9n est\u00e1 en proceso de cierre.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_001H-1024x819.jpg\" alt=\"\" class=\"wp-image-5178\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_001H-1024x819.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_001H-300x240.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_001H-768x614.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_001H-1600x1280.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_001H-1536x1229.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_001H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sopo Mezvrilishvili y sus hijas asisten diariamente en Emegobre. (foto: Justyna Mielnikiewicz)<\/figcaption><\/figure>\n\n\n\n<p>\u201cSolo trabaj\u00e1bamos otro chico y yo en turnos de 24 horas\u201d, dice Jemal Chachkhaia, trabajador juvenil de Caritas. \u201cDiez de los 12 ni\u00f1os padec\u00edan problemas de conducta. La m\u00e1s m\u00ednima cosa podr\u00eda hacerles estallar. Tuvimos que cerrar antes de que ocurriera una cat\u00e1strofe\u201d.<\/p>\n\n\n\n<p>\u201cSolicitamos ayuda al Ministerio de Salud, pero nunca devolvieron nuestras llamadas. Estos ni\u00f1os son agresivos y necesitan ayuda profesional\u201d.<\/p>\n\n\n\n<p>En los \u00faltimos tres a\u00f1os, Chachkhaia tambi\u00e9n ha observado un aumento en el abuso de drogas.<\/p>\n\n\n\n<p>\u201cAntes, chico ol\u00edan pegamento\u201d, dice. \u201cAhora, toman drogas m\u00e1s duras y peligrosas. Los ni\u00f1os necesitan dinero para conseguirlas, por eso roban\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>A menudo, un miembro de la familia obliga a estos ni\u00f1os a mendigar; algunos de estos ni\u00f1os son la \u00fanica fuente de ingresos de su familia.<\/p><\/blockquote><\/figure>\n\n\n\n<p>No hay estudios sobre las causas de estos cambios de conducta en los j\u00f3venes de la calle en Georgia, dice Tamar Sharashidze, directora del programa para ni\u00f1os y j\u00f3venes de Caritas Georgia. En los \u00faltimos a\u00f1os, casi todos sus casos se deb\u00edan a la pobreza.<\/p>\n\n\n\n<p>\u201cAhora tenemos ni\u00f1os cuyos padres no son necesariamente pobres, simplemente no pueden controlar a sus hijos\u201d, dice. \u201cHace m\u00e1s de un a\u00f1o pedimos a los ministerios gubernamentales que formen grupos de trabajo para estudiar esto, pero no tienen ning\u00fan inter\u00e9s\u201d.<\/p>\n\n\n\n<p>En Georgia no existen instituciones de tratamiento para j\u00f3venes en riesgo. El estado ten\u00eda un internado al oeste del pa\u00eds, que Sharashidze describe como \u201chorrible\u201d, pero fue cerrado y no fue reemplazado.<\/p>\n\n\n\n<p>\u201cPor malo que era, al menos era mejor que las calles\u201d.<\/p>\n\n\n\n<p class=\"has-drop-cap\">Rustavi es una antigua ciudad industrial de 140.000 habitantes y hogar de Tbili Sakhli, que tiene un centro de 24 horas de atenci\u00f3n para ni\u00f1os con una capacidad m\u00e1xima para 12. Las empresas locales contribuyen para cubrir el alquiler. Algunos de los adolescentes fueron trasladados del refugio de Tbilisi, incluido Sandro, 17, que est\u00e1 ansioso por practicar el ingl\u00e9s que aprendi\u00f3 viendo videos de YouTube y escuchando m\u00fasica.<\/p>\n\n\n\n<p>\u201cTuve problemas con mi familia y vine aqu\u00ed hace seis a\u00f1os\u201d, dice Sandro, cuyo apellido se omite para proteger su identidad. \u201cLos profesores me ayudaron a aprender y a volver a la escuela, y el psic\u00f3logo me ayuda mucho con mis problemas. Me encanta ayudar a los otros ni\u00f1os aqu\u00ed y me encantar\u00eda hacer trabajo social despu\u00e9s de la universidad\u201d.<\/p>\n\n\n\n<p>Ilona Martinova, 17, una ex beneficiaria, se muestra t\u00edmida al de hablar de su pasado. Recientemente se reuni\u00f3 con su madre biol\u00f3gica y ahora es voluntaria en el centro. \u201cSiento una responsabilidad con los otros chicos\u201d, dice.<\/p>\n\n\n\n<p>Sharashidze, de Caritas Georgia, dice que muchos del personal fueron beneficiarios. Valeri Chidzovi, 24, lleg\u00f3 cuando era un adolescente y ahora es educador de pares en Tbili Sakhli, mientras estudia en la academia culinaria de Tbilisi. A menudo ayuda en la cocina del centro, compartiendo lo que ha aprendido con los j\u00f3venes.<\/p>\n\n\n\n<p>Tbili Sakhli y Emegobre ofrecen visitas de psic\u00f3logos tanto a adultos como a ni\u00f1os, as\u00ed como sesiones sobre abuso, derechos humanos, discriminaci\u00f3n de g\u00e9nero, habilidades dom\u00e9sticas y c\u00f3mo proteger a los ni\u00f1os de la violencia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_079H-1024x819.jpg\" alt=\"\" class=\"wp-image-5179\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_079H-1024x819.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_079H-300x240.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_079H-768x614.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_079H-1600x1280.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_079H-1536x1229.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_079H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">En Emegobre, las mam\u00e1s y los ni\u00f1os juegan juegos para fortalecer el v\u00ednculo entre padres e hijos. (foto: Justyna Mielnikiewicz)<\/figcaption><\/figure>\n\n\n\n<p>Nadia Koldari es una moldava \u00e9tnica que creci\u00f3 cerca de Caritas Nutsubidze en Tbilisi. Conoce a Abuladze, directora de Emegobre, desde joven. Koldari nunca aprendi\u00f3 a leer ni a escribir. Ahora casada y con dos hijos, lleva a sus hijos al centro con el apoyo de su marido y asiste a sesiones para padres en un esfuerzo por romper el patr\u00f3n de vida en la calle.<\/p>\n\n\n\n<p>\u201cNuestros hijos no mendigan\u201d, dice con orgullo. \u201cEstudiar\u00e1n e ir\u00e1n a la universidad\u201d.<\/p>\n\n\n\n<p>La mayor\u00eda de los beneficiarios saben de Caritas de boca a boca o por el trabajo de los equipos m\u00f3viles, formados por un psic\u00f3logo de Caritas, un educador de pares, un chofer y un trabajador social estatal. Visitan a los ni\u00f1os en el metro y en lugares donde es probable que trabajen o se re\u00fanan. El objetivo es generar confianza y que los ni\u00f1os sepan del centro. Despu\u00e9s, el equipo ofrece algunas actividades educativas en las calles.<\/p>\n\n\n\n<p>Tambi\u00e9n se contacta a los j\u00f3venes vulnerables en las comisar\u00edas. Dado que el estado no tiene programas para menores de 14 a\u00f1os, ni derecho a intervenir a menos que los ni\u00f1os est\u00e9n registrados bajo tutela del estado, la polic\u00eda llama a proveedores de atenci\u00f3n privada, como Caritas, cada vez que descubre a ni\u00f1os infringiendo la ley o v\u00edctimas de abuso dom\u00e9stico y no pueden regresarlos a un miembro de la familia.<\/p>\n\n\n\n<p>El equipo m\u00f3vil tiene mayor \u00e9xito cuando los ni\u00f1os son peque\u00f1os. Las intervenciones se vuelven m\u00e1s dif\u00edciles cuanto m\u00e1s tiempo pasa un ni\u00f1o en la calle.<\/p>\n\n\n\n<p class=\"has-drop-cap\">De vuelta en la sala de actividades de Emegobre en Tbilisi, una docena de ni\u00f1os de distintas edades est\u00e1n parados en l\u00ednea recta conteniendo las risitas. Un personal de Caritas le vend\u00f3 los ojos a Mezvrilishvili. Como parte del juego, la madre de tres hijas debe caminar por la fila, tocar la cara de cada ni\u00f1o y adivinar cu\u00e1l es el suyo. Otras tres madres esperan su turno.<\/p>\n\n\n\n<p>\u201cAmo a estos ni\u00f1os\u201d, dice Teona Jujoy, psic\u00f3loga del equipo m\u00f3vil, mientras observa a Mezvrilishvili pasar sus dedos por la cabeza de una ni\u00f1a. \u201cQuiero que tengan una buena vida. Todos los ni\u00f1os tienen ese derecho\u201d.<\/p>\n\n\n<div class=\"cnewa-connections\">\n  <div class=\"cnewa-connections-heading\">\n    <h2>Conexi\u00f3n CNEWA<\/h2>\n  <\/div>\n  <div class=\"cnewa-connections-content\" style=\"background:#6B4D5E;color:#ffffff\">\n    <p style=\"font-weight: 400;\">CNEWA ha estado presente en Georgia por d\u00e9cadas y ha tocado miles de vidas. Hoy, trabaja en estrecha colaboraci\u00f3n con Caritas Georgia para brindar sanaci\u00f3n y esperanza a los olvidados, incluidos los ni\u00f1os de la calle, brind\u00e1ndoles oportunidades educativas, asesoramiento y un lugar al que llamar hogar. Pero, la falta de financiaci\u00f3n gubernamental para proyectos de servicio social significa que Caritas Georgia depende en gran medida de donaciones para continuar este trabajo. CNEWA patrocina estos proyectos, y programas de apoyo para madres solteras, v\u00edctimas de abuso dom\u00e9stico, personas mayores, personas con necesidades especiales y otros grupos vulnerables.<\/p>\n<p style=\"font-weight: 400;\">Para apoyar esta misi\u00f3n, llame al 1-866-322-4441 (Canad\u00e1) o al 1-800-442-6392 (Estados Unidos) o visite <a href=\"https:\/\/cnewa.org\/es\/haga-una-donacion\/\">https:\/\/cnewa.org\/es\/haga-una-donacion\/<\/a>.<\/p>\n  <\/div>\n<\/div>\n\n\n<p><em>Lea este art\u00edculo en nuestro formato de impresi\u00f3n digital <a href=\"https:\/\/issuu.com\/cnewa\/docs\/one-50-2-2024-final-spanish-issuu\/20\">aqu\u00ed<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00f3venes de la calle encuentran apoyo en Caritas Georgia<\/p>\n","protected":false},"author":70079,"featured_media":5175,"template":"","magazine-issues":[1063],"magazine-sections":[143],"class_list":["post-5174","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","magazine-issues-junio-2024","magazine-sections-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un Lugar al que Pertenecer | ONE en Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"CNEWA trabaja en colaboraci\u00f3n con Caritas Georgia para llevar sanaci\u00f3n y esperanza a los abandonados, incluidos los ni\u00f1os de la calle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Lugar al que Pertenecer | ONE en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"CNEWA trabaja en colaboraci\u00f3n con Caritas Georgia para llevar sanaci\u00f3n y esperanza a los abandonados, incluidos los ni\u00f1os de la calle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-07T19:06:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_051H-r1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/\",\"name\":\"Un Lugar al que Pertenecer | ONE en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/mielnikiewicz202403_051H-r1.jpg\",\"datePublished\":\"2024-06-03T17:57:10+00:00\",\"dateModified\":\"2024-06-07T19:06:46+00:00\",\"description\":\"CNEWA trabaja en colaboraci\u00f3n con Caritas Georgia para llevar sanaci\u00f3n y esperanza a los abandonados, incluidos los ni\u00f1os de la calle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/mielnikiewicz202403_051H-r1.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/mielnikiewicz202403_051H-r1.jpg\",\"width\":1800,\"height\":1440,\"caption\":\"La psic\u00f3loga Tatiana Polikarpova, izq., sentada con Ilona Martinova, voluntaria y ex beneficiaria del refugio de Caritas para ni\u00f1os de la calle en Rustavi, Georgia. (foto: Justyna Mielnikiewicz)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/un-lugar-al-que-pertenecer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Magazine\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un Lugar al que Pertenecer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un Lugar al que Pertenecer | ONE en Espa\u00f1ol","description":"CNEWA trabaja en colaboraci\u00f3n con Caritas Georgia para llevar sanaci\u00f3n y esperanza a los abandonados, incluidos los ni\u00f1os de la calle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/","og_locale":"es_ES","og_type":"article","og_title":"Un Lugar al que Pertenecer | ONE en Espa\u00f1ol","og_description":"CNEWA trabaja en colaboraci\u00f3n con Caritas Georgia para llevar sanaci\u00f3n y esperanza a los abandonados, incluidos los ni\u00f1os de la calle.","og_url":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_modified_time":"2024-06-07T19:06:46+00:00","og_image":[{"width":1800,"height":1440,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_051H-r1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/","url":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/","name":"Un Lugar al que Pertenecer | ONE en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_051H-r1.jpg","datePublished":"2024-06-03T17:57:10+00:00","dateModified":"2024-06-07T19:06:46+00:00","description":"CNEWA trabaja en colaboraci\u00f3n con Caritas Georgia para llevar sanaci\u00f3n y esperanza a los abandonados, incluidos los ni\u00f1os de la calle.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_051H-r1.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2024\/06\/mielnikiewicz202403_051H-r1.jpg","width":1800,"height":1440,"caption":"La psic\u00f3loga Tatiana Polikarpova, izq., sentada con Ilona Martinova, voluntaria y ex beneficiaria del refugio de Caritas para ni\u00f1os de la calle en Rustavi, Georgia. (foto: Justyna Mielnikiewicz)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/revista\/un-lugar-al-que-pertenecer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"One Magazine","item":"https:\/\/cnewa.org\/es\/revista\/"},{"@type":"ListItem","position":3,"name":"Un Lugar al que Pertenecer"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/5174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/magazine"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70079"}],"version-history":[{"count":0,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/5174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/5175"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=5174"}],"wp:term":[{"taxonomy":"magazine-issues","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-issues?post=5174"},{"taxonomy":"magazine-sections","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-sections?post=5174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}