{"id":7747,"date":"2026-01-14T10:29:44","date_gmt":"2026-01-14T15:29:44","guid":{"rendered":"https:\/\/cnewa.org\/es\/?post_type=magazine&#038;p=7747"},"modified":"2026-01-14T10:29:44","modified_gmt":"2026-01-14T15:29:44","slug":"los-ultimos-valles-abiertos","status":"publish","type":"magazine","link":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/","title":{"rendered":"Los \u00daltimos Valles Abiertos"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Riham Jahshan puede ver el asentamiento israel\u00ed de Gilo desde la ventana de su sala. Ella y su familia viven en una casa ordenada y cuidadosamente cuidada en Beit Jala \u2014 a solo una milla de la Ciudad Vieja de Bel\u00e9n, durante mucho tiempo venerada como la cuna del cristianismo.<\/p>\n\n\n\n<p>Sin embargo, la realidad en Bel\u00e9n y sus comunidades vecinas en el sur de Cisjordania, donde los palestinos viven bajo ocupaci\u00f3n militar israel\u00ed, se parece muy poco a las im\u00e1genes postales de Tierra Santa.&nbsp;<\/p>\n\n\n\n<p>Est\u00e1 previsto que Gilo, que alberga a m\u00e1s de 30.000 personas, se expanda de nuevo con una construcci\u00f3n de cerca de 2.000 nuevas viviendas en 43 acres. Para Jahshan, una palestina griega ortodoxa, lo que ve a trav\u00e9s de su ventana es un recordatorio diario de que el mundo que rodea a su familia se va cerrando a su alrededor.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_086H-1024x683.jpg\" alt=\"Dos hombres y una mujer est\u00e1n sentados en un muro bajo de contenci\u00f3n mientras una joven sirve una taza de t\u00e9 para la mujer.\" class=\"wp-image-7746\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_086H-1024x683.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_086H-300x200.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_086H-768x512.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_086H-1536x1024.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_086H-1600x1067.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_086H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Carlos Barham, segundo desde la derecha, toma t\u00e9 con sus familiares en su casa de al-Makhrour, Cisjordania. \u00c9l cuida diariamente las tierras ancestrales de su familia. (foto: Samar Hazboun)<\/figcaption><\/figure>\n\n\n\n<p>Al menos 23 asentamientos israel\u00edes, con m\u00e1s de 180.000 habitantes, ocupan ahora la gobernaci\u00f3n de Bel\u00e9n. Los asentamientos se consideran ilegales seg\u00fan el derecho internacional.<\/p>\n\n\n\n<p>\u201cNo podemos movernos mucho\u201d, dice. \u201cNo podemos salir de Beit Jala ni de la zona de Bel\u00e9n para nada\u201d.<\/p>\n\n\n\n<p>Su \u201cradio familiar\u201d se ha reducido a solo unos pocos vecindarios desde que comenz\u00f3 la guerra de Israel contra Gaza en octubre 2023. Antes de la guerra, era m\u00e1s f\u00e1cil conducir entre ciudades, dice.<\/p>\n\n\n\n<p>Jerusal\u00e9n est\u00e1 a solo seis millas en auto, pero es pr\u00e1cticamente inaccesible tras el muro de separaci\u00f3n y el r\u00e9gimen de permisos israel\u00ed que impide la entrada a la mayor\u00eda de los palestinos. En el a\u00f1o posterior a la invasi\u00f3n de Ham\u00e1s a Israel el 7 de octubre, 2023, muchos permisos existentes para palestinos fueron revocados o suspendidos, y el 44 por ciento de las 46.163 solicitudes de permisos m\u00e9dicos fueron denegadas o quedaron pendientes, una medida que ha sido descrita como un castigo colectivo por grupos de derechos humanos.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cNo podemos movernos mucho. No podemos salir de Beit Jala ni de la zona de Bel\u00e9n para nada\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p>En cambio, los colonizadores israel\u00edes se mueven libremente por carreteras de circunvalaci\u00f3n, t\u00faneles y autopistas segregadas que conectan sus hogares con Jerusal\u00e9n y Tel Aviv. El plan de anexi\u00f3n recientemente aprobado por Israel, denominado E1, conectar\u00e1 Ma&#8217;ale Adumim \u2014 actualmente el tercer asentamiento israel\u00ed m\u00e1s grande \u2014 al norte de Bel\u00e9n, con Jerusal\u00e9n, facilitando el acceso de los colonos a Cisjordania y dividiendo las partes norte y sur del territorio palestino.&nbsp;<\/p>\n\n\n\n<p>\u201cEl plan E1 mata incluso el peque\u00f1o resto de esperanza que queda\u201d, dice Jahshan.&nbsp;<\/p>\n\n\n\n<p>Cada proyecto cambia las rutas de los colegios, pospone las visitas y convierte cada viaje en un c\u00e1lculo. Sus d\u00edas siguen un ritmo similar: incursiones militares al amanecer, cierres repentinos, incursiones de colonizadores y gases lacrim\u00f3genos que llegan desde el campo de refugiados de Dheisheh, donde ella asesora a ni\u00f1os cuyos padres han sido encarcelados o asesinados por el ej\u00e9rcito israel\u00ed. El campamento, establecido en Bel\u00e9n en 1949 tras la primera guerra \u00e1rabe-israel\u00ed, fue construido para 3.000 refugiados palestinos expulsados de sus hogares en lo que hoy es el Estado de Israel; actualmente alberga a m\u00e1s de 19.000 personas.<\/p>\n\n\n\n<p>La Oficina de Coordinaci\u00f3n de Asuntos Humanitarios de la ONU (UNOCHA) ha registrado casi 7.500 redadas militares en toda Cisjordania solo en 2025, un aumento del 37 por ciento desde 2024, y las restricciones <a href=\"https:\/\/cnewa.org\/es\/revista\/paisaje-de-perdidas\/\">han aumentado en el \u00faltimo a\u00f1o<\/a>.<\/p>\n\n\n\n<p>Fuera de la ciudad, los \u00faltimos valles abiertos accesibles para los palestinos en Bel\u00e9n son Cremisan y <a href=\"https:\/\/cnewa.org\/es\/revista\/enraizados-en-la-tierra-llamada-santa\/\">al-Makhrour<\/a>, donde muchos terratenientes son cristianos.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1-683x1024.jpg\" alt=\"Una mujer poda un arbusto.\" class=\"wp-image-7745\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1-683x1024.jpg 683w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1-200x300.jpg 200w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1-768x1152.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1-1024x1536.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1-1366x2048.jpg 1366w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1-1600x2400.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_076H-scaled-1.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">Riham Jahshan recoge recortes de \u00e1rboles de las tierras ancestrales de su familia en al-Makrour, Cisjordania, que utilizar\u00e1 en su l\u00ednea de productos naturales. (foto: Samar Hazboun)<\/figcaption><\/figure>\n\n\n\n<p class=\"has-drop-cap\">En al-Makhrour, el t\u00edo de la se\u00f1ora Jahshan, Carlos Barham, vive en una casa tradicional de piedra en casi 10 acres de tierra ancestral. Cada d\u00eda, con tijeras de podar en el bolsillo trasero, cuida amplias terrazas \u2014una tarea que hered\u00f3 de su padre\u2014 con docenas de olivos y albaricoqueros, vides e hileras de salvia, tomillo y menta.&nbsp;<\/p>\n\n\n\n<p>\u201cNac\u00ed en 1947\u201d, dice. \u201cHe ido y venido de esta tierra durante 74 a\u00f1os. En aquel entonces, todo estaba lleno de vida. Ahora est\u00e1 desierto. Esta tierra ya no sirve al agricultor; sirve a los intereses de Israel\u201d.<\/p>\n\n\n\n<p>Barham explica c\u00f3mo, seg\u00fan la pol\u00edtica israel\u00ed, las tierras que no se cultivan pueden ser confiscadas y declaradas tierras estatales. Las Naciones Unidas informan que m\u00e1s del 99 por ciento de las tierras estatales en el \u00c1rea C \u2014la parte de Cisjordania puesta bajo control israel\u00ed bajo los Acuerdos de Oslo de 1995\u2014 han sido integradas en jurisdicciones de asentamiento, no en ciudades palestinas.<\/p>\n\n\n\n<p>El miedo a la confiscaci\u00f3n y a la violencia de los colonos est\u00e1 constantemente presente entre los due\u00f1os de tierras palestinos.&nbsp;<\/p>\n\n\n\n<p>\u201cCada d\u00eda planto, riego los \u00e1rboles, riego la salvia, el tomillo. Todo esto, para que la tierra permanezca para nosotros y para los dem\u00e1s\u201d, dice Barham. \u201cA\u00f1os de trabajo, y pueden llev\u00e1rselo en un d\u00eda. Y una vez toman la tierra, nunca la devuelven\u201d.<\/p>\n\n\n\n<p>Los colonizadores quemaron las tierras de una familia vecina \u2014 una t\u00e1ctica destinada a infundir miedo en los due\u00f1os de tierras palestinos y expulsarlos \u2014 pero la familia mantuvo la posesi\u00f3n de sus tierras.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cSi el precio de la seguridad se va, quiz\u00e1 me vaya. Y mi alma se quedar\u00e1 aqu\u00ed\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p>\u201cSi el fuego se hubiera extendido, todos nuestros olivos se habr\u00edan quemado\u201d, dice Barham, se\u00f1alando los aproximadamente 45 \u00e1rboles de su huerta.&nbsp;<\/p>\n\n\n\n<p>\u201cQuien viola tu tierra viola tu honor\u201d, a\u00f1ade. \u201cProtegemos la tierra, generaci\u00f3n tras generaci\u00f3n\u201d.<\/p>\n\n\n\n<p>Cuando Jahshan, sus hijos y primos la visitan, \u00e9l dice: \u201cse siente como una boda, la alegr\u00eda llena la tierra\u201d.<\/p>\n\n\n\n<p>Jahshan recuerda cuando se alojaba en la casa de piedra de su t\u00edo de ni\u00f1a durante las temporadas de cosecha de albaricoques y aceitunos, corriendo descalza entre el patio y los \u00e1rboles.&nbsp;<\/p>\n\n\n\n<p>\u201cTodos mis mejores recuerdos de infancia est\u00e1n en esta tierra\u201d, dice. \u201cSu aroma lo es todo para m\u00ed. Cuando llego, siento que mi esp\u00edritu regresa\u201d.<\/p>\n\n\n\n<p>Incluso empez\u00f3 una peque\u00f1a l\u00ednea de productos para el cuidado corporal, llamada \u201cArdi\u201d, que en \u00e1rabe significa \u201cMi Tierra\u201d, con las hierbas cultivadas all\u00ed. Pero el acceso a la tierra ya no est\u00e1 garantizado, afirma.&nbsp;<\/p>\n\n\n\n<p>\u201cEntre maniobras legales israel\u00edes, \u00f3rdenes militares, puestos de colonos y repetidas incursiones, nuestro acceso se est\u00e1 reduciendo\u201d, dice Jahshan.<\/p>\n\n\n\n<p>Una tarde reciente, ella y sus hijos conduc\u00edan hacia el bosque cuando un jeep militar bloque\u00f3 la carretera. Cuando ella le pregunt\u00f3 al soldado por qu\u00e9 le negaban el paso, \u00e9l le apunt\u00f3 con su rifle.&nbsp;<\/p>\n\n\n\n<p>\u201cDesde entonces, vamos menos\u201d, dice suavemente, con la voz quebrada.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cA\u00f1os de trabajo, y pueden llev\u00e1rselo en un d\u00eda. Y una vez toman la tierra, nunca la devuelven\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-drop-cap\">Grupos de derechos humanos han reportado una mayor incidencia de violencia de colonizadores en los \u00faltimos meses. En octubre de 2025, UNOCHA registr\u00f3 el mayor n\u00famero mensual de ataques de colonizadores contra terratenientes palestinos desde 2006 \u2014 264, una media de ocho incidentes diarios \u2014 que resultaron en v\u00edctimas o da\u00f1os materiales.<\/p>\n\n\n\n<p>\u201cIntentamos mantenernos firmes\u201d, dice Jahshan, \u201cpero \u00bfhasta cu\u00e1ndo? Estamos bajo presi\u00f3n por todas partes\u201d.&nbsp;<\/p>\n\n\n\n<p>Durante la guerra \u00e1rabe-israel\u00ed de 1948, la familia de su padre fue desplazada por la fuerza de Haifa y Lydd, como parte de la Nakba \u2014 la cat\u00e1strofe, tal como describen los palestinos al desplazamiento de m\u00e1s de 700.000 personas durante la guerra de independencia de Israel en 1948. Es una historia familiar que influye profundamente en c\u00f3mo Jahshan piensa sobre su futuro en Cisjordania.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_064H-1024x683.jpg\" alt=\"Un hombre mayor sonr\u00ede mientras observa a una mujer jugando con su hijo en una mesa.\" class=\"wp-image-7743\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_064H-1024x683.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_064H-300x200.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_064H-768x512.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_064H-1536x1024.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_064H-1600x1067.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_064H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Riham Jahshan y su hijo visitan a su t\u00edo, Carlos Barham, en la antigua casa de piedra tradicional de la familia en al-Makhrour, Cisjordania. (foto: Samar Hazboun)<\/figcaption><\/figure>\n\n\n\n<p>\u201cNo quiero irme\u201d, dice. \u201cSi el precio de la seguridad se va, quiz\u00e1 me vaya. Y mi alma se quedar\u00e1 aqu\u00ed\u201d.<\/p>\n\n\n\n<p>Como ocurre con muchos palestinos que debaten si deben marcharse, las condiciones que necesita para quedarse son sencillas: una carretera sin verjas, una caminata sin permisos militares, un camino despejado hasta la vieja casa de piedra donde sus hijos puedan dormir bajo los albaricoques, como ella hizo.<\/p>\n\n\n\n<p>\u201cNo es pedir mucho\u201d, dice. \u201cEso es una vida normal\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Familias palestinas cuidan sus tierras ancestrales para evitar la confiscaci\u00f3n<\/p>\n","protected":false},"author":70019,"featured_media":7742,"template":"","magazine-issues":[1120],"magazine-sections":[1121],"class_list":["post-7747","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","magazine-issues-diciembre-2025","magazine-sections-web-exclusivo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Los \u00daltimos Valles Abiertos | ONE en Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"El temor a la confiscaci\u00f3n preocupa a los due\u00f1os de tierra palestinos en Cisjordania, desde la aprobaci\u00f3n de planes de expansi\u00f3n de asentamientos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los \u00daltimos Valles Abiertos | ONE en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"El temor a la confiscaci\u00f3n preocupa a los due\u00f1os de tierra palestinos en Cisjordania, desde la aprobaci\u00f3n de planes de expansi\u00f3n de asentamientos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_058H.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/\",\"name\":\"Los \u00daltimos Valles Abiertos | ONE en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/01\\\/hazboun202510_058H.jpg\",\"datePublished\":\"2026-01-14T15:29:44+00:00\",\"description\":\"El temor a la confiscaci\u00f3n preocupa a los due\u00f1os de tierra palestinos en Cisjordania, desde la aprobaci\u00f3n de planes de expansi\u00f3n de asentamientos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/01\\\/hazboun202510_058H.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/01\\\/hazboun202510_058H.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"La cristiana palestina Riham Jahshan mira hacia las tierras ancestrales de su familia en el valle de Al-Makhrour en Cisjordania. (foto: Samar Hazboun)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/los-ultimos-valles-abiertos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Magazine\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Los \u00daltimos Valles Abiertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Los \u00daltimos Valles Abiertos | ONE en Espa\u00f1ol","description":"El temor a la confiscaci\u00f3n preocupa a los due\u00f1os de tierra palestinos en Cisjordania, desde la aprobaci\u00f3n de planes de expansi\u00f3n de asentamientos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/","og_locale":"es_ES","og_type":"article","og_title":"Los \u00daltimos Valles Abiertos | ONE en Espa\u00f1ol","og_description":"El temor a la confiscaci\u00f3n preocupa a los due\u00f1os de tierra palestinos en Cisjordania, desde la aprobaci\u00f3n de planes de expansi\u00f3n de asentamientos.","og_url":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","og_image":[{"width":1800,"height":1200,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_058H.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/","url":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/","name":"Los \u00daltimos Valles Abiertos | ONE en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_058H.jpg","datePublished":"2026-01-14T15:29:44+00:00","description":"El temor a la confiscaci\u00f3n preocupa a los due\u00f1os de tierra palestinos en Cisjordania, desde la aprobaci\u00f3n de planes de expansi\u00f3n de asentamientos.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_058H.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/01\/hazboun202510_058H.jpg","width":1800,"height":1200,"caption":"La cristiana palestina Riham Jahshan mira hacia las tierras ancestrales de su familia en el valle de Al-Makhrour en Cisjordania. (foto: Samar Hazboun)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/revista\/los-ultimos-valles-abiertos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"One Magazine","item":"https:\/\/cnewa.org\/es\/revista\/"},{"@type":"ListItem","position":3,"name":"Los \u00daltimos Valles Abiertos"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/7747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/magazine"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"version-history":[{"count":1,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/7747\/revisions"}],"predecessor-version":[{"id":7748,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/7747\/revisions\/7748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/7742"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=7747"}],"wp:term":[{"taxonomy":"magazine-issues","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-issues?post=7747"},{"taxonomy":"magazine-sections","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-sections?post=7747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}