{"id":7934,"date":"2026-03-31T09:00:45","date_gmt":"2026-03-31T13:00:45","guid":{"rendered":"https:\/\/cnewa.org\/es\/?post_type=magazine&#038;p=7934"},"modified":"2026-04-01T08:46:56","modified_gmt":"2026-04-01T12:46:56","slug":"la-iglesia-como-hospital-de-campana","status":"publish","type":"magazine","link":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/","title":{"rendered":"La Iglesia como Hospital de Campa\u00f1a"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Vipin Valiyannukaran, nacido con discapacidades intelectuales y del desarrollo, ha necesitado cuidados las 24 horas del d\u00eda durante toda su vida. Su abuela fue su principal cuidadora, mientras que su madre, Mary, trabajaba como cocinera en un convento. Cuando su abuela falleci\u00f3 hace cuatro a\u00f1os, Mary se convirti\u00f3 en la \u00fanica cuidadora de Vipin. A pesar de las dificultades, Mary persever\u00f3 hasta que le diagnosticaron p\u00e1rkinson y depresi\u00f3n hace dos a\u00f1os.<\/p>\n\n\n\n<p>La hija de Mary los invit\u00f3 a vivir con ella, su esposo, sus cuatro hijos y sus suegros, pero la situaci\u00f3n empeor\u00f3 r\u00e1pidamente y las discusiones eran casi diarias. Un familiar sugiri\u00f3 entonces que Vipin, 37, y Mary, 64, vivieran en el Instituto Damien.<\/p>\n\n\n\n<p>El Instituto Damien est\u00e1 situado en las colinas de Mulayam, en el distrito de Thrissur, <a href=\"https:\/\/cnewa.org\/es\/revista\/ultimos-pero-no-menos-importantes\/\">Kerala<\/a>, al sur de la India. Sus 74 hect\u00e1reas est\u00e1n plantadas con pi\u00f1as, pl\u00e1tanos y cocoteros, y en las zonas bajas se cultiva arroz.<\/p>\n\n\n\n<p>El instituto, fundado en 1953, es un apostolado de la arquieparqu\u00eda cat\u00f3lica sirio-malabar de Trichur y lleva el nombre de San Dami\u00e1n de Veuster, un sacerdote belga que atendi\u00f3 a personas con la enfermedad de Hansen (com\u00fanmente conocida como lepra) desterradas a la isla hawaiana de Molokai. Finalmente, contrajo la enfermedad y falleci\u00f3 a los 49 a\u00f1os en 1889.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La Iglesia como Hospital de Campa\u00f1a\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/NAo3LDR6nV8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>La hermana Lissy Valloppally dirige el Instituto Dami\u00e1n. Antes de llegar hace tres a\u00f1os, trabaj\u00f3 en un hospital para leprosos en Hyderabad, India.<\/p>\n\n\n\n<p>\u201cTenemos 42 pacientes aqu\u00ed en total\u201d, dice. \u201cLa mayor\u00eda padece problemas de salud mental, como esquizofrenia, man\u00eda, etc.<\/p>\n\n\n\n<p>\u201cTambi\u00e9n hay cuatro pacientes de lepra que llevan a\u00f1os sin s\u00edntomas, pero no tienen ad\u00f3nde ir, as\u00ed que se quedan aqu\u00ed. Tambi\u00e9n hay algunos pacientes que acuden a consulta externa.\u201d<\/p>\n\n\n\n<p>Pathu Muthu, de 92 a\u00f1os, tiene deformidad en las manos y los pies debido a la lepra.<\/p>\n\n\n\n<p>\u201cLleva aqu\u00ed 38 a\u00f1os\u201d, dice la Hermana Lissy. \u201cLe han dado el alta, pero todav\u00eda necesita que le curen las manos y los pies dos veces por semana o le huelen mal\u201d. Un m\u00e9dico visita el instituto dos veces al mes y un psiquiatra lo hace mensualmente. Los residentes pueden recibir fisioterapia semanalmente y an\u00e1lisis de sangre mensualmente. El personal, compuesto por 10 personas, incluye enfermeras, cuidadores y administradores.<\/p>\n\n\n\n<p>Las mejoras en la salud p\u00fablica a nivel mundial han pr\u00e1cticamente erradicado la enfermedad \u2014alrededor del 95 % de la poblaci\u00f3n mundial no es susceptible\u2014 y no es una enfermedad contagiosa que se transmita por v\u00eda sexual o embarazo.<\/p>\n\n\n\n<p>India declar\u00f3 la erradicaci\u00f3n de la lepra en 2005, en el marco de su Programa Nacional de Erradicaci\u00f3n de la Lepra. Las cifras gubernamentales muestran que la tasa de prevalencia de la lepra en India se redujo de 57,2 por cada 10&nbsp;000 personas en 1981 a tan solo 0,57 en 2025. Sin embargo, cada a\u00f1o se reportan entre 120&nbsp;000 y 130&nbsp;000 nuevos casos de lepra en India, lo que representa casi el 60 % de los nuevos casos a nivel mundial.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cCuando se combina el amor con el cuidado, se les da un sentido de pertenencia\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p>El Instituto Damien ten\u00eda 350 pacientes con lepra. Alcanz\u00f3 su m\u00e1ximo auge en 1962. Cuando el gobierno declar\u00f3 la erradicaci\u00f3n de la lepra, el instituto cambi\u00f3 su misi\u00f3n para atender principalmente a personas con problemas de salud mental.<\/p>\n\n\n\n<p>\u201cDespu\u00e9s de la COVID-19 en 2020, tambi\u00e9n acogimos a algunos pacientes que no ten\u00edan ad\u00f3nde ir\u201d, comenta el reverendo Simson Chiramel, director del instituto.<\/p>\n\n\n\n<p>En 2020, justo antes de la llegada de la COVID-19, Jaison Johnson, de 29 a\u00f1os, se gradu\u00f3 en econom\u00eda y trabajaba en una farmacia mientras controlaba su esquizofrenia.<\/p>\n\n\n\n<p>Sin embargo, durante la pandemia, el Sr. Johnson, su madre y su hermano, quienes tambi\u00e9n padecen problemas de salud mental, deambulaban por las calles d\u00eda y noche. Un familiar los llev\u00f3 al Hospital Jubilee Mission, tambi\u00e9n parte de la red de atenci\u00f3n m\u00e9dica de la Arquieparqu\u00eda de Trichur, pero se negaron a tomar la medicaci\u00f3n recetada. Cuando la salud mental del Sr. Johnson se deterior\u00f3 a\u00fan m\u00e1s, ingres\u00f3 en el hospital durante dos meses. Su m\u00e9dico lo remiti\u00f3 al Instituto Damien, donde reside desde hace dos a\u00f1os. <\/p>\n\n\n\n<p>\u201cTrabajamos con los residentes para que sean m\u00e1s independientes\u201d, dice el padre Chiramel. \u201cCuando se combina el amor con el cuidado, se les da un sentido de pertenencia\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"655\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_048H-1024x655.jpg\" alt=\"Una mujer sentada en una mesa escolar con tres ni\u00f1os con discapacidades.\" class=\"wp-image-7906\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_048H-1024x655.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_048H-300x192.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_048H-768x491.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_048H-1536x982.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_048H-1600x1023.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_048H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La profesora Brinda Ajith se re\u00fane con ni\u00f1os con necesidades especiales en la Sociedad de Servicios Sociales de Malankara. (foto: Sajeendran V.S.)<\/figcaption><\/figure>\n\n\n\n<p class=\"has-drop-cap\">Ayyappan Kutty, de 80 a\u00f1os, se encuentra en buena forma para su edad, una ventaja de haber pasado la vida trepando cocoteros y recogiendo la fruta. Vive en Karalam, donde cuida de su hermana Shantha, de 54 a\u00f1os, a quien le diagnosticaron c\u00e1ncer de mama metast\u00e1sico. Sus otras hermanas, Kochumol y Valleyamma, tienen necesidades de salud mental.<\/p>\n\n\n\n<p>Los cuatro hermanos reciben el apoyo del Programa de Cuidados Paliativos Hrudaya, una iniciativa de acci\u00f3n social de la Eparqu\u00eda Cat\u00f3lica Sirio-Malabar de Irinjalakuda. La eparqu\u00eda cuenta con 260.000 cat\u00f3licos sirio-malabares y unas 140 parroquias. El personal del programa, compuesto por 30 personas, atiende a 1.500 familias.<\/p>\n\n\n\n<p>\u201cOfrecemos atenci\u00f3n integral gratuita a personas que est\u00e1n postradas en cama por afecciones como c\u00e1ncer, accidentes cerebrovasculares, lesiones de m\u00e9dula espinal y otras enfermedades complejas de dif\u00edcil recuperaci\u00f3n\u201d, afirma el director, el reverendo Shaju Chirayath. \u201cProporcionamos medicamentos totalmente gratis a las personas que reciben cuidados paliativos\u201d, afirma. \u201cNos aseguramos de que quienes m\u00e1s lo necesitan tengan acceso a medicamentos esenciales que pueden ayudar a mejorar su calidad de vida\u201d.<\/p>\n\n\n\n<p>En la aldea de Vellani, Jewel Mary Jijoy, de 6 a\u00f1os, padece una enfermedad poco com\u00fan que puede causar convulsiones y defectos en las extremidades.<\/p>\n\n\n\n<p>La madre de Jewel Mary, Dhanya Jijoy, es su principal cuidadora. \u201cEs dif\u00edcil cuidarla porque necesita atenci\u00f3n las 24 horas\u201d, explica la Sra. Jijoy. Su hermano, de 14 a\u00f1os, y su hermana, de 9, ayudan en todo lo que pueden, a\u00f1ade.<\/p>\n\n\n\n<p>El padre de Jewel Mary conduce un taxi en otra ciudad y regresa a casa cada fin de semana. Sus ingresos no son suficientes para mantener a la familia ni para cubrir las necesidades de salud espec\u00edficas de Jewel Mary.<\/p>\n\n\n\n<p>\u201cUn coordinador de Hrudaya nos cont\u00f3 sobre la condici\u00f3n de esta familia\u201d, dice el padre Chirayath. Vinimos y vimos c\u00f3mo pod\u00edamos ayudarlos. Hrudaya paga los medicamentos de Jewel Mary, que cuestan casi 250 d\u00f3lares al mes.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"1024\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_033H-741x1024.jpg\" alt=\"Un sacerdote toma las manos de un hombre en una cama de hospital.\" class=\"wp-image-7908\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_033H-741x1024.jpg 741w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_033H-217x300.jpg 217w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_033H-768x1062.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_033H-1111x1536.jpg 1111w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_033H.jpg 1303w\" sizes=\"auto, (max-width: 741px) 100vw, 741px\" \/><figcaption class=\"wp-element-caption\">El padre Shaju Chirayath visita a Joy Thaliyan, paciente del Programa de Cuidados Paliativos Hrudaya. (foto: Sajeendran V.S.)<\/figcaption><\/figure>\n\n\n\n<p>\u201cSi no fuera por Hrudaya, no s\u00e9 c\u00f3mo nos habr\u00edamos arreglado\u201d, dice la Sra. Jijoy, quien asiste a la iglesia a diario. \u201cJes\u00fas obra de maneras misteriosas\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cNos aseguramos de que quienes m\u00e1s lo necesitan tengan acceso a medicamentos esenciales que pueden ayudar a mejorar su calidad de vida\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Joy Thaliyan, de 56 a\u00f1os, de Thumbakode, se ganaba la vida para su familia como le\u00f1ador hasta que una ca\u00edda de un \u00e1rbol de caucho hace siete a\u00f1os lo dej\u00f3 paralizado.<\/p>\n\n\n\n<p>\u201cLa situaci\u00f3n es dif\u00edcil\u201d, dice su esposa, Annie Joy. \u201cPero Hrudaya es muy servicial. El padre Shaju nos visita con regularidad, y eso nos da mucho apoyo y consuelo\u201d.<\/p>\n\n\n\n<p>El padre Chirayath dice que Hrudaya tambi\u00e9n ofrece visitas m\u00e9dicas y de enfermer\u00eda, y ayuda a las personas con necesidades relacionadas con la salud, como la entrega de pa\u00f1ales. \u201cEs importante que nos mantengamos conectados con las personas y no las dejemos socialmente aisladas\u201d, dice. \u201cEl apoyo emocional, espiritual y religioso es muy importante para los seres humanos\u201d. El Centro de Hospicio Hrudaya ayuda a quienes requieren cuidados paliativos avanzados.<\/p>\n\n\n\n<p>\u201cQueremos que las personas tengan dignidad tanto en la vida como en la muerte. Por eso son necesarios programas como Hrudaya\u201d, afirma el Padre Chirayath.<\/p>\n\n\n\n<p>Desde la d\u00e9cada de 1970, Kerala se ha convertido en uno de los estados m\u00e1s ricos y desarrollados de la India. La esperanza de vida es de 73 a\u00f1os para los hombres y de 79 para las mujeres, impulsada en gran medida por centros de salud profesionales, un alto nivel de alfabetizaci\u00f3n y un saneamiento mejorado.<\/p>\n\n\n\n<p>M\u00e1s de 5 millones de keralanos trabajan en el extranjero, principalmente en los estados del Golfo P\u00e9rsico, lo que contribuye significativamente a la riqueza del estado. La econom\u00eda se basa principalmente en el sector servicios, y depende en gran medida del turismo, la atenci\u00f3n m\u00e9dica, la tecnolog\u00eda de la informaci\u00f3n y el comercio, m\u00e1s que de la industria manufacturera.<\/p>\n\n\n\n<p>El ingreso per c\u00e1pita promedio en Kerala es de $1,950, seg\u00fan las estad\u00edsticas gubernamentales de 2024-2025. Sin embargo, a pesar del crecimiento socioecon\u00f3mico y tecnol\u00f3gico, el estado contin\u00faa dependiendo de sus iglesias para aliviar la pobreza: m\u00e1s de una cuarta parte de la poblaci\u00f3n de Kerala es cristiana, y las redes de escuelas, atenci\u00f3n m\u00e9dica y programas de servicios sociales de las iglesias impactan tanto a cristianos como a no cristianos.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cSi no fuera por Hrudaya, no s\u00e9 c\u00f3mo lo habr\u00edamos logrado\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Adem\u00e1s de atender a las personas marginadas, las organizaciones dirigidas por la iglesia brindan capacitaci\u00f3n laboral y una financiaci\u00f3n significativa para el desarrollo comunitario. Tambi\u00e9n gestionan una extensa red de instituciones educativas y hospitales, especialmente en zonas remotas o desatendidas, comedores sociales y programas de asistencia social para familias que enfrentan dificultades o p\u00e9rdidas econ\u00f3micas.<\/p>\n\n\n\n<p>Adem\u00e1s, la iglesia es un apoyo importante para el gobierno en la intervenci\u00f3n en situaciones de crisis, como desastres naturales, inundaciones y deslizamientos de tierra, cubriendo las carencias de la ayuda gubernamental con apoyo inmediato, que incluye alimentos, medicamentos, agua potable y campamentos improvisados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"610\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_003H-1024x610.jpg\" alt=\"Una hermana religiosa abraza a una mujer sentada en una cama de hospital.\" class=\"wp-image-7910\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_003H-1024x610.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_003H-300x179.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_003H-768x458.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_003H-1536x916.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_003H-1600x954.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_003H.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La hermana Lissy Valloppally visita a Juvan en el Instituto Damien. (foto: Sajeendran V.S.)<\/figcaption><\/figure>\n\n\n\n<p>Dhiya R.V. juega con sus amigos en el centro comunitario de la Sociedad de Servicios Sociales Malankara (MSSS) en Thiruvananthapuram, capital de Kerala. MSSS es la rama de ministerio social de la Arquieparqu\u00eda Cat\u00f3lica Sirio-Malankara de Trivandrum.<\/p>\n\n\n\n<p class=\"has-drop-cap\">Dhiya, de 9 a\u00f1os, naci\u00f3 con el s\u00edndrome del Triple X, una afecci\u00f3n gen\u00e9tica aleatoria que se presenta en aproximadamente 1 de cada 1000 mujeres que nacen con tres cromosomas X en lugar de dos. El s\u00edndrome suele ser leve y muchos casos no se diagnostican. Sin embargo, puede causar retrasos en el desarrollo, dificultades de aprendizaje y problemas del habla, la audici\u00f3n y el lenguaje.<\/p>\n\n\n\n<p>La madre de Dhiya se fue con otro hombre tras el diagn\u00f3stico, por lo que su abuela paterna la ha criado.<\/p>\n\n\n\n<p>Dhiya tiene una discapacidad auditiva grave, una discapacidad de aprendizaje y presenta hiperactividad.<\/p>\n\n\n\n<p>\u201cPero venir aqu\u00ed la ha ayudado\u201d, dice el reverendo Varghese Kizahakkekara, director de M.S.S.S. \u201cPuede jugar y relacionarse con otros ni\u00f1os como ella\u201d.<\/p>\n\n\n\n<p>Estos ni\u00f1os forman parte del programa Sparsh de la organizaci\u00f3n. \u201cLos apoyamos mediante educaci\u00f3n, asesoramiento, terapia y clases de comunicaci\u00f3n\u201d, dice el padre Kizahakkekara.<\/p>\n\n\n\n<p>Los 15 empleados de Sparsh atienden a 76 ni\u00f1os. Sus maestros tambi\u00e9n trabajan en escuelas p\u00fablicas que se han asociado con M.S.S.S. para brindar apoyo educativo a ni\u00f1os con necesidades especiales.<\/p>\n\n\n\n<p>Sparsh ha estado implementando un programa de almuerzos, de lunes a s\u00e1bado, en el complejo de M.S.S.S. para m\u00e1s de 100 personas desde 2020. Entre los beneficiarios se encuentran personas de todas las edades, estudiantes y trabajadores.<\/p>\n\n\n\n<p>\u201cCualquiera puede venir a comer aqu\u00ed\u201d, dice el padre Kizahakkekara. \u201cLa comida es saludable y, al considerar el men\u00fa, tenemos en cuenta que aporta todo: prote\u00ednas, carbohidratos, vitaminas y minerales\u201d.<\/p>\n\n\n\n<p>M.S.S.S. recibi\u00f3 estatus consultivo especial de las Naciones Unidas en 2016, lo que identifica a la organizaci\u00f3n eclesi\u00e1stica como una entidad reconocida por su recepci\u00f3n de subvenciones extranjeras.<\/p>\n\n\n\n<p>\u201cHemos estado sirviendo a los sectores pobres, necesitados, marginados y no organizados de la poblaci\u00f3n, independientemente de su casta, religi\u00f3n o g\u00e9nero\u201d, dice el padre Kizahakkekara, se\u00f1alando que el ministerio sirve a todo el subcontinente indio.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u201cJes\u00fas obra de maneras misteriosas\u201d.<\/p><\/blockquote><\/figure>\n\n\n\n<p>Entre otros grupos marginados de Kerala, M.S.S.S. ayuda a viudas, a trav\u00e9s del programa Sneha Suraksha, as\u00ed como a ni\u00f1os dalit. Sneha Suraksha, que depende principalmente de donaciones de feligreses y benefactores, apoya a 130 madres solteras con un estipendio mensual de 11 d\u00f3lares.<\/p>\n\n\n\n<p>\u201cIntentamos, con nuestra modesta contribuci\u00f3n, mejorar las estructuras socioecon\u00f3micas de las viudas que tambi\u00e9n son madres solteras\u201d, dice el Padre Kizahakkekara.<\/p>\n\n\n\n<p>M.S.S.S. ofrece becas a ni\u00f1os de la comunidad dalit marginada. Las becas se utilizan para libros, cuotas escolares y matr\u00edcula, y para el pago de pr\u00e9stamos estudiantiles.<\/p>\n\n\n\n<p>\u201cHay muchas familias pobres en nuestras parroquias\u201d, dice el Padre Kizahakkekara, citando el apoyo de donantes.<\/p>\n\n\n\n<p>\u201cLa educaci\u00f3n es, sin duda, el mejor regalo que se le puede dar a alguien\u201d.<\/p>\n\n\n\n<p>Anubha George fue editora de la BBC. Es columnista y escritora para diversas publicaciones. Reside en Kerala, India.<\/p>\n\n\n<div class=\"cnewa-connections\">\n  <div class=\"cnewa-connections-heading\">\n    <h2>Conexi\u00f3n CNEWA<\/h2>\n  <\/div>\n  <div class=\"cnewa-connections-content\" style=\"background:#6B4D5E;color:#ffffff\">\n    <p style=\"font-weight: 400;\">CNEWA acompa\u00f1a a las iglesias cat\u00f3licas sirio-malabar y sirio-malankar de la India en sus ministerios sociales y de atenci\u00f3n m\u00e9dica, sirviendo a las poblaciones m\u00e1s vulnerables y marginadas. El apoyo de CNEWA, por d\u00e9cadas, al Instituto Damien incluye fondos para sus operaciones, y alimentos y medicinas para sus pacientes. Una subvenci\u00f3n de CNEWA al programa de Cuidados Paliativos Hrudaya proporciona camas de aire para la prevenci\u00f3n de llagas; cilindros de ox\u00edgeno para asistencia respiratoria; sillas de ruedas para movilidad y accesibilidad; congeladores m\u00f3viles para almacenar medicamentos sensibles a la temperatura y ambulancias para transporte de emergencia. CNEWA tambi\u00e9n financia el programa de becas de la Sociedad de Servicios Sociales Malankara para ni\u00f1os dalit.<\/p>\n<p style=\"font-weight: 400;\">Apoye la labor de CNEWA en India, llamando al 1-866-322-4441 (Canad\u00e1) o al 1-800-442-6392 (Estados Unidos) o visite <a href=\"https:\/\/cnewa.org\/es\/donacion\/\">cnewa.org\/es\/donacion\/.<\/a><\/p>\n  <\/div>\n<\/div>\n\n\n<p><em><a href=\"https:\/\/issuu.com\/cnewa\/docs\/one_magazine_en_espan_ol_marzo_2026\/27\">Lea este art\u00edculo en nuestro formato de impresi\u00f3n digital aqu\u00ed.<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las iglesias orientales de la India llegan a los m\u00e1rgenes de la sociedad, brindando dignidad en la vida y en la muerte a todos.<\/p>\n","protected":false},"author":70019,"featured_media":7909,"template":"","magazine-issues":[1122],"magazine-sections":[143],"class_list":["post-7934","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","magazine-issues-marzo-2026","magazine-sections-articulos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Iglesia como Hospital de Campa\u00f1a | ONE en Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"Las iglesias orientales de la India llegan a los m\u00e1rgenes de la sociedad, brindando dignidad en la vida y en la muerte a todos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Iglesia como Hospital de Campa\u00f1a | ONE en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Las iglesias orientales de la India llegan a los m\u00e1rgenes de la sociedad, brindando dignidad en la vida y en la muerte a todos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T12:46:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_023H.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/\",\"name\":\"La Iglesia como Hospital de Campa\u00f1a | ONE en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/03\\\/sajeendran202602_023H.jpg\",\"datePublished\":\"2026-03-31T13:00:45+00:00\",\"dateModified\":\"2026-04-01T12:46:56+00:00\",\"description\":\"Las iglesias orientales de la India llegan a los m\u00e1rgenes de la sociedad, brindando dignidad en la vida y en la muerte a todos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/03\\\/sajeendran202602_023H.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/03\\\/sajeendran202602_023H.jpg\",\"width\":1800,\"height\":1198,\"caption\":\"Una enfermera recibe a un paciente con c\u00e1ncer del Programa de Cuidados Paliativos Hrudaya. (foto: Sajeendran V.S.)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/la-iglesia-como-hospital-de-campana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Magazine\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Iglesia como Hospital de Campa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Iglesia como Hospital de Campa\u00f1a | ONE en Espa\u00f1ol","description":"Las iglesias orientales de la India llegan a los m\u00e1rgenes de la sociedad, brindando dignidad en la vida y en la muerte a todos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/","og_locale":"es_ES","og_type":"article","og_title":"La Iglesia como Hospital de Campa\u00f1a | ONE en Espa\u00f1ol","og_description":"Las iglesias orientales de la India llegan a los m\u00e1rgenes de la sociedad, brindando dignidad en la vida y en la muerte a todos.","og_url":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_modified_time":"2026-04-01T12:46:56+00:00","og_image":[{"width":1800,"height":1198,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_023H.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/","url":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/","name":"La Iglesia como Hospital de Campa\u00f1a | ONE en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_023H.jpg","datePublished":"2026-03-31T13:00:45+00:00","dateModified":"2026-04-01T12:46:56+00:00","description":"Las iglesias orientales de la India llegan a los m\u00e1rgenes de la sociedad, brindando dignidad en la vida y en la muerte a todos.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_023H.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/03\/sajeendran202602_023H.jpg","width":1800,"height":1198,"caption":"Una enfermera recibe a un paciente con c\u00e1ncer del Programa de Cuidados Paliativos Hrudaya. (foto: Sajeendran V.S.)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/revista\/la-iglesia-como-hospital-de-campana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"One Magazine","item":"https:\/\/cnewa.org\/es\/revista\/"},{"@type":"ListItem","position":3,"name":"La Iglesia como Hospital de Campa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/7934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/magazine"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"version-history":[{"count":5,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/7934\/revisions"}],"predecessor-version":[{"id":7977,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/7934\/revisions\/7977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/7909"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=7934"}],"wp:term":[{"taxonomy":"magazine-issues","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-issues?post=7934"},{"taxonomy":"magazine-sections","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-sections?post=7934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}