{"id":8219,"date":"2026-06-29T14:38:46","date_gmt":"2026-06-29T18:38:46","guid":{"rendered":"https:\/\/cnewa.org\/es\/?post_type=magazine&#038;p=8219"},"modified":"2026-08-20T14:27:18","modified_gmt":"2026-08-20T18:27:18","slug":"conexiones-junio-2026","status":"publish","type":"magazine","link":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/","title":{"rendered":"Conexiones"},"content":{"rendered":"\n<h2 id=\"h-ayuda-de-emergencia\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-292069c2c851163a61e9eb1d280e9428\"><strong>Ayuda de Emergencia<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">CNEWA contin\u00faa enviando alimentos, agua, pan, ropa de cama y medicinas a desplazados por guerras y desastres naturales. M\u00e1s de un mill\u00f3n de personas han sido desplazados por la guerra en el L\u00edbano entre Israel y Hezbol\u00e1. Muchos est\u00e1n refugiados en instalaciones eclesi\u00e1sticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arzobispo Paolo Borgia, nuncio apost\u00f3lico en L\u00edbano, <a href=\"https:\/\/cnewa.org\/es\/el-sur-del-libano-esta-extremadamente-volatil\/\" type=\"link\" id=\"https:\/\/cnewa.org\/es\/el-sur-del-libano-esta-extremadamente-volatil\/\">ha liderado al menos 14 convoyes<\/a> de ayuda a L\u00edbano desde el 2 de marzo, en coordinaci\u00f3n con la Fuerza Provisional de las Naciones Unidas en el <a href=\"https:\/\/cnewa.org\/es\/donde-trabajamos\/medio-oriente\/libano\/\">L\u00edbano<\/a>. El equipo de CNEWA-Misi\u00f3n Pontificia en Beirut, ha colaborado en la organizaci\u00f3n de los convoyes con sus socios, entre ellos L\u2019Oeuvre d\u2019Orient y Caritas L\u00edbano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CNEWA responde a una crisis alimentaria en Etiop\u00eda. M\u00e1s de 10 millones enfrentan una grave inseguridad alimentaria tras a\u00f1os de conflictos tribales, disturbios civiles y desastres clim\u00e1ticos que han desplazado a millones en una regi\u00f3n que a\u00fan se recupera de COVID-19. La eliminaci\u00f3n de programas financiados por Europa como por USAID ha paralizado los esfuerzos de ayuda, que dependen casi por completo de la ayuda de organizaciones ben\u00e9ficas privadas como CNEWA.<\/p>\n\n\n\n<h2 id=\"h-evento-sobre-ucrania\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-77692ef46a5487d5aed9d4651ee704db\"><strong>Evento Sobre Ucrania<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tres importantes organizaciones eclesi\u00e1sticas \u2014CNEWA, los Caballeros de Col\u00f3n y el Subcomit\u00e9 para la iglesia en Europa Central y Oriental de la Conferencia de obispos cat\u00f3licos de Estados Unidos\u2014 se reunieron en la sede de CNEWA en Nueva York el 5 de mayo para un evento transmitido en directo sobre la situaci\u00f3n en Ucrania y su labor de ayuda a los necesitados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arzobispo metropolitano Borys A. Gudziak, de la Arquidi\u00f3cesis greco-cat\u00f3lica ucraniana de Filadelfia, describi\u00f3 la ayuda cat\u00f3lica a Ucrania como \u201cconstante\u201d. Afirm\u00f3 que el apoyo \u201cha sido de coraz\u00f3n a coraz\u00f3n, de persona a persona, de comunidad a comunidad\u201d y \u201cde iglesia a iglesia\u201d. El arzobispo, quien ha viajado a Ucrania 55 veces desde el inicio de las hostilidades con Rusia en 2014, coment\u00f3 que los ucranianos le piden que \u201cagradezca a quienes oran, informan, act\u00faan y ayudan\u201d.<\/p>\n\n\n\n<h2 id=\"h-premio-cardenal-dolan\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-4be9017f7da384c8fc90eebd39fc9137\"><strong>Premio Cardenal Dolan<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">CNEWA otorg\u00f3 su primer Premio Internacional de Liderazgo Cardenal Timothy Michael Dolan al cardenal que da nombre al premio en una reuni\u00f3n en Roma el 15 de abril. El cardenal fue arzobispo de Nueva York por casi 17 a\u00f1os y presidente ex officio de CNEWA. Las fideicomisarias Amanda Caroline Bowman y Marina C. Perna agradecieron al cardenal, cuyo liderazgo abri\u00f3 el camino para que los laicos formaran parte de la junta directiva, y elogiaron su larga trayectoria al servicio de CNEWA. El cardenal dijo que conoci\u00f3 CNEWA por primera vez cuando prestaba servicio en la nunciatura apost\u00f3lica de Washington con el cardenal Pio Laghi, \u201cquien amaba, amaba, amaba a CNEWA, pues conoc\u00eda bien su labor en Tierra Santa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos d\u00edas despu\u00e9s, en N\u00e1poles, CNEWA organiz\u00f3 eventos para donantes y amigos que incluy\u00f3 una presentaci\u00f3n sobre \u201cLas Siete Obras de Misericordia\u201d de Caravaggio; una visita guiada privada al Museo del Tesoro de San Genaro, patr\u00f3n de la ciudad, ubicado en la catedral dedicada a la Asunci\u00f3n de Mar\u00eda; y una cena ben\u00e9fica en el Grand Hotel Vesuvio.<\/p>\n\n\n\n<h2 id=\"h-encuentro-de-obispos\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-ed747b09c2c806ed33ba5ba75b924f01\"><strong>Encuentro de Obispos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mons. Peter I. Vaccari, presidente de CNEWA, viaj\u00f3 a San Luis del 17 al 19 de marzo para la reuni\u00f3n anual de obispos cat\u00f3licos orientales en Estados Unidos, donde habl\u00f3 sobre la misi\u00f3n de CNEWA, los desaf\u00edos que enfrentan las iglesias orientales en sus pa\u00edses de origen y la labor de CNEWA en Europa del Este, el noreste de \u00c1frica, India y Oriente Medio.<\/p>\n\n\n\n<h2 id=\"h-reserva-la-fecha\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-59b90dc3bb43c15e5d951b593cb4c32d\"><strong>\u00a1Reserva la fecha!<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El centenario de CNEWA se celebrar\u00e1 en su Gala Anual de Sanaci\u00f3n y Esperanza en el Hotel Plaza de Nueva York el 15 de diciembre. El invitado de honor ser\u00e1 Fra John T. Dunlap, pr\u00edncipe y gran maestre de la Soberana Orden Militar de Malta, quien ha impulsado a la orden a convertirse en una fuerza de compasi\u00f3n, encuentro y di\u00e1logo, impactando las vidas de las personas marginadas y vulnerables en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Premio Fe y Cultura de CNEWA se otorgar\u00e1 a la hermana Raffaella Petrini, F.S.E., presidenta de la Comisi\u00f3n Pontificia para el Estado de la Ciudad del Vaticano y de la Gobernaci\u00f3n del Estado de la Ciudad del Vaticano. Una destacada acad\u00e9mica y administradora, la hermana Raffaella supervisa las operaciones del Estado de la Ciudad del Vaticano, lo que la convierte en la mujer de mayor rango en el Vaticano.<\/p>\n\n\n\n<h2 id=\"h-los-jovenes-apoyan-a-cnewa\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-32edb0b6c1b6aab35b59b15130f705df\"><strong>Los J\u00f3venes Apoyan a CNEWA<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mons. Vaccari celebr\u00f3 la Misa en la escuela secundaria St. Joseph by-the-Sea en Staten Island por la fiesta de la Ascensi\u00f3n, el 14 de mayo. Tras la Comuni\u00f3n, miembros del consejo estudiantil, en nombre de los 1.400 alumnos presentes, le entregaron un cheque por $28.211 para la misi\u00f3n de CNEWA. Esta donaci\u00f3n represent\u00f3 el sacrificio de Cuaresma de 2026 de estudiantes, profesores, personal administrativo, padres y donantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mons. Vaccari felicit\u00f3 a los estudiantes por su compromiso con la misi\u00f3n de CNEWA de apoyar a las personas vulnerables y marginadas. Esta donaci\u00f3n fue la m\u00e1s reciente de una serie de iniciativas del alumnado \u2014que incluyen un Concierto por la Paz y un proyecto de video\u2014 para recaudar fondos y crear conciencia sobre CNEWA desde 2022, cuando Mons. Vaccari visit\u00f3 la escuela por la primera vez. Hasta la fecha, la escuela ha donado cerca $115.000 a CNEWA.<\/p>\n\n\n\n<h2 id=\"h-fondos-recibidos\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-2426eb90aa9a167077764e552e3693c6\"><strong>Fondos Recibidos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Koch ha otorgado a CNEWA una subvenci\u00f3n de $450.000. M\u00e1s de la mitad, $250.000, se destinar\u00e1n a financiar la labor humanitaria y pastoral de la iglesia en Gaza. Se destinar\u00e1n $100.000 a la formaci\u00f3n de novicios y seminaristas en Etiop\u00eda y Eritrea; y otros $100.000 a escuelas cat\u00f3licas en Etiop\u00eda y la formaci\u00f3n en la fe de j\u00f3venes en Palestina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCon un esp\u00edritu de fiel administraci\u00f3n y servicio al Evangelio, la Fundaci\u00f3n Koch se siente honrada de apoyar la labor de CNEWA en \u00c1frica y Tierra Santa\u201d, declar\u00f3 Andrew LoFaro, director ejecutivo de la fundaci\u00f3n. \u201cEn el coraz\u00f3n de nuestra misi\u00f3n reside un profundo deseo de fortalecer el testimonio evang\u00e9lico de la iglesia y llevar el mensaje de esperanza y caridad de Cristo a los rincones m\u00e1s remotos del mundo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un privilegio continuar nuestra colaboraci\u00f3n con CNEWA, cuyo incansable servicio encarna a la perfecci\u00f3n esta misi\u00f3n al ofrecer esperanza, sanaci\u00f3n y acompa\u00f1amiento a quienes m\u00e1s lo necesitan\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<h2 id=\"h-one-es-honrada\" class=\"wp-block-heading has-crimson-color has-text-color has-link-color has-medium-font-size wp-elements-160ea9ce2cf653554ecc60ad86e5e125\"><strong><em>ONE<\/em> es Honrada<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El jurado del concurso anual de la Asociaci\u00f3n de noticias religiosas (R.N.A.) calific\u00f3 el reportaje de&nbsp;<em>ONE<\/em>&nbsp;como \u201c\u00a1Periodismo en su m\u00e1xima expresi\u00f3n!\u201d al otorgarle a la revista el segundo lugar en la categor\u00eda de reportajes para p\u00fablico religioso y el tercer lugar en fotograf\u00eda. Los premios se entregaron al concluir la conferencia anual de la R.N.A. en Atlanta, el 25 de abril.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstos reporteros de la revista&nbsp;<em>ONE<\/em>&nbsp;llevan a los lectores al lugar donde ocurren las noticias que todos escuchamos y ofrecen historias conmovedoras que nos hacen ver\u201d, se\u00f1alaron los jueces. \u201cHistorias desgarradoras, escritura poderosa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><a href=\"https:\/\/issuu.com\/cnewa\/docs\/one_magazine_en_espan_ol_junio_2026\/5\">Lea este art\u00edculo en nuestro formato de impresi\u00f3n digital aqu\u00ed.<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00daltimos informes sobre el mundo de CNEWA<\/p>\n","protected":false},"author":70019,"featured_media":8230,"template":"","magazine-issues":[1123],"magazine-sections":[142],"class_list":["post-8219","magazine","type-magazine","status-publish","has-post-thumbnail","hentry","magazine-issues-junio-2026","magazine-sections-secciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conexiones | ONE en Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"Ayuda de Emergencia; Premio Cardenal Dolan; Encuentro de Obispos; Los J\u00f3venes Apoyan a CNEWA; Fondos Recibidos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conexiones | ONE en Espa\u00f1ol\" \/>\n<meta property=\"og:description\" content=\"Ayuda de Emergencia; Premio Cardenal Dolan; Encuentro de Obispos; Los J\u00f3venes Apoyan a CNEWA; Fondos Recibidos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-20T18:27:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/shemitz202605_100H-Edit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/\",\"name\":\"Conexiones | ONE en Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/shemitz202605_100H-Edit.jpg\",\"datePublished\":\"2026-06-29T18:38:46+00:00\",\"dateModified\":\"2026-08-20T18:27:18+00:00\",\"description\":\"Ayuda de Emergencia; Premio Cardenal Dolan; Encuentro de Obispos; Los J\u00f3venes Apoyan a CNEWA; Fondos Recibidos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/shemitz202605_100H-Edit.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/shemitz202605_100H-Edit.jpg\",\"width\":1800,\"height\":1448,\"caption\":\"El arzobispo Borys Gudziak se dirige a los asistentes al evento \u201cUnidos por Ucrania\u201d, celebrado en el centro administrativo de CNEWA en Nueva York el 5 de mayo.(foto: Gregory A. Shemitz, Caballeros de Col\u00f3n)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/conexiones-junio-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"One Magazine\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conexiones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conexiones | ONE en Espa\u00f1ol","description":"Ayuda de Emergencia; Premio Cardenal Dolan; Encuentro de Obispos; Los J\u00f3venes Apoyan a CNEWA; Fondos Recibidos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Conexiones | ONE en Espa\u00f1ol","og_description":"Ayuda de Emergencia; Premio Cardenal Dolan; Encuentro de Obispos; Los J\u00f3venes Apoyan a CNEWA; Fondos Recibidos","og_url":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_modified_time":"2026-08-20T18:27:18+00:00","og_image":[{"width":1800,"height":1448,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/shemitz202605_100H-Edit.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/","url":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/","name":"Conexiones | ONE en Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/shemitz202605_100H-Edit.jpg","datePublished":"2026-06-29T18:38:46+00:00","dateModified":"2026-08-20T18:27:18+00:00","description":"Ayuda de Emergencia; Premio Cardenal Dolan; Encuentro de Obispos; Los J\u00f3venes Apoyan a CNEWA; Fondos Recibidos","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/shemitz202605_100H-Edit.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/06\/shemitz202605_100H-Edit.jpg","width":1800,"height":1448,"caption":"El arzobispo Borys Gudziak se dirige a los asistentes al evento \u201cUnidos por Ucrania\u201d, celebrado en el centro administrativo de CNEWA en Nueva York el 5 de mayo.(foto: Gregory A. Shemitz, Caballeros de Col\u00f3n)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/revista\/conexiones-junio-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"One Magazine","item":"https:\/\/cnewa.org\/es\/revista\/"},{"@type":"ListItem","position":3,"name":"Conexiones"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/8219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/magazine"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"version-history":[{"count":7,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/8219\/revisions"}],"predecessor-version":[{"id":8540,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine\/8219\/revisions\/8540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/8230"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=8219"}],"wp:term":[{"taxonomy":"magazine-issues","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-issues?post=8219"},{"taxonomy":"magazine-sections","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/magazine-sections?post=8219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}