{"id":1891,"date":"2022-11-03T12:06:16","date_gmt":"2022-11-03T16:06:16","guid":{"rendered":"https:\/\/cnewa.org\/es\/?p=1891"},"modified":"2024-10-30T12:16:23","modified_gmt":"2024-10-30T16:16:23","slug":"carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia","status":"publish","type":"post","link":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/","title":{"rendered":"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia"},"content":{"rendered":"\n<p><em>A continuaci\u00f3n se muestra el discurso principal dirigido a los miembros de la Orden Ecuestre del Santo Sepulcro de<\/em>&nbsp;<em>Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos, por Michael La Civita, de CNEWA,<\/em>&nbsp;<em>en su gala anual en la ciudad de Nueva York el 16 de octubre. El discurso fue publicado en el&nbsp;<\/em><a href=\"https:\/\/catholicherald.co.uk\/death-and-dishonour-in-docklands\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Catholic Herald<\/em><\/a><em>&nbsp;(Reino Unido).<\/em><\/p>\n\n\n\n<p>La semana pasada regres\u00e9 del C\u00e1ucaso, Armenia y Georgia espec\u00edficamente, despu\u00e9s de una visita de evaluaci\u00f3n de necesidades de dos semanas para la Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente,&nbsp;o CNEWA, que es una iniciativa de la Santa Sede que trabaja entre las antiguas iglesias de Oriente.<\/p>\n\n\n\n<p>El primero y el segundo pa\u00edses que han adoptado oficialmente la fe cristiana, Armenia en el a\u00f1o 301 y la vecina Georgia unos 18 a\u00f1os despu\u00e9s, sus pueblos han figurado durante mucho tiempo en la vida de nuestra agencia. Las ra\u00edces de CNEWA se encuentran en estas tierras empapadas por la sangre de los m\u00e1rtires, ya que nuestros primeros esfuerzos humanitarios involucraron el rescate de sobrevivientes del genocidio de armenios, asirio-caldeos y otros cristianos en el Imperio Turco Otomano despu\u00e9s de la Primera Guerra Mundial.<\/p>\n\n\n\n<p>Situado en el cruce de Asia y Europa, donde el Norte Global se encuentra con el Sur Global, donde el Este se encuentra con el Oeste, el C\u00e1ucaso es para las grandes potencias competidoras que lo rodean &#8211; Rusia, Ir\u00e1n y Turqu\u00eda &#8211; Zona Cero. Y cada vez m\u00e1s, las peque\u00f1as Armenia y Georgia se est\u00e1n convirtiendo en prioridades estrat\u00e9gicas para las potencias mucho m\u00e1s grandes en Occidente, especialmente la OTAN y los Estados Unidos.<\/p>\n\n\n\n<p>Las amenazas de guerra nuclear no se toman a la ligera aqu\u00ed. Tampoco se los drones, los misiles, los discursos encendidos ni&nbsp;las alianzas hist\u00f3ricas renovadas a lo largo de l\u00edneas culturales y \u00e9tnicas. Para los pueblos de las peque\u00f1as rep\u00fablicas de Armenia y Georgia, su car\u00e1cter distintivo forjado en gran medida por su fe cristiana compartida, estas preocupaciones son existenciales y se intensifican particularmente en Armenia, pero no menos en Georgia.<\/p>\n\n\n\n<p>Hace apenas unos d\u00edas, la sensaci\u00f3n de calma que impregnaba la plaza que rodea la Catedral de la Dormici\u00f3n de Sioni en la capital georgiana de Tbilisi desment\u00eda las tensiones generales que se sent\u00edan en la ciudad, ahora llena de hombres rusos en edad militar y sus familias, todos huyendo de la movilizaci\u00f3n parcial convocada por el presidente ruso Vladimir Putin. Una estructura del siglo 12 construida sobre las ruinas de una iglesia del siglo VI, la catedral se encuentra en el coraz\u00f3n de una ciudad cada vez m\u00e1s moderna, renovada con inversi\u00f3n extranjera y d\u00f3lares tur\u00edsticos. Las familias se arremolinan alrededor, y entran al oscuro santuario para encender una vela, besar un \u00edcono y tal vez escuchar una parte de los servicios que parecen celebrarse durante todo el d\u00eda.<\/p>\n\n\n\n<p>En toda la ciudad, graffiti en ingl\u00e9s, la mayor\u00eda empleando improperios, marcan edificios, vallas y postes, claramente clamando el apoyo georgiano a&nbsp;<a href=\"https:\/\/cnewa.org\/war-on-ukraine-why-catholic-media-must-cover-conflict\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ucrania<\/a>. La distintiva bandera georgiana, que lleva cuatro cruces rojas sobre un fondo blanco, a menudo se combina con la bandera ucraniana de azul cielo y amarillo. Para las decenas de miles de rusos que huyeron del reclutamiento, la vista desaf\u00eda una narrativa que se les aliment\u00f3 desde que el ej\u00e9rcito ruso invadi\u00f3 a sus \u201chermanos peque\u00f1os\u201d en Ucrania el 24 de febrero.<\/p>\n\n\n\n<p>En Armenia, los sentimientos est\u00e1n divididos. Una fuerza militar rusa de mantenimiento de la paz ocupa gran parte del pa\u00eds, en gran parte para proteger a Armenia de una Turqu\u00eda cada vez m\u00e1s hostil y su aliado rico en gas, Azerbaiy\u00e1n.&nbsp;<a href=\"https:\/\/cnewa.org\/what-is-nagorno-karabakh\/\" target=\"_blank\" rel=\"noreferrer noopener\">La dependencia de Armenia<\/a>&nbsp;en un patr\u00f3n voluble, Rusia, ahora distra\u00eddo por una guerra perdida de su propia creaci\u00f3n, tiene a los armenios nerviosos, atenuando cualquier apoyo que puedan tener para una naci\u00f3n que, como ellos, est\u00e1 siendo atacada por un vecino m\u00e1s poderoso. Como dicen mis amigos armenios: \u201cEs complicado\u201d.<\/p>\n\n\n\n<p>Efectivamente, y abrumador.<\/p>\n\n\n\n<p>En un mundo aparentemente enloquecido, \u00bfqu\u00e9 pasar\u00e1 con los pa\u00edses m\u00e1s peque\u00f1os, las comunidades vulnerables, las distintas culturas y&nbsp;&nbsp;sociedades que no se ajustan a las demandas de imperios m\u00e1s ricos y poderosos que buscan a\u00fan m\u00e1s control, m\u00e1s influencia, m\u00e1s poder y m\u00e1s recursos? \u00bfQu\u00e9 pasar\u00e1 con aquellos que se oponen a la deshumanizaci\u00f3n de la persona humana para obtener ganancias pol\u00edticas ideol\u00f3gicas, comerciales o partidistas?<\/p>\n\n\n\n<p>Las comunidades religiosas pueden desempe\u00f1ar un papel importante, incluso servir como ant\u00eddoto, para contrarrestar esta creciente b\u00fasqueda similar a la de Pac-Man para engullir a los peque\u00f1os, los d\u00e9biles y los vulnerables. Las iglesias cat\u00f3licas de Armenia y Georgia, por ejemplo, son peque\u00f1as comunidades de escasos recursos que, sin embargo, desempe\u00f1an un papel desproporcionado en cada pa\u00eds, donde las iglesias&nbsp;<a href=\"https:\/\/cnewa.org\/magazine\/profiles-33239\/\" target=\"_blank\" rel=\"noreferrer noopener\">apost\u00f3licas armenias<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/cnewa.org\/magazine\/profiles-33421\/\" target=\"_blank\" rel=\"noreferrer noopener\">ortodoxas georgianas<\/a>&nbsp;funcionan como religiones estatales. Esto se debe en gran parte a la ense\u00f1anza social cat\u00f3lica que, enraizada en el Evangelio de Jes\u00fas, busca construir y&nbsp;alimentar al pueblo de Dios y trabajar por el bien com\u00fan de todos, cat\u00f3licos, cristianos y todas las personas de buena voluntad.<\/p>\n\n\n\n<p>A lo largo de los a\u00f1os, a lo largo de mis&nbsp;<a href=\"https:\/\/cnewa.org\/journey-through-the-south-caucasushelp-me-save-my-village-51405\/\" target=\"_blank\" rel=\"noreferrer noopener\">viajes en Armenia y Georgia<\/a>&nbsp;como parte del equipo de evaluaci\u00f3n de necesidades de CNEWA, el papel de estas peque\u00f1as iglesias cat\u00f3licas se ha vuelto m\u00e1s claro. En Ucrania, en una visita de CNEWA a principios de mayo dirigida por su presidente, el cardenal Timothy Dolan de Nueva York, el volumen masivo de asistencia de emergencia dada por la comunidad cat\u00f3lica mundial para un pueblo en fuga a trav\u00e9s de las iglesias cat\u00f3licas griegas y latinas de Ucrania asombr\u00f3, y da testimonio del esp\u00edritu generoso de los cat\u00f3licos de todo el mundo, ricos, pobres, blancos, marr\u00f3n, tradicional y progresivo.<\/p>\n\n\n\n<p>En la Tierra Santa m\u00e1s amplia, el papel de la Iglesia Cat\u00f3lica, incluidos grupos caritativos como la Orden Ecuestre del Santo Sepulcro&nbsp;de&nbsp;&nbsp;Jerusal\u00e9n, es creativo y crucial, a pesar de d\u00e9cadas de conflicto y guerra prolongada. En Palestina, por ejemplo, m\u00e1s del 40 por ciento de los programas de servicios sociales de los territorios para ni\u00f1os y sus familias, ancianos y, en general, los m\u00e1s vulnerables y marginados de la sociedad, son administrados por una comunidad cat\u00f3lica cuya poblaci\u00f3n representa menos del 1 por ciento de la poblaci\u00f3n.<\/p>\n\n\n\n<p>No nos equivoquemos: la naturaleza generosa de los cat\u00f3licos, arraigada en el Evangelio de Jes\u00fas, es un poderoso ant\u00eddoto contra los excesos de la globalizaci\u00f3n y su subproducto, la deshumanizaci\u00f3n. Y el compromiso de la iglesia de nutrir, preservar y promover las muchas culturas distintivas que forman estas naciones sanando a sus quebrantados, curando a sus enfermos, alimentando a sus hambrientos y abogando por sus derechos dados por Dios permanece firme. Incluso si nuestra escala es limitada, cambiar una vida es mejor que no cambiar ninguna.<\/p>\n\n\n\n<p>Las peque\u00f1as cosas importan.<\/p>\n\n\n\n<p>Sus asociaciones con miembros de otras iglesias y comunidades religiosas, autoridades civiles cuando corresponde, l\u00edderes laicos locales y la comunidad internacional, particularmente a trav\u00e9s de las din\u00e1micas agencias de servicios sociales de las iglesias, como la red internacional Caritas, CNEWA y la Orden del Santo Sepulcro, les permiten responder al poderoso llamado del Evangelio: \u201c\u00bfY qui\u00e9n es mi pr\u00f3jimo?\u201d<\/p>\n\n\n\n<p>Durante nuestros \u00faltimos d\u00edas en el C\u00e1ucaso, nuestro equipo de CNEWA se reuni\u00f3 con un grupo de refugiados ucranianos que viven en Tbilisi en una casa segura administrada por Caritas, la organizaci\u00f3n ben\u00e9fica de las iglesias cat\u00f3licas locales. Las familias eran de las regiones ahora anexionadas ilegalmente por Rusia, pero la mayor\u00eda sobrevivi\u00f3 a los horrores de Mariupol, huyendo a trav\u00e9s de Rusia en autob\u00fas hacia puntos del sur. A pesar de sus experiencias, ninguno aceptar\u00eda la consejer\u00eda ofrecida por Caritas, que como explic\u00f3 Anahit Mkhoyan,&nbsp;su director, es su derecho.<\/p>\n\n\n\n<p>\u201cNo vamos a forzar nada a nadie, y tal vez encuentren otras formas de resolver el trauma, pero en este momento su enfoque est\u00e1 en llegar a Canad\u00e1 o Europa\u201d, dijo, mientras los refugiados nos mostraban sus humildes habitaciones, y una, su mascota, un pastora belga, Emily.<\/p>\n\n\n\n<p>Unos pocos cientos de refugiados han pasado por esta casa segura desde que los ucranianos comenzaron a llegar a Georgia a fines de la primavera. En este momento, 17 personas, la mayor\u00eda de ellas mujeres, viven en la casa, compartiendo una cocina y algunos ba\u00f1os.<\/p>\n\n\n\n<p>\u201cTenemos nuestros propios conflictos que resolver\u201d, dijo Mkhoyan sobre las crisis internas ocasionales que invariablemente surgen d\u00eda a d\u00eda, incluida una esa misma ma\u00f1ana.<\/p>\n\n\n\n<p>\u201cPara un pueblo que vive bajo tal estr\u00e9s, el curso de sus vidas interrumpido y sus planes destruidos, uno tiene que esperar esto\u201d.<\/p>\n\n\n\n<p>Para mi querida amiga Liana Mkheidze,&nbsp;que ha coordinado las respuestas de emergencia de Caritas Georgia durante unos 20 a\u00f1os, estas resoluciones, as\u00ed como la provisi\u00f3n de asistencia como refugio, alimentos, capacitaci\u00f3n laboral e incluso asesoramiento, son peque\u00f1as victorias.<\/p>\n\n\n\n<p>\u201cLas peque\u00f1as cosas importan\u201d, dijo en su discreta manera sovi\u00e9tica, encogi\u00e9ndose de hombros y manos.<\/p>\n\n\n\n<p>\u201cLas peque\u00f1as cosas importan\u201d.<\/p>\n\n\n\n<p>No podr\u00eda haberlo dicho mejor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n se muestra el discurso principal dirigido a los miembros de la Orden Ecuestre del Santo Sepulcro de&nbsp;Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos, por Michael La Civita, de CNEWA,&nbsp;en su gala anual en la ciudad de Nueva York el 16 de octubre. El discurso fue publicado en el&nbsp;Catholic Herald&nbsp;(Reino Unido). La semana pasada &hellip; <a href=\"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/\">Continued<\/a><\/p>\n","protected":false},"author":70019,"featured_media":1890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[44],"class_list":["post-1891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ucrania"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia | CNEWA Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"Discurso durante gala anual en Nueva York de la Orden Ecuestre del Santo Sepulcro de Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia\" \/>\n<meta property=\"og:description\" content=\"Discurso durante gala anual en Nueva York de la Orden Ecuestre del Santo Sepulcro de Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-03T16:06:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T16:16:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2022\/11\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"883\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael J. La Civita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David R. Aquije\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/\"},\"author\":{\"name\":\"Michael J. La Civita\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/person\\\/d2935c46e239b59210c38997d4aedf00\"},\"headline\":\"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia\",\"datePublished\":\"2022-11-03T16:06:16+00:00\",\"dateModified\":\"2024-10-30T16:16:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/\"},\"wordCount\":1638,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/11\\\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg\",\"articleSection\":[\"Ucrania\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/\",\"name\":\"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia | CNEWA Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/11\\\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg\",\"datePublished\":\"2022-11-03T16:06:16+00:00\",\"dateModified\":\"2024-10-30T16:16:23+00:00\",\"description\":\"Discurso durante gala anual en Nueva York de la Orden Ecuestre del Santo Sepulcro de Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/11\\\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/11\\\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg\",\"width\":883,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ucrania\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/categoria\\\/ucrania\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Michael J. La Civita\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia | CNEWA Espa\u00f1ol","description":"Discurso durante gala anual en Nueva York de la Orden Ecuestre del Santo Sepulcro de Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/","og_locale":"es_ES","og_type":"article","og_title":"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia","og_description":"Discurso durante gala anual en Nueva York de la Orden Ecuestre del Santo Sepulcro de Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos.","og_url":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_published_time":"2022-11-03T16:06:16+00:00","article_modified_time":"2024-10-30T16:16:23+00:00","og_image":[{"width":883,"height":1024,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2022\/11\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg","type":"image\/jpeg"}],"author":"Michael J. La Civita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David R. Aquije","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/"},"author":{"name":"Michael J. La Civita","@id":"https:\/\/cnewa.org\/es\/#\/schema\/person\/d2935c46e239b59210c38997d4aedf00"},"headline":"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia","datePublished":"2022-11-03T16:06:16+00:00","dateModified":"2024-10-30T16:16:23+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/"},"wordCount":1638,"publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2022\/11\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg","articleSection":["Ucrania"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/","url":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/","name":"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia | CNEWA Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2022\/11\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg","datePublished":"2022-11-03T16:06:16+00:00","dateModified":"2024-10-30T16:16:23+00:00","description":"Discurso durante gala anual en Nueva York de la Orden Ecuestre del Santo Sepulcro de Jerusal\u00e9n, Lugartenencia Oriental de los Estados Unidos.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2022\/11\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2022\/11\/IMG_2246-scaled-e1666972363412-883x1024-1.jpg","width":883,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/carta-desde-el-caucaso-por-que-importa-el-destino-de-los-catolicos-en-armenia-y-georgia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ucrania","item":"https:\/\/cnewa.org\/es\/categoria\/ucrania\/"},{"@type":"ListItem","position":3,"name":"Carta desde el C\u00e1ucaso: Por qu\u00e9 Importa el Destino de los Cat\u00f3licos en Armenia y Georgia"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Michael J. La Civita"}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/1891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/comments?post=1891"}],"version-history":[{"count":6,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/1891\/revisions"}],"predecessor-version":[{"id":5848,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/1891\/revisions\/5848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/1890"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=1891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/categories?post=1891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}