{"id":2290,"date":"2023-01-27T11:19:45","date_gmt":"2023-01-27T16:19:45","guid":{"rendered":"https:\/\/cnewa.org\/es\/?p=2290"},"modified":"2023-01-27T11:19:46","modified_gmt":"2023-01-27T16:19:46","slug":"conexiones-con-monsenor-peter-primer-episodio-de-2023","status":"publish","type":"post","link":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/","title":{"rendered":"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023"},"content":{"rendered":"\n<p>A pesar de que es solo el primer mes del nuevo a\u00f1o, el mundo de CNEWA est\u00e1 lleno de actualizaciones. Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para escuchar sobre los acontecimientos de la agencia en enero, as\u00ed como sus objetivos y planes para 2023.<\/p>\n\n\n\n<p>Monse\u00f1or Peter I. Vaccari regres\u00f3 recientemente de la oficina de CNEWA en India, donde dio la bienvenida al reverendo Abraham Kavilpurayidathil, Ph.D., como director ejecutivoy funcionario principal del Fideicomiso de CNEWA en la India, y agradeci\u00f3 a su predecesor, ML Thomas, por sus dedicados a\u00f1os de servicio.<\/p>\n\n\n\n<p>Con un aumento en las restricciones a las contribuciones extranjeras a trav\u00e9s de la Ley de Regulaci\u00f3n de Contribuciones Extranjeras en la India, CNEWA ha tenido que adaptar sus procesos para cumplir con estas enmiendas a la legislaci\u00f3n. Como tal, esta visita fue crucial para continuar el compromiso de CNEWA con su oficina en la India y las personas a las que sirve.<\/p>\n\n\n\n<p>La visita incluy\u00f3 paradas en varios programas financiados por CNEWA, incluidos seminarios y noviciados, la Escuela Oral para Sordos Santa Clara, el Instituto T\u00e9cnico de Bienestar Social y el Hogar de la Fe, entre otros. Monse\u00f1or Vaccari tambi\u00e9n asisti\u00f3 al S\u00ednodo de la Iglesia Siro-Malabar y se reuni\u00f3 con el Cardenal Baselios Cleemis Thottunkal, arzobispo mayor de la Iglesia Siro-Malankar.<\/p>\n\n\n\n<p>Escuche m\u00e1s acerca de la visita de Monse\u00f1or Vaccari a la India en esta entrega de \u201cConexiones con Monse\u00f1or Peter\u201d. Thomas Varghese, el director de programas de CNEWA que se desempe\u00f1\u00f3 como el primer director ejecutivo y funcionario principal del Fideicomiso de CNEWA en la India, es su invitado.<\/p>\n\n\n\n<p>Monse\u00f1or Vaccari tambi\u00e9n compartir\u00e1 noticias sobre su viaje a Roma, donde se reuni\u00f3 con otros miembros del comit\u00e9 directivo de ROACO, una coalici\u00f3n de agencias papales que ayudan a las iglesias orientales de todo el mundo con ayuda humanitaria y apoyo pastoral.<\/p>\n\n\n\n<p>La entrega de enero de \u201cConexiones con Monse\u00f1or Peter\u201d se puede ver en el canal de<a href=\"https:\/\/www.youtube.com\/watch?v=m3tiP57I_BE\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a>&nbsp;de CNEWA, en<a href=\"https:\/\/www.facebook.com\/events\/858483525226999\/?ref=newsfeed\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Facebook<\/a>&nbsp;y Twitter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de que es solo el primer mes del nuevo a\u00f1o, el mundo de CNEWA est\u00e1 lleno de actualizaciones. Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para escuchar sobre los acontecimientos de la agencia en enero, as\u00ed como sus objetivos y planes para 2023. Monse\u00f1or Peter I. Vaccari regres\u00f3 recientemente de &hellip; <a href=\"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/\">Continued<\/a><\/p>\n","protected":false},"author":70019,"featured_media":2289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[91],"class_list":["post-2290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conexiones-con-monsenor-peter"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conexiones con Monse\u00f1or Peter: Primer episodio de 2023<\/title>\n<meta name=\"description\" content=\"Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para conocer los objetivos y planes de la agencia papal para 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023\" \/>\n<meta property=\"og:description\" content=\"Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para conocer los objetivos y planes de la agencia papal para 2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T16:19:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-27T16:19:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/01\/curia202301_002h-CC-1024x823-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"823\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Olivia Poust\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David R. Aquije\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/\"},\"author\":{\"name\":\"Olivia Poust\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/person\\\/d2935c46e239b59210c38997d4aedf00\"},\"headline\":\"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023\",\"datePublished\":\"2023-01-27T16:19:45+00:00\",\"dateModified\":\"2023-01-27T16:19:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/\"},\"wordCount\":359,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/curia202301_002h-CC-1024x823-1.jpg\",\"articleSection\":[\"Conexiones con Monse\u00f1or Peter\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/\",\"name\":\"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/curia202301_002h-CC-1024x823-1.jpg\",\"datePublished\":\"2023-01-27T16:19:45+00:00\",\"dateModified\":\"2023-01-27T16:19:46+00:00\",\"description\":\"Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para conocer los objetivos y planes de la agencia papal para 2023.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/curia202301_002h-CC-1024x823-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/01\\\/curia202301_002h-CC-1024x823-1.jpg\",\"width\":1024,\"height\":823,\"caption\":\"La visita pastoral de Monse\u00f1or Peter I. Vaccari a la India incluy\u00f3 asistir a un S\u00ednodo de la Iglesia Siro-Malabar. De izquierda a derecha: Thomas Varghese, el cardenal George Alencherry, Arzobispo Mayor de Ernakulam-Angamalhy para los Siro-Malabar, el presidente de CNEWA Mons. Peter I. Vaccari, y el director ejecutivo y funcionario principal del Fideicomiso de CNEWA en la India Rev. Dr. Abraham Kavilpurayidathil. (foto: Cortes\u00eda de la Curia de la Iglesia Siro-Malabar)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-con-monsenor-peter-primer-episodio-de-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conexiones con Monse\u00f1or Peter\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/categoria\\\/conexiones-con-monsenor-peter\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Olivia Poust\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023","description":"Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para conocer los objetivos y planes de la agencia papal para 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023","og_description":"Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para conocer los objetivos y planes de la agencia papal para 2023.","og_url":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_published_time":"2023-01-27T16:19:45+00:00","article_modified_time":"2023-01-27T16:19:46+00:00","og_image":[{"width":1024,"height":823,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/01\/curia202301_002h-CC-1024x823-1.jpg","type":"image\/jpeg"}],"author":"Olivia Poust","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David R. Aquije","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/"},"author":{"name":"Olivia Poust","@id":"https:\/\/cnewa.org\/es\/#\/schema\/person\/d2935c46e239b59210c38997d4aedf00"},"headline":"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023","datePublished":"2023-01-27T16:19:45+00:00","dateModified":"2023-01-27T16:19:46+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/"},"wordCount":359,"publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/01\/curia202301_002h-CC-1024x823-1.jpg","articleSection":["Conexiones con Monse\u00f1or Peter"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/","url":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/","name":"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/01\/curia202301_002h-CC-1024x823-1.jpg","datePublished":"2023-01-27T16:19:45+00:00","dateModified":"2023-01-27T16:19:46+00:00","description":"Vea el \u201cConexiones con Monse\u00f1or Peter\u201d del 25 de enero para conocer los objetivos y planes de la agencia papal para 2023.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/01\/curia202301_002h-CC-1024x823-1.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/01\/curia202301_002h-CC-1024x823-1.jpg","width":1024,"height":823,"caption":"La visita pastoral de Monse\u00f1or Peter I. Vaccari a la India incluy\u00f3 asistir a un S\u00ednodo de la Iglesia Siro-Malabar. De izquierda a derecha: Thomas Varghese, el cardenal George Alencherry, Arzobispo Mayor de Ernakulam-Angamalhy para los Siro-Malabar, el presidente de CNEWA Mons. Peter I. Vaccari, y el director ejecutivo y funcionario principal del Fideicomiso de CNEWA en la India Rev. Dr. Abraham Kavilpurayidathil. (foto: Cortes\u00eda de la Curia de la Iglesia Siro-Malabar)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/conexiones-con-monsenor-peter-primer-episodio-de-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conexiones con Monse\u00f1or Peter","item":"https:\/\/cnewa.org\/es\/categoria\/conexiones-con-monsenor-peter\/"},{"@type":"ListItem","position":3,"name":"Conexiones con Monse\u00f1or Peter: Primer episodio de 2023"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Olivia Poust"}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/comments?post=2290"}],"version-history":[{"count":5,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2290\/revisions"}],"predecessor-version":[{"id":2296,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2290\/revisions\/2296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/2289"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=2290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/categories?post=2290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}