{"id":2353,"date":"2023-02-06T14:48:04","date_gmt":"2023-02-06T19:48:04","guid":{"rendered":"https:\/\/cnewa.org\/es\/?p=2353"},"modified":"2024-10-30T13:26:07","modified_gmt":"2024-10-30T17:26:07","slug":"la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa","status":"publish","type":"post","link":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/","title":{"rendered":"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En 1999, mientras el mundo se preparaba para dar la bienvenida a un nuevo a\u00f1o, un nuevo siglo y un nuevo milenio, las Naciones Unidas preparaban quiz\u00e1s el conjunto m\u00e1s ambicioso de \u201cresoluciones de A\u00f1o Nuevo\u201d de la historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conocidos como los Objetivos de Desarrollo del Milenio, o ODM,&nbsp;<a href=\"https:\/\/www.who.int\/es\/news-room\/fact-sheets\/detail\/millennium-development-goals-(mdgs)\" target=\"_blank\" rel=\"noreferrer noopener\">estos ocho objetivos<\/a> demandaron erradicar la pobreza extrema y el hambre; lograr la educaci\u00f3n primaria universal; promover la igualdad de g\u00e9nero y empoderar a las mujeres; reducir la mortalidad infantil; mejorar la salud materna; combatir el VIH\/SIDA, la malaria y otras enfermedades; garantizar la sostenibilidad ambiental; y desarrollar una asociaci\u00f3n global para el desarrollo. La ONU fij\u00f3 como fecha l\u00edmite para alcanzar estos objetivos el 2015.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el principio hubo cr\u00edticas. Los ODM parec\u00edan idealistas e ingenuos. Muchos preguntaron, la mayor\u00eda seriamente, algunos sarc\u00e1sticamente: \u201c\u00bfY qu\u00e9 pasar\u00e1 en 2016?\u201d Algunos temieron comprensiblemente que los ambiciosos objetivos fueran un caso cl\u00e1sico de extralimitaci\u00f3n burocr\u00e1tica y esperaban que desaparecieran como tantas otras cosas en el pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque la declaraci\u00f3n fue aprobada por 191 estados miembros de la Asamblea General de la ONU, la resoluci\u00f3n no era vinculante. Adem\u00e1s, surgieron preguntas sobre c\u00f3mo medir el \u00e9xito de los objetivos; no hab\u00eda m\u00e9tricas pr\u00e1cticas disponibles ni universalmente aceptadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe se\u00f1alar, sin embargo, que los Objetivos de Desarrollo del Milenio encontraron una audiencia preparada entre las organizaciones no gubernamentales (ONG) que conforman la \u201csociedad civil\u201d en la comunidad de las Naciones Unidas. Muchas ONG, incluyendo a las organizaciones religiosas, dieron la bienvenida a los objetivos y durante mucho tiempo han trabajado para abogar y promover uno o m\u00e1s de ellos. En consecuencia, estas organizaciones ten\u00edan experiencia con objetivos individuales y tambi\u00e9n desarrollaron m\u00e9tricas de evaluaci\u00f3n a partir de sus experiencias \u201csobre el campo\u201d. Se podr\u00eda decir que las ONG desempe\u00f1aron un papel clave para ayudar a avanzar en las resoluciones de la ONU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quince a\u00f1os es poco tiempo para lograr cualquier objetivo desafiante, para no mencionar la realizaci\u00f3n de objetivos tan ambiciosos como los Objetivos de Desarrollo del Milenio. La pregunta, \u201c\u00bfQu\u00e9 pasar\u00e1 en 2016?\u00bb comenz\u00f3 a tomarse no solo en serio, sino estrat\u00e9gicamente. El a\u00f1o 2015 ya no se consider\u00f3 como el a\u00f1o para admitir la incapacidad de lograr todos los objetivos, sino m\u00e1s bien como una oportunidad para revisar, evaluar y determinar. Lo m\u00e1s importante es que el liderazgo de la ONU y las organizaciones miembros comenzaron a reconocer que 2015 no fue el final del esfuerzo, sino el comienzo de una nueva fase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo,<a href=\"https:\/\/www.undp.org\/es\/publications\/objetivos-de-desarrollo-del-milenio-informe-de-2015\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;el Informe sobre los Objetivos de Desarrollo del Milenio<\/a>,&nbsp;publicado en 2015, sorprendi\u00f3 a muchos con los resultados en lo que se ha descrito como un \u201cinforme de progreso\u201d y no un informe de \u201cmisi\u00f3n cumplida\u201d. Es importante se\u00f1alar que ninguno de los objetivos identificados en 1999 se consider\u00f3 superfluo o alcanzado. Adem\u00e1s, las m\u00e9tricas tienden a depender de datos y condiciones espec\u00edficas que podr\u00edan no ser obvias para el lector promedio. Algunos de los hallazgos del informe incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La \u201ctasa de pobreza extrema\u201d en los pa\u00edses en desarrollo se redujo del 47% al 14% entre 1990 y 2015;<\/li>\n\n\n\n<li>El n\u00famero de \u201cni\u00f1os sin escolarizar\u201d en todo el mundo se redujo de 100 millones a 57 millones entre 2000 y 2015;<\/li>\n\n\n\n<li>Las muertes de ni\u00f1os menores de cinco a\u00f1os disminuyeron a nivel mundial de 12,7 millones a 6 millones entre 1990 y 2015.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Lejos de ser la fecha de una derrota, 2015 proporcion\u00f3 un gran impulso para evaluar los Objetivos de Desarrollo del Milenio y planificar \u201cel siguiente paso\u201d. Una vez m\u00e1s, la sociedad civil, las ONG, proporcionaron una gran cantidad de energ\u00eda y experiencia para articular esta fase, ya que muchos ya se hab\u00edan estado preparando. Con cierta simplificaci\u00f3n excesiva, los objetivos identificados como los Objetivos de Desarrollo del Milenio de la ONU en 1999 evolucionaron en Objetivos de Desarrollo Sostenible o ODS.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"691\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/wiggers20201_038H-1024x691-1.jpg\" alt=\"\" class=\"wp-image-2351\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/wiggers20201_038H-1024x691-1.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/wiggers20201_038H-1024x691-1-300x202.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/wiggers20201_038H-1024x691-1-768x518.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ni\u00f1os de la Escuela Cat\u00f3lica Kidane Meheret reciben beneficios gracias a generosos benefactores de CNEWA. (foto: Petterik Wiggers)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En 2015, el Consejo Econ\u00f3mico y Social de las Naciones Unidas public\u00f3&nbsp;<a href=\"https:\/\/www.un.org\/sustainabledevelopment\/es\/development-agenda\/\" target=\"_blank\" rel=\"noreferrer noopener\">Transformar Nuestro Mundo: la Agenda 2030 para&nbsp;el Desarrollo Sostenible,<\/a> que introdujo los ODS: \u201cLos 17 Objetivos de Desarrollo Sostenible y las 169 metas que anunciamos hoy demuestran la escala y la ambici\u00f3n de esta nueva agenda universal. Buscan construir sobre los Objetivos de Desarrollo del Milenio y completar lo que estos no lograron\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque hay superposici\u00f3n entre los dos conjuntos de objetivos, hay pruebas claras de una evoluci\u00f3n ya que el n\u00famero de goles aument\u00f3 de ocho a&nbsp;<a href=\"https:\/\/www.undp.org\/sustainable-development-goals\" target=\"_blank\" rel=\"noreferrer noopener\">17.<\/a>&nbsp;&nbsp;El papel cr\u00edtico de las ONG, que por definici\u00f3n est\u00e1n \u201csobre el campo\u201d, permanece constante, ya que se encuentran entre los principales agentes y evaluadores de los Objetivos de Desarrollo Sostenible. No se puede sobreestimar su papel, no s\u00f3lo como ejecutores sino como evaluadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada cuatro a\u00f1os, cada estado miembro de la ONU debe presentar lo que se llama un Examen Peri\u00f3dico Universal (EPU), que informa sobre asuntos como los derechos humanos y los Objetivos de Desarrollo Sostenible. Hay una tendencia en todos los gobiernos de ser positivos en sus autoinformes sobre la aplicaci\u00f3n y el impacto de los ODS. A menudo, los pa\u00edses, especialmente las autocracias, tienden a pintar una imagen m\u00e1s positiva de las condiciones de lo que los hechos podr\u00edan permitir. Las organizaciones no gubernamentales que trabajan en esos pa\u00edses con frecuencia presentan un \u201cODS alternativo\u201d. Tales informes pueden y resultan a menudo en acciones opresivas y violentas contra la ONG por parte del gobierno en cuesti\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo tanto, las ONG a menudo proporcionan un informe crucial y m\u00e1s preciso, aunque menos optimista, sobre la aplicaci\u00f3n, recepci\u00f3n e impacto de los ODS, ya sea en general o espec\u00edficamente. Dicho esto, muy pocas, si alguna, de las ONG promueven todos los 17 objetivos esbozados por las Naciones Unidas. La mayor\u00eda se centra en cuestiones espec\u00edficas, como la atenci\u00f3n m\u00e9dica, las mujeres, los refugiados y los migrantes. Adem\u00e1s, no todas las ONGs est\u00e1n totalmente de acuerdo con ciertos aspectos de cada ODS. La Santa Sede, Estado Observador Permanente ante las Naciones Unidas, no est\u00e1 de acuerdo con algunas cuestiones relativas a la sexualidad humana, el aborto y la salud materna. Sin embargo, es imperativo reconocer que, aunque la Santa Sede tiene muy claro d\u00f3nde y por qu\u00e9 no est\u00e1 de acuerdo y no participa en algunos aspectos de los ODS, est\u00e1 profundamente involucrada y apoya a la mayor\u00eda de ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CNEWA ha sido acreditada ante el Departamento de Comunicaci\u00f3n Global de las Naciones Unidas durante varias d\u00e9cadas. Como tal, CNEWA es parte de la sociedad civil en la organizaci\u00f3n de la ONU, la llamada \u201ccomunidad ONG\u201d. Como una ONG cat\u00f3lica acreditada, basada en la fe, una de docenas, CNEWA sigue tanto el compromiso como las reservas de la Santa Sede con respecto a los ODS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existe una coincidencia natural entre el amplio compromiso de CNEWA con el trabajo humanitario y los Objetivos de Desarrollo Sostenible de la ONU. La presencia de CNEWA en la ONU, junto con docenas de otras ONG cat\u00f3licas, es un ejemplo de la ense\u00f1anza social de la Iglesia Cat\u00f3lica en acci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1999, mientras el mundo se preparaba para dar la bienvenida a un nuevo a\u00f1o, un nuevo siglo y un nuevo milenio, las Naciones Unidas preparaban quiz\u00e1s el conjunto m\u00e1s ambicioso de \u201cresoluciones de A\u00f1o Nuevo\u201d de la historia. Conocidos como los Objetivos de Desarrollo del Milenio, o ODM,&nbsp;estos ocho objetivos demandaron erradicar la pobreza &hellip; <a href=\"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/\">Continued<\/a><\/p>\n","protected":false},"author":70019,"featured_media":2352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[92],"class_list":["post-2353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-naciones-unidas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La ONU, los Objetivos de Desarrollo Sostenible y CNEWA<\/title>\n<meta name=\"description\" content=\"Existe una coincidencia entre el amplio compromiso de CNEWA con el trabajo humanitario y los Objetivos de Desarrollo Sostenible de la ONU\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA\" \/>\n<meta property=\"og:description\" content=\"Existe una coincidencia entre el amplio compromiso de CNEWA con el trabajo humanitario y los Objetivos de Desarrollo Sostenible de la ONU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T19:48:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T17:26:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/nassar20171_052H-1-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elias D. Mallon, S.A., Ph.D.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David R. Aquije\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/\"},\"author\":{\"name\":\"Elias D. Mallon, S.A., Ph.D.\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/person\\\/d2935c46e239b59210c38997d4aedf00\"},\"headline\":\"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA\",\"datePublished\":\"2023-02-06T19:48:04+00:00\",\"dateModified\":\"2024-10-30T17:26:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/\"},\"wordCount\":1253,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/02\\\/nassar20171_052H-1-1024x683-1.jpg\",\"articleSection\":[\"Naciones Unidas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/\",\"name\":\"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/02\\\/nassar20171_052H-1-1024x683-1.jpg\",\"datePublished\":\"2023-02-06T19:48:04+00:00\",\"dateModified\":\"2024-10-30T17:26:07+00:00\",\"description\":\"Existe una coincidencia entre el amplio compromiso de CNEWA con el trabajo humanitario y los Objetivos de Desarrollo Sostenible de la ONU\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/02\\\/nassar20171_052H-1-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/02\\\/nassar20171_052H-1-1024x683-1.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Madres palestinas y sus beb\u00e9s y ni\u00f1os reciben tratamiento en la Cl\u00ednica del Consejo de Iglesias del Cercano Oriente en Al Shejaiya, Gaza. (foto: Wissam Nassar)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Naciones Unidas\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/categoria\\\/naciones-unidas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Elias D. Mallon, S.A., Ph.D.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA","description":"Existe una coincidencia entre el amplio compromiso de CNEWA con el trabajo humanitario y los Objetivos de Desarrollo Sostenible de la ONU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/","og_locale":"es_ES","og_type":"article","og_title":"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA","og_description":"Existe una coincidencia entre el amplio compromiso de CNEWA con el trabajo humanitario y los Objetivos de Desarrollo Sostenible de la ONU","og_url":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_published_time":"2023-02-06T19:48:04+00:00","article_modified_time":"2024-10-30T17:26:07+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/nassar20171_052H-1-1024x683-1.jpg","type":"image\/jpeg"}],"author":"Elias D. Mallon, S.A., Ph.D.","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David R. Aquije","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/"},"author":{"name":"Elias D. Mallon, S.A., Ph.D.","@id":"https:\/\/cnewa.org\/es\/#\/schema\/person\/d2935c46e239b59210c38997d4aedf00"},"headline":"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA","datePublished":"2023-02-06T19:48:04+00:00","dateModified":"2024-10-30T17:26:07+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/"},"wordCount":1253,"publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/nassar20171_052H-1-1024x683-1.jpg","articleSection":["Naciones Unidas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/","url":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/","name":"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/nassar20171_052H-1-1024x683-1.jpg","datePublished":"2023-02-06T19:48:04+00:00","dateModified":"2024-10-30T17:26:07+00:00","description":"Existe una coincidencia entre el amplio compromiso de CNEWA con el trabajo humanitario y los Objetivos de Desarrollo Sostenible de la ONU","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/nassar20171_052H-1-1024x683-1.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/02\/nassar20171_052H-1-1024x683-1.jpg","width":1024,"height":683,"caption":"Madres palestinas y sus beb\u00e9s y ni\u00f1os reciben tratamiento en la Cl\u00ednica del Consejo de Iglesias del Cercano Oriente en Al Shejaiya, Gaza. (foto: Wissam Nassar)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/la-onu-los-objetivos-de-desarrollo-sostenible-y-cnewa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Naciones Unidas","item":"https:\/\/cnewa.org\/es\/categoria\/naciones-unidas\/"},{"@type":"ListItem","position":3,"name":"La ONU, los Objetivos de Desarrollo Sostenible y CNEWA"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Elias D. Mallon, S.A., Ph.D."}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/comments?post=2353"}],"version-history":[{"count":8,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2353\/revisions"}],"predecessor-version":[{"id":5867,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2353\/revisions\/5867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/2352"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=2353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/categories?post=2353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}