{"id":2900,"date":"2023-04-19T13:09:36","date_gmt":"2023-04-19T17:09:36","guid":{"rendered":"https:\/\/cnewa.org\/es\/?p=2900"},"modified":"2023-04-19T13:09:37","modified_gmt":"2023-04-19T17:09:37","slug":"conexiones-cnewa-en-conmemoracion-del-holocausto","status":"publish","type":"post","link":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/","title":{"rendered":"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto"},"content":{"rendered":"\n<p>El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril. Aunque para la <a href=\"https:\/\/www.un.org\/es\/holocaustremembrance\" target=\"_blank\" rel=\"noreferrer noopener\">ONU el d\u00eda de conmemoraci\u00f3n es el 27 de enero<\/a>, los jud\u00edos (dependiendo del s\u00e1bado) conmemoran el d\u00eda 27 del mes jud\u00edo de nis\u00e1n (abril\/mayo), unas dos semanas despu\u00e9s del comienzo de la Pascua. Yom HaShoah 2023 tambi\u00e9n conmemora el 80 aniversario del levantamiento del <a href=\"https:\/\/www.yadvashem.org\/es\/holocaust\/about\/ghettos\/warsaw.html\" target=\"_blank\" rel=\"noreferrer noopener\">gueto jud\u00edo de Varsovia<\/a> contra los ocupantes nazis.<\/p>\n\n\n\n<p>Aunque el Holocausto ha llegado a referirse \u00fanicamente al exterminio nazi de seis millones de jud\u00edos entre 1941 y 1945, no deja de tener una importancia mucho m\u00e1s amplia, en realidad global. El Holocausto no fue solo un evento \u00fanico en el sentido de que no ten\u00eda ra\u00edces y que simplemente apareci\u00f3 en el escenario de la historia, como Atenea apareci\u00f3 totalmente armada en la cabeza de Zeus.<\/p>\n\n\n\n<p>El Holocausto fue el resultado de siglos de desprecio, opresi\u00f3n y alienaci\u00f3n. Aunque la eficiencia demon\u00edaca del Holocausto pudo haber sido algo inesperado, la trayectoria de los siglos que culminaron en el holocausto no lo fue.&nbsp;<\/p>\n\n\n\n<p>Durante siglos en Europa, los jud\u00edos se convirtieron cada vez m\u00e1s en los&nbsp;<em>outsider<\/em>s por excelencia. Los jud\u00edos no formaban parte de la \u201ccultura\u201d abrumadoramente cristiana. A menudo, los jud\u00edos ten\u00edan que usar ropa o s\u00edmbolos especiales para demostrar que eran forasteros. A los jud\u00edos se les prohibi\u00f3 participar en muchos oficios, no pod\u00edan poseer tierras y, a menudo, se les obligaba a vivir en guetos, separados de la cultura dominante. La transici\u00f3n entre ser etiquetado como un \u201coutsider\u201d a ser etiquetado como un \u201cinfrahumano\u201d no fue muy grande y fue lograda de manera eficiente por la propaganda nazi.<\/p>\n\n\n\n<p>Aunque Yom HaShoah es una conmemoraci\u00f3n jud\u00eda, le habla al mundo entero de una manera que otras celebraciones jud\u00edas como Pesach (Pascua), Rosh Hashannah (A\u00f1o Nuevo) y Yom Kippur (D\u00eda de la Expiaci\u00f3n) no lo hacen. Si bien admitimos una singularidad en el Holocausto nazi, no podemos pasar por alto que no fue el primero ni el \u00faltimo genocidio del siglo XX. Millones de personas murieron en el genocidio de los armenios despu\u00e9s de la Primera Guerra Mundial. Desde 1975 hasta 1979, Pot Pol y los Jemeres Rojos mataron entre 1,5 y 2 millones de personas en Camboya. Tambi\u00e9n hay indicios recientes de que Rusia ha practicado t\u00e1cticas genocidas contra los ucranianos.<\/p>\n\n\n\n<p>Aun cuando conmemoramos el Yom HaShoah 2023, estamos alarmados por el aumento del antisemitismo en el mundo industrializado incluso en nuestro propio pa\u00eds. Las minor\u00edas de todo tipo est\u00e1n siendo empujadas a la periferia en todo el mundo.<\/p>\n\n\n\n<p>Yom HaShoah muestra que la trayectoria es terriblemente clara. Un grupo dominante, o un grupo que desea volverse dominante, comienza a empujar a otro grupo a la periferia de la sociedad hasta que este se convierta en un intruso y, en \u00faltima instancia, en intruso amenazante. Ser relegado a la periferia de la sociedad est\u00e1 a un paso de ser relegado a la periferia de la humanidad.&nbsp;Yom HaShoah es un recordatorio para el mundo entero del peligro de deshumanizar al forastero. El Papa Francisco nos llama constantemente a ser conscientes de \u201clos que est\u00e1n en las periferias\u201d. En su lema que hace referencia a \u201cUn Dios, mundo y familia humana\u2026\u201d CNEWA se compromete a llegar a los marginados, acoger a los forasteros y defender los derechos de todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril. Aunque para la ONU el d\u00eda de conmemoraci\u00f3n es el 27 de enero, los jud\u00edos (dependiendo del s\u00e1bado) conmemoran el d\u00eda 27 del mes jud\u00edo de nis\u00e1n (abril\/mayo), unas dos semanas despu\u00e9s del &hellip; <a href=\"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/\">Continued<\/a><\/p>\n","protected":false},"author":70019,"featured_media":2899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[92,34,7],"class_list":["post-2900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-naciones-unidas","category-meditacion","category-conexiones-cnewa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto | CNEWA Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto\" \/>\n<meta property=\"og:description\" content=\"El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T17:09:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T17:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/04\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"1127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elias D. Mallon, S.A., Ph.D.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David R. Aquije\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/\"},\"author\":{\"name\":\"Elias D. Mallon, S.A., Ph.D.\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/person\\\/d2935c46e239b59210c38997d4aedf00\"},\"headline\":\"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto\",\"datePublished\":\"2023-04-19T17:09:36+00:00\",\"dateModified\":\"2023-04-19T17:09:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/\"},\"wordCount\":600,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg\",\"articleSection\":[\"Naciones Unidas\",\"Meditaci\u00f3n\",\"Conexiones CNEWA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/\",\"name\":\"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto | CNEWA Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg\",\"datePublished\":\"2023-04-19T17:09:36+00:00\",\"dateModified\":\"2023-04-19T17:09:37+00:00\",\"description\":\"El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/04\\\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg\",\"width\":1700,\"height\":1127,\"caption\":\"Fotos de las v\u00edctimas del Holocausto se exhiben en el Sal\u00f3n de los Nombres en el Museo de Historia del Holocausto en Yad Vashem en Jerusal\u00e9n en marzo 2005. (foto: CNS\\\/ Debbie Hill)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/conexiones-cnewa-en-conmemoracion-del-holocausto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meditaci\u00f3n\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/categoria\\\/meditacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Elias D. Mallon, S.A., Ph.D.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto | CNEWA Espa\u00f1ol","description":"El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/","og_locale":"es_ES","og_type":"article","og_title":"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto","og_description":"El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril.","og_url":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_published_time":"2023-04-19T17:09:36+00:00","article_modified_time":"2023-04-19T17:09:37+00:00","og_image":[{"width":1700,"height":1127,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/04\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg","type":"image\/jpeg"}],"author":"Elias D. Mallon, S.A., Ph.D.","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David R. Aquije","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/"},"author":{"name":"Elias D. Mallon, S.A., Ph.D.","@id":"https:\/\/cnewa.org\/es\/#\/schema\/person\/d2935c46e239b59210c38997d4aedf00"},"headline":"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto","datePublished":"2023-04-19T17:09:36+00:00","dateModified":"2023-04-19T17:09:37+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/"},"wordCount":600,"publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/04\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg","articleSection":["Naciones Unidas","Meditaci\u00f3n","Conexiones CNEWA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/","url":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/","name":"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto | CNEWA Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/04\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg","datePublished":"2023-04-19T17:09:36+00:00","dateModified":"2023-04-19T17:09:37+00:00","description":"El D\u00eda Internacional de Conmemoraci\u00f3n del Holocausto (Yom HaShoah) es celebrado este a\u00f1o desde la noche del 17 al 18 de abril.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/04\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2023\/04\/20050314T0900-JERUSALEM-HOLOCAUST-HISTORY-1229721.jpg","width":1700,"height":1127,"caption":"Fotos de las v\u00edctimas del Holocausto se exhiben en el Sal\u00f3n de los Nombres en el Museo de Historia del Holocausto en Yad Vashem en Jerusal\u00e9n en marzo 2005. (foto: CNS\/ Debbie Hill)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/conexiones-cnewa-en-conmemoracion-del-holocausto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Meditaci\u00f3n","item":"https:\/\/cnewa.org\/es\/categoria\/meditacion\/"},{"@type":"ListItem","position":3,"name":"Conexiones CNEWA: En Conmemoraci\u00f3n del Holocausto"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Elias D. Mallon, S.A., Ph.D."}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/comments?post=2900"}],"version-history":[{"count":5,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2900\/revisions"}],"predecessor-version":[{"id":2906,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/2900\/revisions\/2906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/2899"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=2900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/categories?post=2900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}