{"id":6166,"date":"2025-01-29T11:48:20","date_gmt":"2025-01-29T16:48:20","guid":{"rendered":"https:\/\/cnewa.org\/es\/?p=6166"},"modified":"2025-03-21T11:39:42","modified_gmt":"2025-03-21T15:39:42","slug":"actualizacion-de-la-situacion-en-gaza","status":"publish","type":"post","link":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/","title":{"rendered":"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza"},"content":{"rendered":"\n<p>Desde que comenz\u00f3 el actual acuerdo de alto el fuego entre Israel y Ham\u00e1s el 19 de enero, unos 500 camiones de ayuda han entrado en Gaza diariamente. Se espera que estos esfuerzos repongan los suministros de alimentos para las campa\u00f1as de distribuci\u00f3n de alimentos. Sin embargo, se neg\u00f3 la entrada de cobertizos y tiendas de campa\u00f1a a trav\u00e9s del cruce, lo que dificult\u00f3 a\u00fan m\u00e1s la capacidad de las personas para enfrentar el fr\u00edo.<\/p>\n\n\n\n<p>La situaci\u00f3n humanitaria de Gaza es sombr\u00eda. M\u00e1s de 17.000 ni\u00f1os de Gaza est\u00e1n sin sus familias, muchos de ellos hu\u00e9rfanos. Se estima que 150.000 mujeres embarazadas y madres primerizas necesitan desesperadamente servicios de salud vitales. Las personas con enfermedades cr\u00f3nicas no tienen medicamentos ni acceso a tratamiento m\u00e9dico. Mujeres y ni\u00f1as se enfrentan a la violencia sexual; las sobrevivientes de violaciones y abusos no tienen acceso a atenci\u00f3n m\u00e9dica ni a agua potable. Quedan expuestas y vulnerables. Seg\u00fan UNICEF, un mill\u00f3n de ni\u00f1os necesitan apoyo psicosocial y de salud mental para la depresi\u00f3n grave, la ansiedad y los pensamientos suicidas.<\/p>\n\n\n\n<p>El equipo de CNEWA-Misi\u00f3n Pontificia con sede en Jerusal\u00e9n contin\u00faa sus esfuerzos en Gaza, promoviendo sus programas psicosociales entre las comunidades vulnerables, especialmente los ni\u00f1os; proporcionando paquetes de alimentos y bienestar; y financiando un programa de atenci\u00f3n m\u00e9dica que atiende a miles de ni\u00f1os, j\u00f3venes y mujeres. Estas intervenciones, llevadas a cabo en cooperaci\u00f3n con nuestros socios, est\u00e1n salvando vidas y ayudando a miles de personas a hacer frente a esta crisis.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250120T1708-ISRAEL-HAMAS-CEASEFIRE-STARTS-1788617-1024x682.jpg\" alt=\"\" class=\"wp-image-6164\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250120T1708-ISRAEL-HAMAS-CEASEFIRE-STARTS-1788617-1024x682.jpg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250120T1708-ISRAEL-HAMAS-CEASEFIRE-STARTS-1788617-300x200.jpg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250120T1708-ISRAEL-HAMAS-CEASEFIRE-STARTS-1788617-768x512.jpg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250120T1708-ISRAEL-HAMAS-CEASEFIRE-STARTS-1788617-1536x1024.jpg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250120T1708-ISRAEL-HAMAS-CEASEFIRE-STARTS-1788617-1600x1066.jpg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250120T1708-ISRAEL-HAMAS-CEASEFIRE-STARTS-1788617.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Un joven palestino con una parte de su pierna amputada camina entre los escombros de casas y edificios en Al-Bureij, en el centro de la Franja de Gaza, destruidos durante la guerra entre Israel y Ham\u00e1s, el 20 de enero. (foto: OSV News\/Khamis Saeed, Reuters)<\/figcaption><\/figure>\n\n\n\n<p>Los programas de desnutrici\u00f3n para madres e hijos son una prioridad a medida que las enfermedades cr\u00f3nicas contin\u00faan aumentando. Se requiere atenci\u00f3n m\u00e9dica urgente, y los pacientes con problemas de salud cr\u00f3nicos no han visto a especialistas en 15 meses, ya que hay limitadas instalaciones y m\u00e9dicos especializados despu\u00e9s del bombardeo incesante de instalaciones e infraestructura. Las escuelas deben ser rehabilitadas lo antes posible para que los ni\u00f1os puedan reanudar su educaci\u00f3n.<\/p>\n\n\n\n<p>El mayor desaf\u00edo que tenemos por delante es la libre circulaci\u00f3n de personas y la reconstrucci\u00f3n de Gaza, que costar\u00e1 miles de millones de d\u00f3lares. Seg\u00fan la \u00faltima actualizaci\u00f3n humanitaria de la Oficina de las Naciones Unidas para la Coordinaci\u00f3n de Asuntos Humanitarios, desde el comienzo del alto el fuego se ha producido una oleada de suministros, se han incrementado las distribuciones, se han iniciado las reparaciones de infraestructuras cr\u00edticas y se ha distribuido combustible.<\/p>\n\n\n\n<p><a href=\"https:\/\/cnewa.org\/es\/que-hacemos\/apoye-la-ayuda-de-emergencia-en-tierra-santa\/\">Apoye el trabajo de CNEWA-Misi\u00f3n Pontificia en Gaza.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joseph Hazboun, director regional de la oficina de Jerusal\u00e9n de CNEWA-Misi\u00f3n Pontificia, ofrece una actualizaci\u00f3n sobre el estado de la situaci\u00f3n humanitaria en Gaza en medio del reciente alto el fuego.<\/p>\n","protected":false},"author":70019,"featured_media":6165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1114,53,48],"class_list":["post-6166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuda-urgente-para-emergencias","category-tierra-santa","category-gaza"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Actualizaci\u00f3n de la Situaci\u00f3n en Gaza | CNEWA Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"Director regional de la oficina de Jerusal\u00e9n de CNEWA-Misi\u00f3n Pontificia, brinda una actualizaci\u00f3n sobre la situaci\u00f3n humanitaria en Gaza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza\" \/>\n<meta property=\"og:description\" content=\"Director regional de la oficina de Jerusal\u00e9n de CNEWA-Misi\u00f3n Pontificia, brinda una actualizaci\u00f3n sobre la situaci\u00f3n humanitaria en Gaza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T16:48:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T15:39:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joseph Hazboun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David R. Aquije\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/\"},\"author\":{\"name\":\"Joseph Hazboun\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/person\\\/d2935c46e239b59210c38997d4aedf00\"},\"headline\":\"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza\",\"datePublished\":\"2025-01-29T16:48:20+00:00\",\"dateModified\":\"2025-03-21T15:39:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/\"},\"wordCount\":504,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/01\\\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg\",\"articleSection\":[\"Ayuda Urgente para Emergencias\",\"Tierra Santa\",\"Gaza\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/\",\"name\":\"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza | CNEWA Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/01\\\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg\",\"datePublished\":\"2025-01-29T16:48:20+00:00\",\"dateModified\":\"2025-03-21T15:39:42+00:00\",\"description\":\"Director regional de la oficina de Jerusal\u00e9n de CNEWA-Misi\u00f3n Pontificia, brinda una actualizaci\u00f3n sobre la situaci\u00f3n humanitaria en Gaza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/01\\\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/01\\\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Palestinos se abren paso entre los escombros de casas y edificios destruidos en Jabalia, en el norte de la Franja de Gaza, el 21 de enero, tras un alto el fuego entre Israel y Hamas. (foto: OSV News\\\/Dawoud Abu Alkas, Reuters)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/actualizacion-de-la-situacion-en-gaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tierra Santa\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/categoria\\\/tierra-santa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Joseph Hazboun\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza | CNEWA Espa\u00f1ol","description":"Director regional de la oficina de Jerusal\u00e9n de CNEWA-Misi\u00f3n Pontificia, brinda una actualizaci\u00f3n sobre la situaci\u00f3n humanitaria en Gaza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/","og_locale":"es_ES","og_type":"article","og_title":"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza","og_description":"Director regional de la oficina de Jerusal\u00e9n de CNEWA-Misi\u00f3n Pontificia, brinda una actualizaci\u00f3n sobre la situaci\u00f3n humanitaria en Gaza.","og_url":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_published_time":"2025-01-29T16:48:20+00:00","article_modified_time":"2025-03-21T15:39:42+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg","type":"image\/jpeg"}],"author":"Joseph Hazboun","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David R. Aquije","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/"},"author":{"name":"Joseph Hazboun","@id":"https:\/\/cnewa.org\/es\/#\/schema\/person\/d2935c46e239b59210c38997d4aedf00"},"headline":"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza","datePublished":"2025-01-29T16:48:20+00:00","dateModified":"2025-03-21T15:39:42+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/"},"wordCount":504,"publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg","articleSection":["Ayuda Urgente para Emergencias","Tierra Santa","Gaza"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/","url":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/","name":"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza | CNEWA Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg","datePublished":"2025-01-29T16:48:20+00:00","dateModified":"2025-03-21T15:39:42+00:00","description":"Director regional de la oficina de Jerusal\u00e9n de CNEWA-Misi\u00f3n Pontificia, brinda una actualizaci\u00f3n sobre la situaci\u00f3n humanitaria en Gaza.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/01\/20250122T1223-HOLY-LAND-PILGRIM-RETURN-APPEAL-1788714.jpg","width":2000,"height":1333,"caption":"Palestinos se abren paso entre los escombros de casas y edificios destruidos en Jabalia, en el norte de la Franja de Gaza, el 21 de enero, tras un alto el fuego entre Israel y Hamas. (foto: OSV News\/Dawoud Abu Alkas, Reuters)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/actualizacion-de-la-situacion-en-gaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Tierra Santa","item":"https:\/\/cnewa.org\/es\/categoria\/tierra-santa\/"},{"@type":"ListItem","position":3,"name":"Actualizaci\u00f3n de la Situaci\u00f3n en Gaza"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Joseph Hazboun"}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/6166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/comments?post=6166"}],"version-history":[{"count":1,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/6166\/revisions"}],"predecessor-version":[{"id":6167,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/6166\/revisions\/6167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/6165"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=6166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/categories?post=6166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}