{"id":7507,"date":"2025-12-03T13:46:56","date_gmt":"2025-12-03T18:46:56","guid":{"rendered":"https:\/\/cnewa.org\/es\/?p=7507"},"modified":"2025-12-03T13:46:57","modified_gmt":"2025-12-03T18:46:57","slug":"papa-y-patriarca-urgen-fecha-comun-para-la-pascua","status":"publish","type":"post","link":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/","title":{"rendered":"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua"},"content":{"rendered":"\n<p>ESTAMBUL (CNS) \u2014 El Papa Le\u00f3n XIV y el Patriarca Ecum\u00e9nico Bartolom\u00e9 de Constantinopla hicieron un llamado a los cristianos de Oriente y Occidente para que finalmente acuerden una fecha com\u00fan para la Pascua.<\/p>\n\n\n\n<p>Durante una reuni\u00f3n en el palacio patriarcal el 29 de noviembre, ambos l\u00edderes \u2014quienes se reunieron para celebrar el 1.700 aniversario del Concilio de Nicea\u2014 afirmaron que el aniversario deber\u00eda inspirar \u201cnuevos y valientes pasos en el camino hacia la unidad\u201d, incluyendo la b\u00fasqueda de esa fecha com\u00fan. <\/p>\n\n\n\n<p>En una <a href=\"https:\/\/www.vatican.va\/content\/leo-xiv\/es\/travels\/2025\/documents\/20251129-dichiarazione-congiunta.html\">declaraci\u00f3n conjunta<\/a>, el Papa Le\u00f3n XVI y el Patriarca Bartolom\u00e9 II declararon: \u201cEstamos agradecidos con la Divina Providencia porque este a\u00f1o todo el mundo cristiano celebr\u00f3 la Pascua el mismo d\u00eda. Es nuestro deseo com\u00fan continuar el proceso para buscar una posible soluci\u00f3n que permita celebrar juntos la Fiesta de las Fiestas cada a\u00f1o. Esperamos y oramos para que todos los cristianos, \u2018con toda sabidur\u00eda e inteligencia espiritual\u2019, se comprometan en el proceso de llegar a una celebraci\u00f3n com\u00fan de la gloriosa resurrecci\u00f3n de nuestro Se\u00f1or Jesucristo\u201d.<\/p>\n\n\n\n<p>La declaraci\u00f3n conjunta tambi\u00e9n se\u00f1al\u00f3 que parte del objetivo del cristianismo es contribuir a la paz entre todos los pueblos.<\/p>\n\n\n\n<p>\u201cJuntos elevamos fervientemente nuestras voces para invocar el don de la paz de Dios sobre nuestro mundo. Tr\u00e1gicamente, en muchas regiones de nuestro planeta, los conflictos y la violencia contin\u00faan destruyendo la vida de tantas personas. Hacemos un llamamiento a quienes tienen responsabilidades civiles y pol\u00edticas para que hagan todo lo posible a fin de garantizar que la tragedia de la guerra cese inmediatamente, y pedimos a todas las personas de buena voluntad que apoyen nuestra s\u00faplica\u201d.&nbsp;<\/p>\n\n\n\n<p>Al d\u00eda siguiente, durante el vuelo de Turqu\u00eda al L\u00edbano, el Papa Le\u00f3n XVI declar\u00f3 a la prensa que hab\u00eda hablado sobre las guerras en curso en Ucrania y Gaza durante su reuni\u00f3n privada con el presidente turco, Recep Tayyip Erdogan, el 27 de noviembre.<\/p>\n\n\n\n<p>\u201cEn este viaje, el tema central fue ser un mensajero de paz, el deseo de promover la paz en toda la regi\u00f3n\u201d, declar\u00f3 el Papa Le\u00f3n XIII.<\/p>\n\n\n\n<p>En cuanto a Gaza, a\u00f1adi\u00f3 que \u201cla Santa Sede lleva muchos a\u00f1os apoyando p\u00fablicamente la propuesta de una soluci\u00f3n de dos Estados\u201d en Tierra Santa, con Israel y Palestina como naciones plenamente independientes, seguras dentro de fronteras definidas.<\/p>\n\n\n\n<p>\u201cTodos sabemos que, en este momento, Israel no acepta esa soluci\u00f3n, pero la vemos como la \u00fanica soluci\u00f3n posible al conflicto que viven continuamente\u201d, dijo el Papa Le\u00f3n.<\/p>\n\n\n\n<p>\u201cTambi\u00e9n somos amigos de Israel\u201d, a\u00f1adi\u00f3, \u201cy con ambas partes intentamos ser una voz mediadora que pueda ayudar a alcanzar una soluci\u00f3n con justicia para todos\u201d.<\/p>\n\n\n\n<p>El papa Le\u00f3n tambi\u00e9n se\u00f1al\u00f3 que Erdogan se hab\u00eda ofrecido repetidamente a mediar en las conversaciones directas entre Ucrania y Rusia en busca de la paz. \u201cDesafortunadamente\u201d, dijo el papa, \u201ca\u00fan no hemos visto una soluci\u00f3n, pero hoy hay propuestas concretas para la paz, y esperamos que el presidente Erdogan, gracias a su relaci\u00f3n con los presidentes de Ucrania, Rusia y Estados Unidos, pueda ayudar en este sentido a promover el di\u00e1logo, un alto el fuego y a ver c\u00f3mo resolver este conflicto, esta guerra en Ucrania\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Papa Le\u00f3n XIV tambi\u00e9n afirm\u00f3 haber abordado las guerras en curso en Gaza y Ucrania durante su reuni\u00f3n con el presidente de Turqu\u00eda.<\/p>\n","protected":false},"author":70019,"featured_media":7505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1111,1116,3,43],"class_list":["post-7507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acompanando-a-las-iglesias-locales","category-promoviendo-el-dialogo-y-la-unidad","category-noticias","category-oriente-cristiano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua | CNEWA Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"El Papa Le\u00f3n XIV tambi\u00e9n afirm\u00f3 haber abordado las guerras en curso en Gaza y Ucrania durante su reuni\u00f3n con el presidente de Turqu\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua\" \/>\n<meta property=\"og:description\" content=\"El Papa Le\u00f3n XIV tambi\u00e9n afirm\u00f3 haber abordado las guerras en curso en Gaza y Ucrania durante su reuni\u00f3n con el presidente de Turqu\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-03T18:46:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T18:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/12\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cindy Wooden, Catholic News Service\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David R. Aquije\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/\"},\"author\":{\"name\":\"Cindy Wooden, Catholic News Service\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/person\\\/d2935c46e239b59210c38997d4aedf00\"},\"headline\":\"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua\",\"datePublished\":\"2025-12-03T18:46:56+00:00\",\"dateModified\":\"2025-12-03T18:46:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/12\\\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg\",\"articleSection\":[\"Acompa\u00f1ando a las Iglesias locales\",\"Promoviendo el Di\u00e1logo y la Unidad\",\"Noticias\",\"Oriente Cristiano\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/\",\"name\":\"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua | CNEWA Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/12\\\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg\",\"datePublished\":\"2025-12-03T18:46:56+00:00\",\"dateModified\":\"2025-12-03T18:46:57+00:00\",\"description\":\"El Papa Le\u00f3n XIV tambi\u00e9n afirm\u00f3 haber abordado las guerras en curso en Gaza y Ucrania durante su reuni\u00f3n con el presidente de Turqu\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/12\\\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/12\\\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"El Papa Le\u00f3n XIV y el Patriarca Ecum\u00e9nico Bartolom\u00e9 de Constantinopla se entregan copias de una declaraci\u00f3n conjunta que firmaron el 29 de noviembre al final de un servicio de oraci\u00f3n en la Catedral Patriarcal de San Jorge en Estambul. (foto: CNS\\\/Lola Gomez)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acompa\u00f1ando a las Iglesias locales\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/categoria\\\/acompanando-a-las-iglesias-locales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Cindy Wooden, Catholic News Service\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua | CNEWA Espa\u00f1ol","description":"El Papa Le\u00f3n XIV tambi\u00e9n afirm\u00f3 haber abordado las guerras en curso en Gaza y Ucrania durante su reuni\u00f3n con el presidente de Turqu\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/","og_locale":"es_ES","og_type":"article","og_title":"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua","og_description":"El Papa Le\u00f3n XIV tambi\u00e9n afirm\u00f3 haber abordado las guerras en curso en Gaza y Ucrania durante su reuni\u00f3n con el presidente de Turqu\u00eda.","og_url":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_published_time":"2025-12-03T18:46:56+00:00","article_modified_time":"2025-12-03T18:46:57+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/12\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg","type":"image\/jpeg"}],"author":"Cindy Wooden, Catholic News Service","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David R. Aquije","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/"},"author":{"name":"Cindy Wooden, Catholic News Service","@id":"https:\/\/cnewa.org\/es\/#\/schema\/person\/d2935c46e239b59210c38997d4aedf00"},"headline":"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua","datePublished":"2025-12-03T18:46:56+00:00","dateModified":"2025-12-03T18:46:57+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/"},"wordCount":580,"publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/12\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg","articleSection":["Acompa\u00f1ando a las Iglesias locales","Promoviendo el Di\u00e1logo y la Unidad","Noticias","Oriente Cristiano"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/","url":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/","name":"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua | CNEWA Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/12\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg","datePublished":"2025-12-03T18:46:56+00:00","dateModified":"2025-12-03T18:46:57+00:00","description":"El Papa Le\u00f3n XIV tambi\u00e9n afirm\u00f3 haber abordado las guerras en curso en Gaza y Ucrania durante su reuni\u00f3n con el presidente de Turqu\u00eda.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/12\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2025\/12\/20251129T1115-POPE-ISTANBUL-PATRIARCH-1808639.jpg","width":1800,"height":1200,"caption":"El Papa Le\u00f3n XIV y el Patriarca Ecum\u00e9nico Bartolom\u00e9 de Constantinopla se entregan copias de una declaraci\u00f3n conjunta que firmaron el 29 de noviembre al final de un servicio de oraci\u00f3n en la Catedral Patriarcal de San Jorge en Estambul. (foto: CNS\/Lola Gomez)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/papa-y-patriarca-urgen-fecha-comun-para-la-pascua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Acompa\u00f1ando a las Iglesias locales","item":"https:\/\/cnewa.org\/es\/categoria\/acompanando-a-las-iglesias-locales\/"},{"@type":"ListItem","position":3,"name":"Papa y Patriarca Urgen Fecha Com\u00fan para la Pascua"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Cindy Wooden, Catholic News Service"}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/7507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/comments?post=7507"}],"version-history":[{"count":2,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/7507\/revisions"}],"predecessor-version":[{"id":7509,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/7507\/revisions\/7509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/7505"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=7507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/categories?post=7507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}