{"id":8035,"date":"2026-04-16T14:05:26","date_gmt":"2026-04-16T18:05:26","guid":{"rendered":"https:\/\/cnewa.org\/es\/?p=8035"},"modified":"2026-04-16T14:05:27","modified_gmt":"2026-04-16T18:05:27","slug":"el-cardenal-dolan-recibe-el-primer-premio-cnewa","status":"publish","type":"post","link":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/","title":{"rendered":"El Cardenal Dolan Recibe el Primer Premio CNEWA"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"h-los-miembros-de-la-junta-de-directivos-de-cnewa-se-reunieron-el-15-de-abril-con-un-gran-grupo-de-amigos-donantes-y-socios-en-el-hotel-kolbe-junto-al-historico-foro-de-roma-para-entregar-su-primer-premio-internacional-de-liderazgo-timothy-michael-dolan-al-arzobispo-emerito-de-nueva-york-y-expresidente-de-cnewa-timothy-michael-cardinal-dolan-nbsp\">Los miembros de la Junta de Directivos de CNEWA se reunieron el 15 de abril con un gran grupo de amigos, donantes y socios en el Hotel Kolbe, junto al hist\u00f3rico Foro de Roma, para entregar su primer Premio Internacional de Liderazgo Timothy Michael Dolan al arzobispo em\u00e9rito de Nueva York y expresidente de CNEWA, Timothy Michael Cardinal Dolan.&nbsp;<\/h2>\n\n\n\n<p>Hablando en nombre de la junta, la fideicomisaria Amanda Caroline Bowman agradeci\u00f3 al cardenal el regalo de su ministerio sacerdotal y episcopal, se\u00f1alando que este a\u00f1o se cumplen el 25\u00ba aniversario de su ordenaci\u00f3n episcopal y el 50\u00ba aniversario de su ordenaci\u00f3n como sacerdote.&nbsp;<\/p>\n\n\n\n<p>Pero prest\u00f3 especial atenci\u00f3n a su largo servicio a CNEWA, que comenz\u00f3 mucho antes de que asumiera el manto de esta agencia de sanaci\u00f3n y esperanza como su presidente en 2009, y c\u00f3mo su visi\u00f3n y ejercicio de liderazgo abrieron la oportunidad para que miembros del laicado, como ella y Marina C. Perna, se unieran a las filas de su junta internacional de directores, que hab\u00eda estado limitada a los miembros del episcopado.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"836\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_001H-1024x836.jpeg\" alt=\"Dos damas entregan un premio al cardenal Dolan mientras otro arzobispo observa.\" class=\"wp-image-8037\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_001H-1024x836.jpeg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_001H-300x245.jpeg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_001H-768x627.jpeg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_001H-1536x1254.jpeg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_001H-1600x1306.jpeg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_001H.jpeg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Amanda Bowman y Marina Perna, fideicomisarias de la Junta Directiva de CNEWA, entregan el premio al cardenal Dolan mientras el arzobispo Michel Jalakh observa. (foto: Michael J. La Civita)<\/figcaption><\/figure>\n\n\n\n<p>Al aceptar el premio, el cardenal agradeci\u00f3 a las se\u00f1oras Bowman y Perna y a toda la junta por su compromiso y servicio entusiasta.&nbsp;<\/p>\n\n\n\n<p>Tambi\u00e9n destac\u00f3 el liderazgo de Mons. Peter I. Vaccari como su presidente, destacando c\u00f3mo Mons. Vaccari ha posicionado h\u00e1bilmente a CNEWA \u2014 que ahora conmemora su centenario \u2014 forjando alianzas mientras responde a las crecientes necesidades de los pueblos atendidos por las iglesias orientales en \u00e1reas de conflicto intenso, enumerando los pa\u00edses donde CNEWA tiene el privilegio de servir:<\/p>\n\n\n\n<p>\u201cGaza, Israel, L\u00edbano, Siria, Etiop\u00eda, India, Ucrania, Armenia &#8230; \u00bfLes suena familiar, amigos?&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cnewa-esta-alli-sobre-el-terreno-siendo-uno-con-la-iglesia-y-el-pueblo-dijo-senalando-su-presencia-en-medio-del-conflicto-la-pobreza-y-la-persecucion-nbsp\">\u201cCNEWA est\u00e1 all\u00ed, sobre el terreno\u201d, siendo uno con la iglesia y el pueblo, dijo, se\u00f1alando su presencia en medio del conflicto, la pobreza y la persecuci\u00f3n.&nbsp;<\/h3>\n\n\n\n<p>El cardenal record\u00f3 que su introducci\u00f3n a CNEWA data de sus a\u00f1os al servicio del cardenal P\u00edo Laghi, quien de 1984 a 1990 fue pro-nuncio de la Santa Sede en Estados Unidos en Washington, D.C., \u201cquien amaba, amaba, amaba a CNEWA, conociendo bien su labor en Tierra Santa cuando sirvi\u00f3 all\u00ed como delegado del Santo Padre en Jerusal\u00e9n\u201d.<\/p>\n\n\n\n<p>\u201cEn aquel momento\u201d, a\u00f1adi\u00f3 el cardenal, \u201cCNEWA estaba dirigida por un personaje, Monse\u00f1or John Gavin Nolan&#8230; y cuando les digo que era un personaje, ya saben a qu\u00e9 me refiero con un personaje&#8230;\u00bb<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"855\" src=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_008H-1024x855.jpeg\" alt=\"\" class=\"wp-image-8036\" srcset=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_008H-1024x855.jpeg 1024w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_008H-300x251.jpeg 300w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_008H-768x641.jpeg 768w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_008H-1536x1283.jpeg 1536w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_008H-1600x1336.jpeg 1600w, https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_008H.jpeg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cardenal Dolan y miembros del equipo CNEWA cortaron el pastel del centenario de CNEWA. (foto: Michael J. La Civita)<\/figcaption><\/figure>\n\n\n\n<p>\u201cAhora, cuando los rehenes estadounidenses en Teher\u00e1n estaban siendo liberados, \u00bfqui\u00e9n fue la primera persona que estuvo all\u00ed para verlos y estar con ellos? John Gavin Nolan, de CNEWA\u201d, dijo, enfatizando el papel discreto pero eficaz que CNEWA ha desempe\u00f1ado en la vida de la iglesia en el Medio Oriente, el noreste de \u00c1frica, India y Europa del Este.&nbsp;<\/p>\n\n\n\n<p>Entre los distinguidos invitados que asistieron a la recepci\u00f3n y la cena, que concluy\u00f3 con el corte del pastel para celebrar el centenario de la CNEWA, se encontraban el pr\u00edncipe y gran maestre de la Soberana Orden Militar de Malta, Fra John T. Dunlap; la hermana Raffaella Petrini, FSE, presidenta de la Comisi\u00f3n Pontificia y gobernaci\u00f3n del Estado de la Ciudad del Vaticano; el patriarca cat\u00f3lico armenio de Cilicia, Rafael Bedros XXI Minassiano; el embajador de EE.UU. ante la Santa Sede, Brian F. Burch, y su esposa Sara; el caballero supremo de los Caballeros de Col\u00f3n, Patrick E. Kelly, y su esposa Vanessa; los cardenales Raymond Leo Burke, James Michael Harvey y Edwin F. O&#8217;Brien; y el secretario del Dicasterio para las Iglesias Orientales, el arzobispo Michel Jalakh, O.A.M.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CNEWA entrega su primer Premio Internacional de Liderazgo Timothy Michael Cardinal Dolan al arzobispo em\u00e9rito de Nueva York y expresidente de CNEWA, Timothy Michael Cardinal Dolan. <\/p>\n","protected":false},"author":70019,"featured_media":8038,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1117,3,7],"class_list":["post-8035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peregrinos-de-sanacion-y-esperanza","category-noticias","category-conexiones-cnewa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Cardenal Dolan Recibe el Primer Premio CNEWA | CNEWA Espa\u00f1ol<\/title>\n<meta name=\"description\" content=\"CNEWA entrega su primer Premio Internacional de Liderazgo Timothy Michael Cardinal Dolan al arzobispo em\u00e9rito de Nueva York, Timothy Dolan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Cardenal Dolan Recibe el Primer Premio CNEWA\" \/>\n<meta property=\"og:description\" content=\"CNEWA entrega su primer Premio Internacional de Liderazgo Timothy Michael Cardinal Dolan al arzobispo em\u00e9rito de Nueva York, Timothy Dolan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CNEWAenespanol\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T18:05:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T18:05:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_007H.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael J. La Civita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David R. Aquije\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/\"},\"author\":{\"name\":\"Michael J. La Civita\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/person\\\/d2935c46e239b59210c38997d4aedf00\"},\"headline\":\"El Cardenal Dolan Recibe el Primer Premio CNEWA\",\"datePublished\":\"2026-04-16T18:05:26+00:00\",\"dateModified\":\"2026-04-16T18:05:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/\"},\"wordCount\":674,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/lacivita202604_007H.jpeg\",\"articleSection\":[\"Peregrinos de Sanaci\u00f3n y Esperanza\",\"Noticias\",\"Conexiones CNEWA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/\",\"name\":\"El Cardenal Dolan Recibe el Primer Premio CNEWA | CNEWA Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/lacivita202604_007H.jpeg\",\"datePublished\":\"2026-04-16T18:05:26+00:00\",\"dateModified\":\"2026-04-16T18:05:27+00:00\",\"description\":\"CNEWA entrega su primer Premio Internacional de Liderazgo Timothy Michael Cardinal Dolan al arzobispo em\u00e9rito de Nueva York, Timothy Dolan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/lacivita202604_007H.jpeg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/04\\\/lacivita202604_007H.jpeg\",\"width\":1800,\"height\":1350,\"caption\":\"Monse\u00f1or Peter I. Vaccari, Maria C. Perna, el Cardenal Timothy Dolan, la hermana Raffaella Petrini, Amanda Bowman, Patrick E. Kelly y su esposa Vanessa, y el Fra John T. Dunlap, gran maestre de la Soberana Orden Militar de Malta, en la inauguraci\u00f3n del Premio Internacional de Liderazgo Timothy Michael Dolan de CNEWA. (foto: Michael J. La Civita)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peregrinos de Sanaci\u00f3n y Esperanza\",\"item\":\"https:\\\/\\\/cnewa.org\\\/es\\\/categoria\\\/peregrinos-de-sanacion-y-esperanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Cardenal Dolan Recibe el Primer Premio CNEWA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"name\":\"CNEWA Espa\u00f1ol\",\"description\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#organization\",\"name\":\"CNEWA Espa\u00f1ol\",\"alternateName\":\"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/07\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CNEWAenespanol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Michael J. La Civita\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Cardenal Dolan Recibe el Primer Premio CNEWA | CNEWA Espa\u00f1ol","description":"CNEWA entrega su primer Premio Internacional de Liderazgo Timothy Michael Cardinal Dolan al arzobispo em\u00e9rito de Nueva York, Timothy Dolan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/","og_locale":"es_ES","og_type":"article","og_title":"El Cardenal Dolan Recibe el Primer Premio CNEWA","og_description":"CNEWA entrega su primer Premio Internacional de Liderazgo Timothy Michael Cardinal Dolan al arzobispo em\u00e9rito de Nueva York, Timothy Dolan.","og_url":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/","og_site_name":"CNEWA Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/CNEWAenespanol\/","article_published_time":"2026-04-16T18:05:26+00:00","article_modified_time":"2026-04-16T18:05:27+00:00","og_image":[{"width":1800,"height":1350,"url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_007H.jpeg","type":"image\/jpeg"}],"author":"Michael J. La Civita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"David R. Aquije","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/"},"author":{"name":"Michael J. La Civita","@id":"https:\/\/cnewa.org\/es\/#\/schema\/person\/d2935c46e239b59210c38997d4aedf00"},"headline":"El Cardenal Dolan Recibe el Primer Premio CNEWA","datePublished":"2026-04-16T18:05:26+00:00","dateModified":"2026-04-16T18:05:27+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/"},"wordCount":674,"commentCount":0,"publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_007H.jpeg","articleSection":["Peregrinos de Sanaci\u00f3n y Esperanza","Noticias","Conexiones CNEWA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/","url":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/","name":"El Cardenal Dolan Recibe el Primer Premio CNEWA | CNEWA Espa\u00f1ol","isPartOf":{"@id":"https:\/\/cnewa.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_007H.jpeg","datePublished":"2026-04-16T18:05:26+00:00","dateModified":"2026-04-16T18:05:27+00:00","description":"CNEWA entrega su primer Premio Internacional de Liderazgo Timothy Michael Cardinal Dolan al arzobispo em\u00e9rito de Nueva York, Timothy Dolan.","breadcrumb":{"@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#primaryimage","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_007H.jpeg","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2026\/04\/lacivita202604_007H.jpeg","width":1800,"height":1350,"caption":"Monse\u00f1or Peter I. Vaccari, Maria C. Perna, el Cardenal Timothy Dolan, la hermana Raffaella Petrini, Amanda Bowman, Patrick E. Kelly y su esposa Vanessa, y el Fra John T. Dunlap, gran maestre de la Soberana Orden Militar de Malta, en la inauguraci\u00f3n del Premio Internacional de Liderazgo Timothy Michael Dolan de CNEWA. (foto: Michael J. La Civita)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/es\/el-cardenal-dolan-recibe-el-primer-premio-cnewa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cnewa.org\/es\/"},{"@type":"ListItem","position":2,"name":"Peregrinos de Sanaci\u00f3n y Esperanza","item":"https:\/\/cnewa.org\/es\/categoria\/peregrinos-de-sanacion-y-esperanza\/"},{"@type":"ListItem","position":3,"name":"El Cardenal Dolan Recibe el Primer Premio CNEWA"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/es\/#website","url":"https:\/\/cnewa.org\/es\/","name":"CNEWA Espa\u00f1ol","description":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","publisher":{"@id":"https:\/\/cnewa.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/es\/#organization","name":"CNEWA Espa\u00f1ol","alternateName":"Asociaci\u00f3n Cat\u00f3lica para el Bienestar del Cercano Oriente","url":"https:\/\/cnewa.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/es\/wp-content\/uploads\/sites\/5\/2021\/07\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Espa\u00f1ol"},"image":{"@id":"https:\/\/cnewa.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CNEWAenespanol\/","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Michael J. La Civita"}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/8035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/users\/70019"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/comments?post=8035"}],"version-history":[{"count":2,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/8035\/revisions"}],"predecessor-version":[{"id":8040,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/posts\/8035\/revisions\/8040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media\/8038"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/media?parent=8035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/es\/wp-json\/wp\/v2\/categories?post=8035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}