{"id":1614,"date":"2023-10-20T15:41:57","date_gmt":"2023-10-20T19:41:57","guid":{"rendered":"https:\/\/cnewa.org\/fr\/?post_type=campaigns&#038;p=1614"},"modified":"2026-07-08T15:18:56","modified_gmt":"2026-07-08T19:18:56","slug":"terre-sainte","status":"publish","type":"campaigns","link":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/","title":{"rendered":"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte"},"content":{"rendered":"\n<h2 id=\"h-il-n-y-a-pas-de-lieux-surs-a-gaza-jusqu-a-60-000-personnes-dont-un-grand-nombre-d-enfants-de-femmes-et-de-personnes-agees-ont-deja-peri-dans-ce-conflit\" class=\"wp-block-heading\">Il n\u2019y a pas de lieux s\u00fbrs \u00e0 Gaza. Jusqu&rsquo;\u00e0 60 000 personnes \u2013 dont un grand nombre d&rsquo;enfants, de femmes et de personnes \u00e2g\u00e9es \u2013 ont d\u00e9j\u00e0 p\u00e9ri dans ce conflit.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il n\u2019y a pas de lieux s\u00fbrs \u00e0 Gaza. Jusqu&rsquo;\u00e0 60 000 personnes \u2013 dont un grand nombre d&rsquo;enfants, de femmes et de personnes \u00e2g\u00e9es \u2013 ont d\u00e9j\u00e0 p\u00e9ri dans ce conflit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il n\u2019y a aucun endroit s\u00e9curitaire o\u00f9 les familles peuvent se r\u00e9fugier lorsqu\u2019il y a une attaque de missiles, pas m\u00eame dans les \u00e9glises. Malgr\u00e9 cela, des centaines de personnes se sont regroup\u00e9es dans l&rsquo;enceinte de l&rsquo;\u00e9glise de la Sainte-Famille, la seule paroisse catholique de Gaza et quelque 150 autres familles se sont r\u00e9fugi\u00e9es dans l&rsquo;ancienne paroisse orthodoxe de Saint-Porphyrios. Cette derni\u00e8re a \u00e9t\u00e9 bombard\u00e9e au d\u00e9but du conflit entre Isra\u00ebl et le Hamas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>90 % des 2,1 millions d\u2019habitants de Gaza <\/strong>ont \u00e9t\u00e9 d\u00e9plac\u00e9s, sont sans abri et vivent dans des conditions pr\u00e9caires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La malnutrition et la famine sont end\u00e9miques. La maladie aussi. Le manque de nourriture et d&rsquo;eau potable a des r\u00e9percussions sur <strong>tout le monde<\/strong>. La plupart des gens, y compris les enfants, s&rsquo;accrochent \u00e0 la vie et peinent \u00e0 survivre avec moins d&rsquo;un repas par jour.<\/p>\n\n\n<div class=\"mcrm-form-wrap mcrm-acf-block\">\n      <div class=\"right-country-wrap ca-version\">\n      <h3>\u00c0 nos amis \u00e0 l\u2019ext\u00e9rieur du Canada :<\/h3>\n      <p>Veuillez <a class=\"inline\" href=\"\/donate\">visiter CNEWA.org<\/a> <br>pour faire votre don.<\/p>\n      <p><a id=\"us-res\" href=\"\/donate\">FAITES UN DON VIA CNEWA.ORG<\/a><\/p>\n      <p><a id=\"us-res-flag\" href=\"\/donate\">FAITES UN DON VIA CNEWA.ORG<\/a><\/p>\n      <hr>\n      <p>Si vous habitez au Canada, <br><strong><a class=\"ca-anyway\">Cliquez ci-dessous pour continuer<\/a><\/strong>.<\/p>\n      <p><a id=\"ca-res\" class=\"ca-anyway\">Mon adresse principale est au Canada<\/a><\/p>\n    <\/div>\n  <iframe loading=\"lazy\" id=\"mcrmIframe\" src=\"https:\/\/secure.cnewa.org\/Donation\/CA-FR-wwd-terre-sainte\/\" height=\"800\" width=\"100%\"><\/iframe><\/div>\n\n\n<p class=\"wp-block-paragraph\">Gaza est en ruine et la vie de ses habitants, dont la plupart sont tr\u00e8s pauvres, a \u00e9t\u00e9 boulevers\u00e9e \u00e0 jamais. La communaut\u00e9 chr\u00e9tienne de Gaza est minuscule mais elle n&rsquo;a pas \u00e9t\u00e9 \u00e9pargn\u00e9e des horreurs de la violence et de la vengeance. L&rsquo;\u00c9vangile pousse les croyants \u00e0 r\u00e9agir, et c&rsquo;est pr\u00e9cis\u00e9ment ce que font les chr\u00e9tiens de Gaza. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nous vous invitons \u00e0 appuyer les efforts de CNEWA-Mission pontificale qui cherche \u00e0 aider l&rsquo;\u00c9glise de Gaza \u00e0 r\u00e9pondre aux besoins de la communaut\u00e9. <\/strong>En collaboration avec le Conseil des \u00c9glises du Proche-Orient, CNEWA-Mission pontificale distribue des l\u00e9gumes frais dans les deux paroisses chr\u00e9tiennes, ainsi qu&rsquo;\u00e0 des personnes qui ont perdues leurs familles et qui se retrouvent seules. CNEWA-Mission pontificale soutient depuis longtemps l&rsquo;h\u00f4pital Al-Ahli Arab et, depuis janvier, s&rsquo;est associ\u00e9 \u00e0 lui pour fournir des services m\u00e9dicaux d&rsquo;urgence. Votre don nous permettra d&rsquo;acheter un plus grand nombre de paniers alimentaires, de bouteilles d&rsquo;eau potable et de fournir des soins aux malades, aux personnes sous-aliment\u00e9es et aux bless\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3AJADFM-111-1024x683.jpg\" alt=\"Un gar\u00e7on va chercher de l'eau dans un camp du nord de Gaza, au milieu des d\u00e9combres.\" class=\"wp-image-2368\" srcset=\"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3AJADFM-111-1024x683.jpg 1024w, https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3AJADFM-111-300x200.jpg 300w, https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3AJADFM-111-768x512.jpg 768w, https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3AJADFM-111-1536x1024.jpg 1536w, https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3AJADFM-111-1600x1067.jpg 1600w, https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3AJADFM-111.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Un gar\u00e7on va chercher de l&rsquo;eau dans un camp au nord de Gaza, le 10 avril 2025. (photo : Mahmoud Zaki\/Xinhua\/Alamy Stock Photo)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab De la bande de Gaza, s&rsquo;\u00e9l\u00e8vent toujours plus intenses vers le ciel les cris des m\u00e8res, des p\u00e8res qui serrent les corps sans vie de leurs enfants et qui sont continuellement oblig\u00e9s de se d\u00e9placer \u00e0 la recherche d&rsquo;un peu de nourriture et d&rsquo;un abri plus s\u00fbr contre les bombardements \u00bb, nous dit le pape L\u00e9on XlV lors de son Audience g\u00e9n\u00e9rale du 28 mai 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et le Pape ajoute<strong>&nbsp;: \u00ab Aux responsables, je renouvelle mon appel : cessez le feu ; lib\u00e9rez tous les otages et respectez int\u00e9gralement le droit humanitaire. \u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que membres de l&rsquo;\u00c9glise universelle, en tant que b\u00e2tisseurs de ponts et d\u00e9fenseurs de la paix, nous sommes unis dans notre d\u00e9sir de soutenir la dignit\u00e9 de toute vie humaine. Merci de nous aider et de collaborer \u00e0 notre mission. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S.V.P. nous faire parvenir votre don d\u00e8s maintenant.<\/strong><\/p>\n","protected":false},"featured_media":2366,"template":"","work-category":[442],"class_list":["post-1614","campaigns","type-campaigns","status-publish","has-post-thumbnail","hentry","work-category-secours-durgence"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte | CNEWA Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte\" \/>\n<meta property=\"og:description\" content=\"Il n\u2019y a pas de lieux s\u00fbrs \u00e0 Gaza. Jusqu&rsquo;\u00e0 60 000 personnes \u2013 dont un grand nombre d&rsquo;enfants, de femmes et de personnes \u00e2g\u00e9es \u2013 ont d\u00e9j\u00e0 p\u00e9ri dans ce conflit. Il n\u2019y a pas de lieux s\u00fbrs \u00e0 Gaza. Jusqu&rsquo;\u00e0 60 000 personnes \u2013 dont un grand nombre d&rsquo;enfants, de femmes et de &hellip; Continued\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cnewacanada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T19:18:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3BFMY97-AI11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cnewac\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/\",\"name\":\"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte | CNEWA Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/06\\\/3BFMY97-AI11.jpg\",\"datePublished\":\"2023-10-20T19:41:57+00:00\",\"dateModified\":\"2026-07-08T19:18:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/06\\\/3BFMY97-AI11.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/06\\\/3BFMY97-AI11.jpg\",\"width\":1800,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/terre-sainte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campaigns\",\"item\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/notre-travail\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\",\"name\":\"CNEWA Canada\",\"description\":\"Association catholique d\u2019aide \u00e0 l\u2019Orient\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\",\"name\":\"CNEWA Canada\",\"alternateName\":\"Association catholique d\u2019aide \u00e0 l\u2019Orient\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cnewacanada\\\/\",\"https:\\\/\\\/x.com\\\/cnewac\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte | CNEWA Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/","og_locale":"fr_CA","og_type":"article","og_title":"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte","og_description":"Il n\u2019y a pas de lieux s\u00fbrs \u00e0 Gaza. Jusqu&rsquo;\u00e0 60 000 personnes \u2013 dont un grand nombre d&rsquo;enfants, de femmes et de personnes \u00e2g\u00e9es \u2013 ont d\u00e9j\u00e0 p\u00e9ri dans ce conflit. Il n\u2019y a pas de lieux s\u00fbrs \u00e0 Gaza. Jusqu&rsquo;\u00e0 60 000 personnes \u2013 dont un grand nombre d&rsquo;enfants, de femmes et de &hellip; Continued","og_site_name":"CNEWA Canada","article_publisher":"https:\/\/www.facebook.com\/cnewacanada\/","article_modified_time":"2026-07-08T19:18:56+00:00","og_image":[{"width":1800,"height":1500,"url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3BFMY97-AI11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cnewac","twitter_misc":{"Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/","url":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/","name":"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte | CNEWA Canada","isPartOf":{"@id":"https:\/\/cnewa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3BFMY97-AI11.jpg","datePublished":"2023-10-20T19:41:57+00:00","dateModified":"2026-07-08T19:18:56+00:00","breadcrumb":{"@id":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/#primaryimage","url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3BFMY97-AI11.jpg","contentUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2025\/06\/3BFMY97-AI11.jpg","width":1800,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/fr\/notre-travail\/terre-sainte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cnewa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Campaigns","item":"https:\/\/cnewa.org\/fr\/notre-travail\/"},{"@type":"ListItem","position":3,"name":"Aidez-nous \u00e0 apporter une aide d\u2019urgence en Terre Sainte"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/fr\/#website","url":"https:\/\/cnewa.org\/fr\/","name":"CNEWA Canada","description":"Association catholique d\u2019aide \u00e0 l\u2019Orient","publisher":{"@id":"https:\/\/cnewa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/fr\/#organization","name":"CNEWA Canada","alternateName":"Association catholique d\u2019aide \u00e0 l\u2019Orient","url":"https:\/\/cnewa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cnewa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2019\/11\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2019\/11\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Canada"},"image":{"@id":"https:\/\/cnewa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cnewacanada\/","https:\/\/x.com\/cnewac","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/campaigns\/1614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/campaigns"}],"about":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/types\/campaigns"}],"version-history":[{"count":5,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/campaigns\/1614\/revisions"}],"predecessor-version":[{"id":3161,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/campaigns\/1614\/revisions\/3161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/media\/2366"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/media?parent=1614"}],"wp:term":[{"taxonomy":"work-category","embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/work-category?post=1614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}