{"id":1021,"date":"2022-06-30T10:03:16","date_gmt":"2022-06-30T14:03:16","guid":{"rendered":"https:\/\/cnewa.org\/fr\/?p=1021"},"modified":"2022-06-30T10:03:16","modified_gmt":"2022-06-30T14:03:16","slug":"cnewa-lance-une-campagne-de-soutien-pour-lethiopie","status":"publish","type":"post","link":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/","title":{"rendered":"CNEWA lance une campagne de soutien pour l&rsquo;\u00c9thiopie"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-d-innombrables-histoires-tristes-et-bouleversantes-poussent-l-agence-a-agir\">D&rsquo;innombrables histoires tristes et bouleversantes poussent l&rsquo;agence \u00e0 agir.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ottawa, le 29 juin 2022 \u2014 <\/strong>CNEWA lance une campagne de soutien afin que l&rsquo;aide humanitaire parvienne rapidement \u00e0 la population \u00e9thiopienne, de plus en plus vuln\u00e9rable.&nbsp; &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les prix des c\u00e9r\u00e9ales, de l&rsquo;huile de cuisson et d&rsquo;autres produits de premi\u00e8re n\u00e9cessit\u00e9 s&rsquo;envolent alors que les \u00c9thiopiens sont confront\u00e9s \u00e0 une s\u00e9cheresse persistante, exacerb\u00e9e par les violences interethniques qui ont s\u00e9vi dans les provinces du nord du pays l&rsquo;ann\u00e9e derni\u00e8re ainsi qu&rsquo;\u00e0 des p\u00e9nuries dues \u00e0 la guerre entre la Russie et l&rsquo;Ukraine. Selon les Nations unies, la Russie et l&rsquo;Ukraine fournissent environ 40 % des importations de c\u00e9r\u00e9ales de l&rsquo;Afrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la r\u00e9gion du Tigr\u00e9 en \u00c9thiopie, o\u00f9 CNEWA concentrera ses fonds, les \u00e9coles et les banques sont toujours ferm\u00e9es, limitant l&rsquo;acc\u00e8s \u00e0 l&rsquo;argent et aux services. Certains rapportent que des entreprises ont cess\u00e9 leurs activit\u00e9s en raison de la flamb\u00e9e des prix du carburant. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ce d\u00e9but de campagne, l&rsquo;\u00e9quipe de CNEWA esp\u00e8re que les Canadiens et Canadiennes de tout le pays r\u00e9pondront \u00e0 son appel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous sommes tr\u00e8s pr\u00e9occup\u00e9s par la situation critique des \u00c9thiopiens, a d\u00e9clar\u00e9 Judith Poitevien, directrice nationale int\u00e9rimaire du bureau de CNEWA \u00e0 Ottawa. Nous esp\u00e9rons que les Canadiens r\u00e9pondront g\u00e9n\u00e9reusement, comme ils l&rsquo;ont fait lors de notre appel pour l&rsquo;Ukraine. Avec le soutien de nos nombreux donateurs et amis, nous avons bon espoir de pouvoir aider \u00e0 servir et \u00e0 soutenir ceux qui sont dans le besoin en \u00c9thiopie. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce pays d&rsquo;Afrique de l&rsquo;Est lutte depuis le milieu des ann\u00e9es 1980 contre les changements environnementaux, la s\u00e9cheresse, la guerre, la r\u00e9volution et les troubles civils. Apr\u00e8s un certain nombre d&rsquo;ann\u00e9es de stabilit\u00e9 relative et de croissance \u00e9conomique, la violence interethnique a d\u00e9chir\u00e9 le pays, surtout dans les provinces du nord. Des maisons, des lieux de culte et des \u00e9coles ont \u00e9t\u00e9 pill\u00e9s et lourdement endommag\u00e9s. Les informations font \u00e9tat de familles vivant dans la peur de l&rsquo;inconnu, confront\u00e9es \u00e0 la faim et \u00e0 la violence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les partenaires de CNEWA en \u00c9thiopie continuent de plaider pour les personnes les plus vuln\u00e9rables, en particulier les enfants, les m\u00e8res allaitantes et les personnes \u00e2g\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Si nous survivons, ce sera avec gratitude pour l&rsquo;aide que vous nous apportez \u00bb, a d\u00e9clar\u00e9 l&rsquo;\u00e9v\u00eaque Medhin d&rsquo;Adigrat, en \u00c9thiopie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vos dons peuvent \u00eatre faits en ligne \u00e0 cnewa.ca ou par t\u00e9l\u00e9phone au 1-866-322-4441. Les ch\u00e8ques peuvent \u00eatre post\u00e9s \u00e0 CNEWA au 223 Main Street, Ottawa, ON K1S 1C4, avec la mention \u00ab \u00c9thiopie \u00bb. Des re\u00e7us fiscaux seront \u00e9mis pour les dons de 10 $ ou plus.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour en savoir plus sur les efforts de CNEWA en \u00c9thiopie, visitez <a href=\"http:\/\/www.cnewa.ca\/fr\">cnewa.ca\/fr<\/a> ou suivez-nous sur Facebook (@CNEWACanada).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos de CNEWA Canada<br><\/strong>Agence du Saint-Si\u00e8ge, l\u2019Association catholique d\u2019aide \u00e0 l\u2019Orient (CNEWA) travaille pour, par et avec les \u00c9glises catholiques orientales au Moyen-Orient, au nord-est de l\u2019Afrique, en Inde et en Europe de l\u2019Est. Mandat\u00e9e par le pape Pie XI en 1926, CNEWA apporte un soutien pastoral et humanitaire aux \u00c9glises et aux peuples de l&rsquo;Orient. CNEWA Canada est enregistr\u00e9e depuis 2003 comme organisme de charit\u00e9 aupr\u00e8s de l\u2019Agence du revenu du Canada. Pour plus de renseignements, visitez <a href=\"http:\/\/www.cnewa.ca\/fr\">cnewa.ca\/fr<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D&rsquo;innombrables histoires tristes et bouleversantes poussent l&rsquo;agence \u00e0 agir. Ottawa, le 29 juin 2022 \u2014 CNEWA lance une campagne de soutien afin que l&rsquo;aide humanitaire parvienne rapidement \u00e0 la population \u00e9thiopienne, de plus en plus vuln\u00e9rable.&nbsp; &nbsp;&nbsp; Les prix des c\u00e9r\u00e9ales, de l&rsquo;huile de cuisson et d&rsquo;autres produits de premi\u00e8re n\u00e9cessit\u00e9 s&rsquo;envolent alors que les &hellip; <a href=\"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/\">Continued<\/a><\/p>\n","protected":false},"author":61,"featured_media":1022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[397,399],"class_list":["post-1021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ethiopie","category-communiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CNEWA lance une campagne de soutien pour l&#039;\u00c9thiopie | CNEWA Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNEWA lance une campagne de soutien pour l&#039;\u00c9thiopie\" \/>\n<meta property=\"og:description\" content=\"D&rsquo;innombrables histoires tristes et bouleversantes poussent l&rsquo;agence \u00e0 agir. Ottawa, le 29 juin 2022 \u2014 CNEWA lance une campagne de soutien afin que l&rsquo;aide humanitaire parvienne rapidement \u00e0 la population \u00e9thiopienne, de plus en plus vuln\u00e9rable.&nbsp; &nbsp;&nbsp; Les prix des c\u00e9r\u00e9ales, de l&rsquo;huile de cuisson et d&rsquo;autres produits de premi\u00e8re n\u00e9cessit\u00e9 s&rsquo;envolent alors que les &hellip; Continued\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cnewacanada\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T14:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2022\/06\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CNEWA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cnewac\" \/>\n<meta name=\"twitter:site\" content=\"@cnewac\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CNEWA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/\"},\"author\":{\"name\":\"CNEWA\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/person\\\/7944644ca6eb0740b984679ea893bd81\"},\"headline\":\"CNEWA lance une campagne de soutien pour l&rsquo;\u00c9thiopie\",\"datePublished\":\"2022-06-30T14:03:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/\"},\"wordCount\":605,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg\",\"articleSection\":[\"\u00c9thiopie\",\"Communiqu\u00e9s\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/\",\"name\":\"CNEWA lance une campagne de soutien pour l'\u00c9thiopie | CNEWA Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg\",\"datePublished\":\"2022-06-30T14:03:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg\",\"width\":1800,\"height\":1260,\"caption\":\"Febedu Mehari sert un repas d'injera et un plat de pois cass\u00e9s jaunes \u00e0 ses enfants \u00e0 Hadush Emba, en \u00c9thiopie, le 7 f\u00e9vrier 2019. L'\u00c9glise en \u00c9thiopie m\u00e8ne des efforts de paix et de r\u00e9conciliation et s'efforce d'aider les millions de personnes qui ont fui leurs foyers apr\u00e8s une recrudescence de la violence communautaire. (CNS Photo\\\/Will Baxter, Catholic Relief Services)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNEWA lance une campagne de soutien pour l&#8217;\u00c9thiopie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\",\"name\":\"CNEWA Canada\",\"description\":\"Association catholique d\u2019aide \u00e0 l\u2019Orient\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\",\"name\":\"CNEWA Canada\",\"alternateName\":\"Association catholique d\u2019aide \u00e0 l\u2019Orient\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cnewacanada\\\/\",\"https:\\\/\\\/x.com\\\/cnewac\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"CNEWA\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CNEWA lance une campagne de soutien pour l'\u00c9thiopie | CNEWA Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/","og_locale":"fr_CA","og_type":"article","og_title":"CNEWA lance une campagne de soutien pour l'\u00c9thiopie","og_description":"D&rsquo;innombrables histoires tristes et bouleversantes poussent l&rsquo;agence \u00e0 agir. Ottawa, le 29 juin 2022 \u2014 CNEWA lance une campagne de soutien afin que l&rsquo;aide humanitaire parvienne rapidement \u00e0 la population \u00e9thiopienne, de plus en plus vuln\u00e9rable.&nbsp; &nbsp;&nbsp; Les prix des c\u00e9r\u00e9ales, de l&rsquo;huile de cuisson et d&rsquo;autres produits de premi\u00e8re n\u00e9cessit\u00e9 s&rsquo;envolent alors que les &hellip; Continued","og_site_name":"CNEWA Canada","article_publisher":"https:\/\/www.facebook.com\/cnewacanada\/","article_published_time":"2022-06-30T14:03:16+00:00","og_image":[{"width":1800,"height":1260,"url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2022\/06\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg","type":"image\/jpeg"}],"author":"CNEWA","twitter_card":"summary_large_image","twitter_creator":"@cnewac","twitter_site":"@cnewac","twitter_misc":{"\u00c9crit par":"CNEWA","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/"},"author":{"name":"CNEWA","@id":"https:\/\/cnewa.org\/fr\/#\/schema\/person\/7944644ca6eb0740b984679ea893bd81"},"headline":"CNEWA lance une campagne de soutien pour l&rsquo;\u00c9thiopie","datePublished":"2022-06-30T14:03:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/"},"wordCount":605,"publisher":{"@id":"https:\/\/cnewa.org\/fr\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2022\/06\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg","articleSection":["\u00c9thiopie","Communiqu\u00e9s"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/","url":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/","name":"CNEWA lance une campagne de soutien pour l'\u00c9thiopie | CNEWA Canada","isPartOf":{"@id":"https:\/\/cnewa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2022\/06\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg","datePublished":"2022-06-30T14:03:16+00:00","breadcrumb":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/#primaryimage","url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2022\/06\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg","contentUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2022\/06\/20210923T1432-FAITH-ALIVE-37-1-1508920-1800x1260px.jpg","width":1800,"height":1260,"caption":"Febedu Mehari sert un repas d'injera et un plat de pois cass\u00e9s jaunes \u00e0 ses enfants \u00e0 Hadush Emba, en \u00c9thiopie, le 7 f\u00e9vrier 2019. L'\u00c9glise en \u00c9thiopie m\u00e8ne des efforts de paix et de r\u00e9conciliation et s'efforce d'aider les millions de personnes qui ont fui leurs foyers apr\u00e8s une recrudescence de la violence communautaire. (CNS Photo\/Will Baxter, Catholic Relief Services)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/fr\/cnewa-lance-une-campagne-de-soutien-pour-lethiopie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cnewa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"CNEWA lance une campagne de soutien pour l&#8217;\u00c9thiopie"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/fr\/#website","url":"https:\/\/cnewa.org\/fr\/","name":"CNEWA Canada","description":"Association catholique d\u2019aide \u00e0 l\u2019Orient","publisher":{"@id":"https:\/\/cnewa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/fr\/#organization","name":"CNEWA Canada","alternateName":"Association catholique d\u2019aide \u00e0 l\u2019Orient","url":"https:\/\/cnewa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cnewa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2019\/11\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2019\/11\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Canada"},"image":{"@id":"https:\/\/cnewa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cnewacanada\/","https:\/\/x.com\/cnewac","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"CNEWA"}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts\/1021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/comments?post=1021"}],"version-history":[{"count":1,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts\/1021\/revisions"}],"predecessor-version":[{"id":1023,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts\/1021\/revisions\/1023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/media\/1022"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/media?parent=1021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/categories?post=1021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}