{"id":1372,"date":"2023-07-04T13:45:19","date_gmt":"2023-07-04T17:45:19","guid":{"rendered":"https:\/\/cnewa.org\/fr\/?p=1372"},"modified":"2023-07-04T15:05:03","modified_gmt":"2023-07-04T19:05:03","slug":"cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine","status":"publish","type":"post","link":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/","title":{"rendered":"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En juin dernier, le pr\u00e9sident de CNEWA, Mgr Peter Vaccari, notre charg\u00e9e de projet pour l&rsquo;Ukraine, Anna Dombrovska, et moi-m\u00eame nous sommes rendus dans l&rsquo;ouest de l&rsquo;Ukraine afin de visiter les diff\u00e9rents programmes auxquels nous apportons notre soutien. Depuis f\u00e9vrier 2022, gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 de nos donateurs canadiens, CNEWA a jou\u00e9 un r\u00f4le de premier plan dans l&rsquo;aide aux Ukrainiens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e8s notre arriv\u00e9e, j&rsquo;ai remarqu\u00e9 que la guerre \u00e9tait bien perceptible. Tous les jours, des sir\u00e8nes d&rsquo;alerte a\u00e9rienne nous incitaient \u00e0 nous mettre \u00e0 l&rsquo;abri. Apr\u00e8s quelques heures nous pouvions reprendre nos activit\u00e9s. Malgr\u00e9 les nombreuses contraintes exerc\u00e9es sur les civils par la guerre, nous avons pu constater que les Ukrainiens faisaient preuve de r\u00e9silience et de d\u00e9termination \u00e0 vivre dans la paix et la stabilit\u00e9. Ils croient en la fin prochaine de la guerre et cultivent la solidarit\u00e9 et l&rsquo;espoir. Des millions de personnes, y compris des Canadiens, ont continu\u00e9 \u00e0 penser \u00e0 eux et \u00e0 les soutenir pendant cette p\u00e9riode difficile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons \u00e9t\u00e9 t\u00e9moins d&rsquo;un incroyable esprit de solidarit\u00e9 en visitant les projets soutenus par notre agence papale. Nous avons \u00e9t\u00e9 touch\u00e9s de voir des b\u00e9n\u00e9voles emballer des bo\u00eetes de nourriture pour les personnes d\u00e9plac\u00e9es, des chauffeurs risquer leur vie afin de distribuer des produits de premi\u00e8re n\u00e9cessit\u00e9 \u00e0 ceux qui ont des besoins criants, des fr\u00e8res religieux transformer un monast\u00e8re en un refuge s\u00e9curitaire pour les personnes d\u00e9plac\u00e9es \u00e0 l&rsquo;int\u00e9rieur du pays, et des religieuses offrir \u00e0 de jeunes orphelins un espace chaleureux et accueillant o\u00f9 poursuivre leurs \u00e9tudes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;Universit\u00e9 catholique ukrainienne a converti des salles de classe en refuges et a appris \u00e0 s&rsquo;adapter afin de pouvoir continuer \u00e0 pr\u00e9parer les \u00e9tudiants \u00e0 exercer leur minist\u00e8re aupr\u00e8s de ceux qui \u00e9prouvent des difficult\u00e9s. Enfin, nous avons pass\u00e9 du temps \u00e0 l&rsquo;h\u00f4pital Sheptytsky, o\u00f9 nous avons constat\u00e9 les efforts d\u00e9ploy\u00e9s pour offrir des soins palliatifs bienveillants aux plus d\u00e9munis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces actes de charit\u00e9 ont \u00e9t\u00e9 d&rsquo;autant plus efficaces et nombreux gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 de Canadiens d&rsquo;un oc\u00e9an \u00e0 l&rsquo;autre. Les pri\u00e8res et le soutien financier des Canadiens ont produit des fruits abondants d&rsquo;amour, de compassion, de soins et de mis\u00e9ricorde en Ukraine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visiter l&rsquo;Ukraine a \u00e9t\u00e9 un v\u00e9ritable cadeau et une exp\u00e9rience \u00e9mouvante pour Anna, le pr\u00e9sident de CNEWA, M<sup>gr<\/sup> Peter Vaccari, et moi-m\u00eame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors que nous reprenons le travail et la vie ici chez nous, CNEWA Canada continuera \u00e0 manifester sa solidarit\u00e9 envers les personnes dans le besoin \u2014 en les aidant lorsqu&rsquo;elles ont faim, en les soignant lorsqu&rsquo;elles sont bless\u00e9es et en les h\u00e9bergeant lorsqu&rsquo;elles n&rsquo;ont pas d&rsquo;endroit o\u00f9 se loger ou qu&rsquo;elles risquent de perdre espoir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puissions-nous continuer \u00e0 soutenir l&rsquo;Ukraine et \u00e0 \u00eatre de grands t\u00e9moins de l&rsquo;amour et de la sollicitude envers ceux que nous servons. Notre travail en Ukraine est loin d&rsquo;\u00eatre termin\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En juin dernier, le pr\u00e9sident de CNEWA, Mgr Peter Vaccari, notre charg\u00e9e de projet pour l&rsquo;Ukraine, Anna Dombrovska, et moi-m\u00eame nous sommes rendus dans l&rsquo;ouest de l&rsquo;Ukraine afin de visiter les diff\u00e9rents programmes auxquels nous apportons notre soutien. Depuis f\u00e9vrier 2022, gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 de nos donateurs canadiens, CNEWA a jou\u00e9 un r\u00f4le de &hellip; <a href=\"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/\">Continued<\/a><\/p>\n","protected":false},"author":70080,"featured_media":1371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,345,400],"class_list":["post-1372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-ukraine","category-lettres-ouvertes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0 | CNEWA Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0\" \/>\n<meta property=\"og:description\" content=\"En juin dernier, le pr\u00e9sident de CNEWA, Mgr Peter Vaccari, notre charg\u00e9e de projet pour l&rsquo;Ukraine, Anna Dombrovska, et moi-m\u00eame nous sommes rendus dans l&rsquo;ouest de l&rsquo;Ukraine afin de visiter les diff\u00e9rents programmes auxquels nous apportons notre soutien. Depuis f\u00e9vrier 2022, gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 de nos donateurs canadiens, CNEWA a jou\u00e9 un r\u00f4le de &hellip; Continued\" \/>\n<meta property=\"og:site_name\" content=\"CNEWA Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cnewacanada\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-04T17:45:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T19:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2023\/07\/tbc202306_021H.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adriana Bara, Ph.D.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cnewac\" \/>\n<meta name=\"twitter:site\" content=\"@cnewac\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Calin Batori\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/\"},\"author\":{\"name\":\"Adriana Bara, Ph.D.\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/person\\\/929839c5dd14a349dc51af681d8cf7ae\"},\"headline\":\"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0\",\"datePublished\":\"2023-07-04T17:45:19+00:00\",\"dateModified\":\"2023-07-04T19:05:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/\"},\"wordCount\":538,\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/tbc202306_021H.jpg\",\"articleSection\":[\"Nouvelles\",\"Ukraine\",\"Lettres ouvertes\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/\",\"name\":\"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0 | CNEWA Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/tbc202306_021H.jpg\",\"datePublished\":\"2023-07-04T17:45:19+00:00\",\"dateModified\":\"2023-07-04T19:05:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/tbc202306_021H.jpg\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/tbc202306_021H.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"Mgr Peter I. Vaccari, Adriana Bara et Anna Dombrovska visitent l'H\u00f4pital m\u00e8re-enfant de Lviv. (Photo : TBC)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\",\"name\":\"CNEWA Canada\",\"description\":\"Association catholique d\u2019aide \u00e0 l\u2019Orient\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#organization\",\"name\":\"CNEWA Canada\",\"alternateName\":\"Association catholique d\u2019aide \u00e0 l\u2019Orient\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/CNEWA-brand-logo.png\",\"contentUrl\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/CNEWA-brand-logo.png\",\"width\":1000,\"height\":1000,\"caption\":\"CNEWA Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/cnewa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cnewacanada\\\/\",\"https:\\\/\\\/x.com\\\/cnewac\",\"https:\\\/\\\/www.instagram.com\\\/cnewa1926\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/TheCNEWA\"]},{\"@type\":\"Person\",\"name\":\"Adriana Bara, Ph.D.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0 | CNEWA Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/","og_locale":"fr_CA","og_type":"article","og_title":"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0","og_description":"En juin dernier, le pr\u00e9sident de CNEWA, Mgr Peter Vaccari, notre charg\u00e9e de projet pour l&rsquo;Ukraine, Anna Dombrovska, et moi-m\u00eame nous sommes rendus dans l&rsquo;ouest de l&rsquo;Ukraine afin de visiter les diff\u00e9rents programmes auxquels nous apportons notre soutien. Depuis f\u00e9vrier 2022, gr\u00e2ce \u00e0 la g\u00e9n\u00e9rosit\u00e9 de nos donateurs canadiens, CNEWA a jou\u00e9 un r\u00f4le de &hellip; Continued","og_site_name":"CNEWA Canada","article_publisher":"https:\/\/www.facebook.com\/cnewacanada\/","article_published_time":"2023-07-04T17:45:19+00:00","article_modified_time":"2023-07-04T19:05:03+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2023\/07\/tbc202306_021H.jpg","type":"image\/jpeg"}],"author":"Adriana Bara, Ph.D.","twitter_card":"summary_large_image","twitter_creator":"@cnewac","twitter_site":"@cnewac","twitter_misc":{"\u00c9crit par":"Calin Batori","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/#article","isPartOf":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/"},"author":{"name":"Adriana Bara, Ph.D.","@id":"https:\/\/cnewa.org\/fr\/#\/schema\/person\/929839c5dd14a349dc51af681d8cf7ae"},"headline":"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0","datePublished":"2023-07-04T17:45:19+00:00","dateModified":"2023-07-04T19:05:03+00:00","mainEntityOfPage":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/"},"wordCount":538,"publisher":{"@id":"https:\/\/cnewa.org\/fr\/#organization"},"image":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2023\/07\/tbc202306_021H.jpg","articleSection":["Nouvelles","Ukraine","Lettres ouvertes"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/","url":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/","name":"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0 | CNEWA Canada","isPartOf":{"@id":"https:\/\/cnewa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2023\/07\/tbc202306_021H.jpg","datePublished":"2023-07-04T17:45:19+00:00","dateModified":"2023-07-04T19:05:03+00:00","breadcrumb":{"@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/#primaryimage","url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2023\/07\/tbc202306_021H.jpg","contentUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2023\/07\/tbc202306_021H.jpg","width":1800,"height":1200,"caption":"Mgr Peter I. Vaccari, Adriana Bara et Anna Dombrovska visitent l'H\u00f4pital m\u00e8re-enfant de Lviv. (Photo : TBC)"},{"@type":"BreadcrumbList","@id":"https:\/\/cnewa.org\/fr\/cnewa-exprime-sa-solidarite-envers-les-personnes-dans-le-besoin-en-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cnewa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"CNEWA exprime sa solidarit\u00e9 envers les personnes dans le besoin en Ukraine\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/cnewa.org\/fr\/#website","url":"https:\/\/cnewa.org\/fr\/","name":"CNEWA Canada","description":"Association catholique d\u2019aide \u00e0 l\u2019Orient","publisher":{"@id":"https:\/\/cnewa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnewa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/cnewa.org\/fr\/#organization","name":"CNEWA Canada","alternateName":"Association catholique d\u2019aide \u00e0 l\u2019Orient","url":"https:\/\/cnewa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cnewa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2019\/11\/CNEWA-brand-logo.png","contentUrl":"https:\/\/cnewa.org\/fr\/wp-content\/uploads\/sites\/3\/2019\/11\/CNEWA-brand-logo.png","width":1000,"height":1000,"caption":"CNEWA Canada"},"image":{"@id":"https:\/\/cnewa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cnewacanada\/","https:\/\/x.com\/cnewac","https:\/\/www.instagram.com\/cnewa1926\/","https:\/\/www.youtube.com\/user\/TheCNEWA"]},{"@type":"Person","name":"Adriana Bara, Ph.D."}]}},"_links":{"self":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts\/1372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/users\/70080"}],"replies":[{"embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/comments?post=1372"}],"version-history":[{"count":4,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts\/1372\/revisions"}],"predecessor-version":[{"id":1376,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/posts\/1372\/revisions\/1376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/media\/1371"}],"wp:attachment":[{"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/media?parent=1372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnewa.org\/fr\/wp-json\/wp\/v2\/categories?post=1372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}